{"id":706,"date":"2017-03-20T14:50:17","date_gmt":"2017-03-20T13:50:17","guid":{"rendered":"http:\/\/naturwatch.cbrell.de\/?p=105"},"modified":"2017-03-20T14:50:17","modified_gmt":"2017-03-20T13:50:17","slug":"pressebericht-in-der-rheinischen-post","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/","title":{"rendered":"Pressebericht in der Rheinischen Post"},"content":{"rendered":"<p>\t\t\t\tRheinische Post: Auf den Spuren von Heinz Sielmann: Studenten bauen &#8222;interaktiven Meisenkasten&#8220; (14. M\u00e4rz 2017)<\/p>\n<p><a href=\"http:\/\/www.rp-online.de\/nrw\/staedte\/krefeld\/auf-den-spuren-von-heinz-sielmann-studenten-bauen-interaktiven-meisenkasten-aid-1.6686844\">Link zum Online-Artikel auf rp-online.de<\/a><\/p>\n<p><a href=\"http:\/\/naturwatch.cbrell.de\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-87 size-large\" src=\"http:\/\/naturwatch.cbrell.de\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann-1024x744.jpg\" alt=\"\" width=\"780\" height=\"567\" \/><\/a>\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rheinische Post: Auf den Spuren von Heinz Sielmann: Studenten bauen &#8222;interaktiven Meisenkasten&#8220; (14. M\u00e4rz 2017) Link zum Online-Artikel auf rp-online.de<\/p>\n","protected":false},"author":1,"featured_media":971,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[1],"tags":[207,208,209,210,211,213],"class_list":["post-706","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-allgemein","tag-heinz-sielmann","tag-hsnr","tag-meisenkasten","tag-naturwatch","tag-naturwatch-hn","tag-presse","post_format-post-format-image"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pressebericht in der Rheinischen Post - Bienen und Technik<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pressebericht in der Rheinischen Post - Bienen und Technik\" \/>\n<meta property=\"og:description\" content=\"Rheinische Post: Auf den Spuren von Heinz Sielmann: Studenten bauen &#8222;interaktiven Meisenkasten&#8220; (14. M\u00e4rz 2017) Link zum Online-Artikel auf rp-online.de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-20T13:50:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/12\/youtube-titelbild-calliope.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"813\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Pressebericht in der Rheinischen Post\",\"datePublished\":\"2017-03-20T13:50:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/\"},\"wordCount\":25,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg\",\"keywords\":[\"heinz sielmann\",\"hsnr\",\"meisenkasten\",\"naturwatch\",\"naturwatch.hn\",\"presse\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/\",\"name\":\"Pressebericht in der Rheinischen Post - Bienen und Technik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg\",\"datePublished\":\"2017-03-20T13:50:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg\",\"width\":1024,\"height\":744},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pressebericht-in-der-rheinischen-post\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pressebericht in der Rheinischen Post\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pressebericht in der Rheinischen Post - Bienen und Technik","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/","og_locale":"de_DE","og_type":"article","og_title":"Pressebericht in der Rheinischen Post - Bienen und Technik","og_description":"Rheinische Post: Auf den Spuren von Heinz Sielmann: Studenten bauen &#8222;interaktiven Meisenkasten&#8220; (14. M\u00e4rz 2017) Link zum Online-Artikel auf rp-online.de","og_url":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/","og_site_name":"Bienen und Technik","article_published_time":"2017-03-20T13:50:17+00:00","og_image":[{"width":1024,"height":813,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/12\/youtube-titelbild-calliope.jpg","type":"image\/jpeg"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Pressebericht in der Rheinischen Post","datePublished":"2017-03-20T13:50:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/"},"wordCount":25,"image":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg","keywords":["heinz sielmann","hsnr","meisenkasten","naturwatch","naturwatch.hn","presse"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/","url":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/","name":"Pressebericht in der Rheinischen Post - Bienen und Technik","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg","datePublished":"2017-03-20T13:50:17+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2017\/08\/180314-SCAN-RP-Auf-den-Spuren-von-Heinz-Sielmann.jpg","width":1024,"height":744},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/pressebericht-in-der-rheinischen-post\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Pressebericht in der Rheinischen Post"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":0,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/971"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}