{"id":4974,"date":"2025-02-03T22:21:59","date_gmt":"2025-02-03T21:21:59","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=4974"},"modified":"2025-03-15T17:54:51","modified_gmt":"2025-03-15T16:54:51","slug":"gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/","title":{"rendered":"Gefriertruhe Stromverbrauch &#8211; Messungen und Kosten"},"content":{"rendered":"<p><em>Eine K\u00fchltruhe (oder hei\u00dft es Gefriertruhe?) ist vermutlich ein Luxus. Hat man sich damit arrangiert, so bedeutet ein Ausfall schon einen kleinen wirtschaftlichen Schaden, wenn sie voll Gefriergut war. F\u00e4llt der Strom aus, ist die Gefriertruhe auch aus und das Gefriergut taut auf. Was auch zu bedenken ist: <\/em><em>\u00a0Der Strom f\u00fcr die Gefriertruhe kostet, allerdings fallen die Kosten mit 53\u20ac pro Jahr moderat aus. Ob sich eine solare Strom-Unterst\u00fctzung f\u00fcr die K\u00fchltruhe lohnt und wie man dem Strom-Blackout vorbeugen kann, beleuchtet dieser Beitrag zum Thema &#8222;K\u00fchltruhe Stromverbrauch&#8220;.<\/em><\/p>\n<p><em>Der Beitrag dient der Vorbereitung f\u00fcr die Auslegungen eines Notstromsystems, das bei einem Stromausfall die kritischen Bereiche im Haus (Heizungssteuerung mit Brenner-Stromversorgung, Internet Router,K\u00fchltruhe bzw Gefriertruhe und Beleuchtung des Treppenhauses) zumindest f\u00fcr 24 Stunden mit Strom versorgt. Der Beitrag ist damit Teil meiner pers\u00f6nlichen &#8222;Prepper- und Maker-Story&#8220; getreu dem Pfadfinder Spruch &#8222;Allzeit bereit&#8220;.<\/em><\/p>\n<p><em>Stand: 03.02.2025<br \/>\nRevision 15.03.2025 (Verlinkung \u00e4hnliche Artikel)<\/em><\/p>\n<p>Bisher wurden\u00a0 weiterhin untersucht:<br \/>\n<a href=\"https:\/\/cbrell.de\/blog\/gasheizung-stromverbrauch-messungen-und-kosten\/\">Gasheizung Stromverbrauch<\/a><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/stromkosten-fritzbox-lohnt-sich-das-abschalten\/\">Internentrouter (Fritzbox) Stromverbrauch.<\/a><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/stromverbrauch-alter-kuehlschrank-lohnt-ein-neuer\/\">Getr\u00e4nkek\u00fchlschrank (ohne Gefrierfunktion)<\/a><\/p>\n<h2>Messungen<\/h2>\n<h3>Vorgehen<\/h3>\n<p>\u00dcber einem\u00a0 Februartag wurde der kumulierte Stromverbrauch und die elektrische Leistung einer 30 Jahre alten &#8211; und entsprechend ineffizienten &#8211; K\u00fchltruher \/ Gefriertruhe\u00a0 gemonitort.<\/p>\n<h3>Messaufbau f\u00fcr die Untersuchungen &#8222;K\u00fchltruhe Stromverbrauch&#8220;<\/h3>\n<p>F\u00fcr Die Messungen des Stromverbrauchs der K\u00fchltruhe wurde lediglich eine WLAN-Steckdose mt Energiemessfunktion (Shelly Plus Plug S) eingesetzt. Ein kleines Script auf der Steckdose misst jede Sekunde den Strom, mittelt den Strom \u00fcber eine Minute und \u00fcbertr\u00e4gt die Werte jede Minute an einen Internetserver, der die Daten in einer Datenbank ablegt. Die Auswertung erfolgt mit einem selbstgeschriebenem PHP-Script.<\/p>\n<h3>Messergebnisse<\/h3>\n<p>In 24 Stunden ben\u00f6tigt die K\u00fchltruhe 0,35kWh Strom (Abb. 1 rechts). Dabei springt sie in 24 Stunden 13 mal an und ben\u00f6tigt eine Leistung bis zu 75 Watt. Nicht zu vernachl\u00e4ssigen ist der kurze Anlaufstrom des Kompressormotors. Der ist im Datenlog nicht sichtbar. Damit der Kompressor sicher anl\u00e4uft, muss eine irgendwie geartetete solare Versorgung diesen Anlaufstrom liefern.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4976\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png\" alt=\"Grafki Leistung und Energie f\u00fcr eine alte K\u00fchltruhe.\" width=\"1024\" height=\"379\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden-300x111.png 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden-768x284.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><em>Abb. 1: Leistung in Watt und kumulierte Leistung (Energie) in kWh f\u00fcr 24 Stunden Betrieb. Die S\u00e4ulen in der Leistungskurve zeigen, wann der Kompressor in Betrieb geht. Der kumulierten Leistung rechts ist zu entnehmen, dass die Heizung in 24 Stunden insgesamt 0,35 kWH Strom ben\u00f6tigt. Dieser Wert ist interessant, da die K\u00fchltruhe auch nachts l\u00e4uft und einen Stromspeicher f\u00fcr eine solare Energieversorgung ben\u00f6tigt. Der Verbrauch sollte typisch f\u00fcr das ganze Jahr sein<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Kostensch\u00e4tzungen<\/h2>\n<h3>Annahmen<\/h3>\n<p>Eine Kostensch\u00e4tzung f\u00fcr den Stromverbrauch erfolgt mit folgenden heuristischen Annahmen:<\/p>\n<ol>\n<li>Die K\u00fchltruhe zeigt, wenn sie in Betrieb ist, immer das Verhalten wie am Tag der Messung. Das ist insofern plausibel, da sie im Keller eines gut isolierten Hauses mit gleichbeibender Temperatur steht.<\/li>\n<li>Die K\u00fchltruhe ist ganzj\u00e4hrig in dieser Form in Betrieb.<\/li>\n<\/ol>\n<h3>Energieverbrauch<\/h3>\n<p>Dann wird eine gesamte elektrische Energie ben\u00f6tigt:<\/p>\n<p>365 Tage * 0,35kWh\/Tag = 128 kWh<\/p>\n<h3>Energiekosten<\/h3>\n<p>Bei einem Strompreis von 30Ct pro kWh entspricht das 38\u20ac im Jahr.<\/p>\n<h3>Ammortisation<\/h3>\n<p>Der durchschnittliche Strombedarf ist, von den Anlauf-Peaks abgesehen,\u00a0 unter 100 Watt. Es wird angenommen, dass die Anlaufleistung 200 Watt nicht \u00fcberschreitet.\u00a0 Dazu gen\u00fcgt tags\u00fcber eine kleine Solaranlage (Balkonkraftwerk mit Speicher), wenn das Solarpanel mit S\u00fcdausrichtung und fast vertikal montiert werden kann (dann ist auch im Winter eine brauchbare Leistung zu erwarten). Das Angebot an kleinen Anlagen mit Speicher ist \u00fcberschaubar. So kostet eine L\u00f6sung mit 890 Watt Peakleistung und einem Speichervolumen von 1600 Wattstunden 969\u20ac.<br \/>\n(https:\/\/priwatt.de\/stecker-solaranlagen\/ohne-halterung\/pribasic-duo-ohne-halterung\/SW10961.1)<\/p>\n<p>Damit w\u00fcrde es fast 25 Jahre ben\u00f6tigen, bis die Gestehungskosten allein f\u00fcr die Anlage erreicht sind. Durch Selbstbau, insbesondere der Speicherl\u00f6sung, wird man einiges sparen k\u00f6nnen, allerdings wird man auch hier nicht unter 600\u20ac investieren m\u00fcssen. <strong>Setzt man die Anlage nur f\u00fcr die K\u00fchltruhe ein, lohnt sich das aus betriebswirtschaftlchen Gr\u00fcnden sicherlich nicht.<\/strong><\/p>\n<p>Anders kann die Kalkulation aussehen, wenn weitere Verbraucher wie WLAN-Router, die Heizungssteuerung oder gar Klimaanlagen mit eingerechten werden.<\/p>\n<h3>Absicherung f\u00fcr den Notfall<\/h3>\n<p>Wie immer, wenn es um <a href=\"https:\/\/cbrell.de\/blog\/informationssicherheitsmanagement\/\">Sicherheitsfunktionen geht, ist eine Absch\u00e4tzung z.B. nach dem Risikobegriff des BSI<\/a> sinnvoll:<br \/>\nRisiko = Schadensh\u00f6he * Schadenseintrittswahrscheinlichkeit.<\/p>\n<p>Die Schadenseintrittswahrscheinlichkeit (ein Stromausfall von mehreren Tagen) ist heute noch eher unwahrscheinlich. Die Schadensh\u00f6he ist eher mittel: Taut das Gefriergut auf, kann es nicht mehr eingefroren werden (das gilt bis auf den Schnaps, der h\u00e4lt das aus). Zur Zeit ist das Risiko also wohl eher gering. Allein das Gef\u00fchl, auch f\u00fcr den eher unwahrscheinlichen Fall ger\u00fcstet zu sein, kann zur Lebensqualit\u00e4t ( &#8230; f\u00fcr <a href=\"https:\/\/de.wikipedia.org\/wiki\/Prepper\">Prepper<\/a> &#8230;) beitragen. Insbesondere <a href=\"https:\/\/de.wikipedia.org\/wiki\/Maker\">Maker<\/a> werden hier f\u00fcr sich einen Zusatznutzen entdecken, da der Selbstbau einer kleinen Anlage an sich schon Freude bereitet. Monet\u00e4re \u00dcberlegungen beschr\u00e4nken sich dann auf die Absch\u00e4tzung, was man f\u00fcr sein Hobby ausgeben will.<\/p>\n<h2>Quellen und Links<\/h2>\n<h3>Mathematik und Statistik zu K\u00fchltruhe Stromverbrauch<\/h3>\n<p>Statistik: wer verstehen m\u00f6chte, die was mit Mittelwert, Median und der in diesem Beitrag verwendeten Aufsummierung funktioniert, dem sei das B\u00fcchlein <a href=\"https:\/\/www.amazon.de\/Statistik-Null-Hundert-Statistik-Grundwissen-Springer-Lehrbuch\/dp\/3662536315\">&#8222;Statistik von Null auf Hundert&#8220; mit Statistik-Kochrezepten<\/a> empfohlen.<br \/>\nBrell, Claus; Brell, Juliana; Kirsch, Siegfried (2016) Statitik von Null auf Hundert &#8211; Mit Kochrezepten schnell zum Statistik-Grundwissen. Springer. 2. Auflage<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=6888\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine K\u00fchltruhe (oder hei\u00dft es Gefriertruhe?) ist vermutlich ein Luxus. Hat man sich damit arrangiert, so bedeutet ein Ausfall schon einen kleinen wirtschaftlichen Schaden, wenn sie voll Gefriergut war. F\u00e4llt &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1173,1176,1172,1174,1175,787],"class_list":["post-4974","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-elektrische-leistung","tag-gefriertruhe","tag-kuehltruhe","tag-solarstrom","tag-stromkosten","tag-stromverbrauch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik<\/title>\n<meta name=\"description\" content=\"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik\" \/>\n<meta property=\"og:description\" content=\"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T21:21:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-15T16:54:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"379\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Gefriertruhe Stromverbrauch &#8211; Messungen und Kosten\",\"datePublished\":\"2025-02-03T21:21:59+00:00\",\"dateModified\":\"2025-03-15T16:54:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/\"},\"wordCount\":849,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Stromverbrauch-Kuehltruhe-24Stunden.png\",\"keywords\":[\"elektrische Leistung\",\"Gefriertruhe\",\"K\u00fchltruhe\",\"Solarstrom\",\"Stromkosten\",\"Stromverbrauch\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/\",\"name\":\"Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Stromverbrauch-Kuehltruhe-24Stunden.png\",\"datePublished\":\"2025-02-03T21:21:59+00:00\",\"dateModified\":\"2025-03-15T16:54:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Stromverbrauch-Kuehltruhe-24Stunden.png\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Stromverbrauch-Kuehltruhe-24Stunden.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gefriertruhe Stromverbrauch &#8211; Messungen und Kosten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik","description":"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/","og_locale":"de_DE","og_type":"article","og_title":"Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik","og_description":"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?","og_url":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/","og_site_name":"Bienen und Technik","article_published_time":"2025-02-03T21:21:59+00:00","article_modified_time":"2025-03-15T16:54:51+00:00","og_image":[{"width":1024,"height":379,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png","type":"image\/png"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Gefriertruhe Stromverbrauch &#8211; Messungen und Kosten","datePublished":"2025-02-03T21:21:59+00:00","dateModified":"2025-03-15T16:54:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/"},"wordCount":849,"image":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png","keywords":["elektrische Leistung","Gefriertruhe","K\u00fchltruhe","Solarstrom","Stromkosten","Stromverbrauch"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/","url":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/","name":"Gefriertruhe Stromverbrauch - Messungen und Kosten - Bienen und Technik","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png","datePublished":"2025-02-03T21:21:59+00:00","dateModified":"2025-03-15T16:54:51+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"K\u00fchltruhe Stromverbrauch - wie hoch ist der eigentlich? Der Beitrag kl\u00e4rt: Lohnt sich daf\u00fcr eine Solaranlage mit Akkuspeicher?","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/02\/Stromverbrauch-Kuehltruhe-24Stunden.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/gefriertruhe-kuehltruhe-stromverbrauch-messungen-und-kosten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Gefriertruhe Stromverbrauch &#8211; Messungen und Kosten"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=4974"}],"version-history":[{"count":6,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4974\/revisions"}],"predecessor-version":[{"id":5155,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4974\/revisions\/5155"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=4974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=4974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=4974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}