{"id":470,"date":"2019-05-05T11:58:02","date_gmt":"2019-05-05T09:58:02","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=470"},"modified":"2021-06-12T13:50:45","modified_gmt":"2021-06-12T11:50:45","slug":"raspilab-wetterstation-grundsystem-aufsetzen","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/","title":{"rendered":"Raspilab Wetterstation Grundsystem aufsetzen"},"content":{"rendered":"<p><em>Die Wetterstation auf Basis des Raspberry Pi ben\u00f6tigt auch ein robustes Wetterstation-Grundsystem, damit sie Stromunterbrechungen schadlos \u00fcbersteht. Dazu geh\u00f6rt insbesondere eine Reduktion der Schreibzugriffe auf die SD-Karte und die Nutzung einer Ram-Disk.<\/em><\/p>\n<p><em>Der Aufbau der &#8222;Wetterstation in sieben Missionen&#8220; ist ein Bestandteil der Raspberry-Pi-Sch\u00fclerworkshops des Fachbereichs Wirtschaftswissenschaften der Hochschule Niederrhein.<\/em><\/p>\n<p><strong>Bisher erschienene Artikel zur RaspiLab Wetterstation<\/strong><\/p>\n<ol>\n<li><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/\">Raspilab Wetterstation Grundsystem aufsetzen<\/a><\/li>\n<li><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-zugriffe-auf-sd-karte-minimieren-und-lebensdauer-erhoehen\/\">Raspilab Wetterstation Lebensdauer der SD-Karte erh\u00f6hen<\/a><\/li>\n<li><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-dritte-mission-temperatur-messen-mit-dem-bs18b20\/\">RaspiLab Wetterstation dritte Mission Temperatur messen mit dem DS18B20<\/a><\/li>\n<li><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-vierte-mission-luftfeuchte-messen-mit-dem-dht22\/\">RaspiLab Wetterstation vierte Mission Luftfeuchte messen mit dem DHT22<\/a><\/li>\n<li><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-sechste-mission-druck-messen-mit-dem-bmp280\/\">RaspiLab Wetterstation sechste Mission Druck messen<\/a><a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-sechste-mission-druck-messen-mit-dem-bmp280\/\"> mit dem BMP280<\/a><\/li>\n<\/ol>\n<h2>Raspbian Lite (Raspberry Pi OS lite) als Betriebssystem f\u00fcr das Wetterstation Grundsystem<\/h2>\n<p>Die erste Frage ist die Wahl des Betriebssystems. Obgleich f\u00fcr einfache Messaufgaben \u00fcberdimensioniert, f\u00e4llt die Wahl auf das Standard Raspbian. Hierzu finden sich die meisten Anleitungen im Netz. Die Wetterstation soll headles laufen, somit wird keine grafische Benutzungsoberfl\u00e4che ben\u00f6tigt, en gen\u00fcgt Raspbian Lite in der neuesten Version.<\/p>\n<p><strong>Update vom 09.09.2020:<\/strong> Seit dem 20.08.2020 hei\u00dft Raspbian anders: Raspberry Pi OS. Daher sind nun einige Begriffe anders.<\/p>\n<h3>Raspberry Pi OS (32-bit) Lite herunterladen und entpacken<\/h3>\n<p>Die aktuelle Version erhalten Sie unter <a href=\"https:\/\/www.raspberrypi.org\/downloads\/raspberry-pi-os\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.raspberrypi.org\/downloads\/raspberry-pi-os\/<\/a>. Zum Zeitpunkt der ersten Erstellung dieses Beitrages war das Release Date 2019-04-08, diesen Anleitung wurde an 2020-08-20 angepasst<strong>.\u00a0<\/strong>W\u00e4hlen Sie &#8222;Raspberry Pi OS (32-bit) Lite, Minimal image based on Debian Stretch&#8220;, Download als ZIP. Die ZIP-Datei ist etwas mehr als 400 MB gro\u00df. Die weitere Anleitung geht davon aus, dass Sie die ZIP Datei in einem Verzeichnis &#8222;Downloads&#8220; gespeichert haben. Entpacken Sie das ZIP-Archiv (alle Betriebssysteme haben einen Entpacker in ihrem Dateimanager integriert), Sie sollten nun eine Datei &#8222;2020-08-20-raspios-buster-armhf-lite.zip&#8220; mit einer Gr\u00f6\u00dfe von 1,85 GB vorfinden. Benennen Sie die Datei zur einfacheren Handhabung in &#8222;raspios.img&#8220; um. Dieses Betriebssystemimage &#8222;brennen&#8220; Sie im weiteren Schritt auf eine SD-Karte.<\/p>\n<h3>Mikro-SD Karte ausw\u00e4hlen<\/h3>\n<p>Grunds\u00e4tzlich w\u00fcrde das System mit einer 2 GB Mikro-SD Karte funktionieren. Da es schwer ist, SD-Karten mit geringerer Kapazit\u00e4t als 16 GB und passabler Geschwindigkeit zu beschaffen, f\u00e4llt die Wahl auf eine 16 GB Karten mit Class 10. Als sehr robust und zuverl\u00e4ssig haben sich z.B. SanDisk Ultra 16 GB erwiesen, die in der Praxis sehr viele Schreibvorg\u00e4nge verkraften und schnell booten.<\/p>\n<h3>Mikro-SD-Karte brennen<\/h3>\n<p>Im Folgenden wird das Verfahren unter MacOS beschrieben, das vergleichbar auch unter Linux funktioniert. F\u00fcr das Brennen der SD-Karten unter Windows existiert eine Vielzahl sehr guter Anleitungen im Netz, die Sie mit der google-Suche &#8222;raspbian brennen sd karte windows&#8220;\u00a0 finden.<\/p>\n<p>Rufen Sie die Konsole auf. Stecken Sie eine SD-Karte ein und suchen Sie die Bezeichnung der SD-Karten mit<\/p>\n<pre>df -h<\/pre>\n<p>Sie erkennen die SD-Karte an der Gr\u00f6\u00dfe (hier 15G) , bei einer neuen Speicherkarte sollte auf dem Bildschirm stehen:<br \/>\n&#8222;\/dev\/disk2s1 15Gi 2.3Mi 15Gi 1% 0 0 100% \/Volumes\/NO NAME&#8220;<\/p>\n<p>Wenn Sie an USB gerade eine andere Festplatte angeschlossen haben, kann die Bezeichnung auch &#8222;disk3s1&#8220; lauten. Passen Sie die folgenden Befehle dann daran an.<\/p>\n<p>Werfen Sie die eingebundene Partition aus mit<\/p>\n<pre>sudo diskutil unmount \/dev\/disk2s1<\/pre>\n<p>Sie erhalten eine Meldung &#8222;Volume NO NAME on disk2s1 unmounted&#8220;<\/p>\n<p>Brennen Sie nun das Image mit<\/p>\n<pre>sudo dd of=\/dev\/rdisk2 if=Downloads\/raspios.img bs=1m<\/pre>\n<p>Der Prozess ist f\u00fcr 3-4 Minuten nicht sehr gespr\u00e4chig, meldet sich dann aber mit den \u00fcbertragenen Bytes und der Transferrate etwa wie folgt:<\/p>\n<p>&#8222;440+0 records in<br \/>\n440+0 records out<br \/>\n1845493760 bytes transferred in 121.641158 secs (15171623 bytes\/sec)&#8220;<\/p>\n<h3>Mikro-SD-Karte f\u00fcr den headless-Betrieb vorbereiten<\/h3>\n<p>Wenn Sie von Beginn an ohne Monitor und Tastatur mit dem Raspberry arbeiten wollen, ben\u00f6tigen Sie einen &#8222;Fernzugriff&#8220; auf dem Raspberry. Das gelingt mit ssh, wenn sich der Raspberry in Ihr WLAN einbucht. Dazu gen\u00fcgt es, zwei Textdateien ssh und wpa_supplicant.conf in der Partition boot der Mikro-SD-Karte anzulegen.<\/p>\n<p>Von der SD-Karte sehen Sie nur die Partition &#8222;boot&#8220; mit 264 MB Gr\u00f6\u00dfe, davon werden 57 MB durch 39 Dateien und einem Ordner verwendet. Praktisch ist, das Sie hier Platz haben, um Dateien abzulegen, die Sie mit dem Mac und mit Windows einfach lesen k\u00f6nnen.<\/p>\n<p>Damit der Raspberry gleich beim ersten Start Ihr WLAN nutzt, erzeugen Sie mit dem Texteditor (notepad++ auf dem Windows PC oder sublime text auf dem Mac) die Datei wpa_supplicant.conf in der Partition boot der Micro-SD-Karte. In der Datei sollte stehen:<\/p>\n<pre><code>country=DE\r\nctrl_interface=DIR=\/var\/run\/wpa_supplicant GROUP=netdev\r\nupdate_config=1\r\nnetwork={\r\n       ssid=\"wlan-bezeichnung\"\r\n       psk=\"passwort\"\r\n       key_mgmt=WPA-PSK\r\n}<\/code><\/pre>\n<p>Damit Sie bequem via ssh auf dem Raspberry arbeiten k\u00f6nnen, erstellen Sie in der Partition &#8222;boot&#8220; der SD-Karte mit einem Texteditor eine leere Datei &#8222;ssh&#8220;.<\/p>\n<p>Entnehmen Sie nun die Mikro-SD-Karte und starten Sie Ihren Raspberry.<\/p>\n<h2>Raspberry Pi OS lite f\u00fcr das Wetterstation Grundsystem einrichten<\/h2>\n<h3>IP-Adresse des Raspberry Pi ermitteln<\/h3>\n<p>Sie ben\u00f6tigen die IP-Adresse, um dr\u00fcber mit ssh auf den Raspberry zuzugreifen. Sie k\u00f6nnen die IP-Adresse Ihres Raspberrys \u00fcber das Konfigurationsmen\u00fcs Ihres Routers oder \u00fcber eine App wie Fritz WLAN Basic mit Ihrem Smartphone ermitteln. F\u00fcr MacOS und Linux gibt es das praktische Konsolenprogramm arp-scan. Sie installieren es auf Ihrem Rechner mit<\/p>\n<pre>sudo apt-get install arp-scan<\/pre>\n<p>und nutzen es mit dem Aufruf<\/p>\n<pre>sudo arp-scan -l<\/pre>\n<h3>Mit ssh auf das Wetterstation Grundsystem\u00a0 zugreifen<\/h3>\n<p>Sie ben\u00f6tigen f\u00fcr den Zugriff den Standardnutzer pi und das Standardpasswwot raspberry, Ist die IP-Adresse z.B. 192.168.1.131, so gelangen Sie mit<\/p>\n<pre>ssh pi@192.168.1.131<\/pre>\n<p>und der nachfolgenden Eingabe des Standardpasswortes raspberry auf Ihren Raspberry und k\u00f6nnen nun so arbeiten, als s\u00e4\u00dfen Sie vor einem angeschlossenen Bildschirm und Tastatur.<\/p>\n<p>Anmerkung: Wenn Sie in verschiedenen netzen und mit mehreren Raspberrys arbeiten, kann es sein, dass die Sicherheitseinrichtungen Ihres Rechners den Zugriff mit einer kryptischen Fehlermeldung verweigern. Es hilft, in diesem Falle die Datei known_hosts im Verzeichnis .ssh auf dem Mac zu l\u00f6schen mit<\/p>\n<pre>cd .ssh\r\nrm known_hosts<\/pre>\n<h3>Zeitzone und Lokalisierung einrichten<\/h3>\n<p>Damit Sie bei den weiteren Skripten f\u00fcr die Wetterstation die richtige Zeit bekommen, sollten Sie noch die Zeitzone einrichten. Das geht bequem mit dem Konfigurationswerkzeug des Raspberrys und dem Aufruf<\/p>\n<pre>sudo raspi-config<\/pre>\n<p>Stellen Sie als Locale de_DE.UTF8 und als Zeitzone Europa &#8211; Berlin ein.<\/p>\n<p><em>Sie haben nun ein Grundsystem eingerichtet, auf dessen Basis Sie die Wetterstation einrichten k\u00f6nnen. Allerdings schreibt ein Linux-Betriebssystem gerne auf die SD-Karte, die mittelfristig dadurch zerst\u00f6rt wird. Wenn Sie Ihr System im 7&#215;12 Stunden Dauerbetrieb nutzen wollen, sollten Sie ein wenig in die &#8222;H\u00e4rtung&#8220;, das hei\u00dft Minimierung der Schreibzugriffe, investieren. Das ist im Folgebeitrag beschrieben.<\/em><\/p>\n<h2>Weitere Quellen zu Wetterstation Grundsystem<\/h2>\n<p>Wie Sie einen Internet- Zugang \u00fcber eduroam auf dem Raspberry Pi herstellen: <a href=\"https:\/\/cbrell.de\/blog\/eduroam-raspberry-pi\/\">eduroam Raspberry Pi einrichten<\/a><\/p>\n<p>Wie Sie die Lebensdauer der SD-Karte des Raspberry Pi erh\u00f6hen: <a href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-zugriffe-auf-sd-karte-minimieren-und-lebensdauer-erhoehen\/\">RaspiLab Wetterstation Zugriffe auf SD-Karte minimieren und Lebensdauer erh\u00f6hen<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=8874\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Wetterstation auf Basis des Raspberry Pi ben\u00f6tigt auch ein robustes Wetterstation-Grundsystem, damit sie Stromunterbrechungen schadlos \u00fcbersteht. Dazu geh\u00f6rt insbesondere eine Reduktion der Schreibzugriffe auf die SD-Karte und die Nutzung &#8230;<\/p>\n","protected":false},"author":1,"featured_media":438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[92,253,77,76],"tags":[399,130,270,131,400,129,78,271,123,134,132,133],"class_list":["post-470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-naturbeobachtung-und-naturschutz","category-programmieren","category-programmierung","category-raspberry-pi","tag-betriebssystem","tag-einrichten","tag-grundsystem","tag-headless","tag-installieren","tag-linux","tag-raspberry-pi","tag-raspbian","tag-schuelerworkshop","tag-wetterstation","tag-wlan","tag-wpa_supplicant"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem<\/title>\n<meta name=\"description\" content=\"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem\" \/>\n<meta property=\"og:description\" content=\"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-05T09:58:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-12T11:50:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"836\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Raspilab Wetterstation Grundsystem aufsetzen\",\"datePublished\":\"2019-05-05T09:58:02+00:00\",\"dateModified\":\"2021-06-12T11:50:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/\"},\"wordCount\":1071,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/raspilab-wetterstation-komplette-schaltung.png\",\"keywords\":[\"Betriebssystem\",\"einrichten\",\"Grundsystem\",\"headless\",\"installieren\",\"Linux\",\"Raspberry Pi\",\"Raspbian\",\"Sch\u00fclerworkshop\",\"Wetterstation\",\"WLAN\",\"wpa_supplicant\"],\"articleSection\":[\"Naturbeobachtung und Naturschutz\",\"Programmieren\",\"Programmierung\",\"Raspberry Pi\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/\",\"name\":\"Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/raspilab-wetterstation-komplette-schaltung.png\",\"datePublished\":\"2019-05-05T09:58:02+00:00\",\"dateModified\":\"2021-06-12T11:50:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/raspilab-wetterstation-komplette-schaltung.png\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/raspilab-wetterstation-komplette-schaltung.png\",\"width\":1024,\"height\":836,\"caption\":\"Wetterstation mit demRaspberry Pi - Sch\u00fclerworkshop\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspilab-wetterstation-grundsystem-aufsetzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raspilab Wetterstation Grundsystem aufsetzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem","description":"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/","og_locale":"de_DE","og_type":"article","og_title":"Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem","og_description":"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.","og_url":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/","og_site_name":"Bienen und Technik","article_published_time":"2019-05-05T09:58:02+00:00","article_modified_time":"2021-06-12T11:50:45+00:00","og_image":[{"width":1024,"height":836,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png","type":"image\/png"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Raspilab Wetterstation Grundsystem aufsetzen","datePublished":"2019-05-05T09:58:02+00:00","dateModified":"2021-06-12T11:50:45+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/"},"wordCount":1071,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png","keywords":["Betriebssystem","einrichten","Grundsystem","headless","installieren","Linux","Raspberry Pi","Raspbian","Sch\u00fclerworkshop","Wetterstation","WLAN","wpa_supplicant"],"articleSection":["Naturbeobachtung und Naturschutz","Programmieren","Programmierung","Raspberry Pi"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/","url":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/","name":"Raspilab Wetterstation Grundsystem aufsetzen Wetterstation Grundsystem","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png","datePublished":"2019-05-05T09:58:02+00:00","dateModified":"2021-06-12T11:50:45+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Das Wetterstation Grundsystem auf Basis des Raspberry Pi muss robust sein, damit die SD-Karte Stromunterbrechungen schadlos \u00fcbersteht.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2019\/03\/raspilab-wetterstation-komplette-schaltung.png","width":1024,"height":836,"caption":"Wetterstation mit demRaspberry Pi - Sch\u00fclerworkshop"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/raspilab-wetterstation-grundsystem-aufsetzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Raspilab Wetterstation Grundsystem aufsetzen"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=470"}],"version-history":[{"count":2,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/470\/revisions"}],"predecessor-version":[{"id":2008,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/470\/revisions\/2008"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/438"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}