{"id":4644,"date":"2024-09-25T21:40:30","date_gmt":"2024-09-25T19:40:30","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=4644"},"modified":"2025-09-19T19:51:25","modified_gmt":"2025-09-19T17:51:25","slug":"bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/","title":{"rendered":"Bienenfutter-Bereiter selber bauen &#8211; Zuckersirup ohne r\u00fchren"},"content":{"rendered":"<p><em>E<\/em><em>ine bebilderte Anleitung f\u00fcr den Bau f\u00fcr einen Bienenfutter-Bereiter. Nachdem nun Haushaltszucker wieder erschwinglich ist, lohnt es sich f\u00fcr Imker, insbesondere das Winterfutter f\u00fcr Ableger selbst herzustellen.<\/em><\/p>\n<p><em>Achtung: Der Sirup-Durchlauf-Prozess ist nichts f\u00fcr Eilige &#8230; und hin und wieder muss man sich um die Hygiene des Beh\u00e4lters k\u00fcmmern.<\/em><\/p>\n<p>Stand: 12.10.2024<br \/>\nUpdate 19.09.2025<\/p>\n<h2>Funktionsweise des Bienenfutter-Bereiters<\/h2>\n<p>Der Bienenfutter-Bereiter stellt laufend eine ges\u00e4ttigte Zuckerwasserl\u00f6sung (etwas konzentrierter als 3:2) als Bienenfutter zur Verf\u00fcgung. Das Bienenfutter kann \u00fcber einen Quetschhahn bequem abgenommen werden. Das Zuckerwasser ist ges\u00e4ttigt, da sich die gesamte L\u00f6sung im Beh\u00e4ltnis mit noch nicht gel\u00f6stem Zucker im Gleichgewicht befindet. Der noch nicht gel\u00f6ste Zucker ist vom fertigen Bienenfutter im unteren Teil des Beh\u00e4ltnisses durch eine Filterinrichtung bestehend aus einer gelochten Holzplatte und einem Abtrockenhandtuch in einen Bienenfutterbereich und einem Zuckerbereich getrennt, jedoch k\u00f6nnen Bienenfutterbereich und Zuckerbereich Fl\u00fcssigkeit und gel\u00f6sten Zucker durch &#8211; langsame &#8211; Str\u00f6mung und Diffusion austauschen. Der Bienenfutterbereich ist unten, der Zuckerbereich ist oben, der Transport des Bienenfutters aus dem Zuckerbereich in den Bienenfutterbereich erfolgt \u00fcber Schwerkraft. Beim Abzapfen des Binenfutters entsteht im Bienenfutterbereich ein Unterdruck, der nicht schnell genug durch Nachfluss aus dem Zuckerwasserbereich ausgeglichen werden kann. F\u00fcr den Ausgleich ist ein Bel\u00fcftungsrohr vom Luftraum oberhalb des Zuckerbereichs in den Bienenfutterbereich montiert (Abb. 1). Im laufenden Betrieb wird oben Zucker und Wasser im Gewichtsverh\u00e4ltnis von etwa 2:1 entsprechend 66% Zucker nachgef\u00fcllt.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4654\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png\" alt=\"Das Bild zeigt eine schematische Zeichnung eines Bienenfutter-Bereiters, der ohne r\u00fchren auskommt.\" width=\"1024\" height=\"678\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung-300x199.png 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung-768x509.png 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><em>Abb. 1: Schematische Zeichnung des Bienenfutter-Bereiters. Es bedeuten: (1) Beh\u00e4ltnis f\u00fcr Sirup, Wasser und Zucker (2) obere F\u00fcllkante (3) Haushaltszucker, ungel\u00f6st (4) Bel\u00fcftungsrohr (5) Abtrockentuch als Filter (6) gelochte Holzplatte als Sieb \u00a0(7) Quetschhahn (8)Bienenfutterbereich (9) Zuckerbereich ACHTUNG UPDATE: Das Bel\u00fcftungsrohr sollte unten mit der Holzplatte abschlie\u00dfen.<\/em><\/p>\n<h2>Baubeschreibung<\/h2>\n<h3>Material<\/h3>\n<p>Diese Materialien werden ben\u00f6tigt (Beschaffungslinks weiter hinten):<\/p>\n<ol>\n<li>Ein Gef\u00e4\u00df mit Ablaufhahn (das kann ein Maischebottich sein oder wie in diesem Beitrag ein Honig-Abf\u00fcll-Hobbock (Abb. 2). Das Gef\u00e4\u00df sollte eine konisch zulaufende Stelle haben, damit die Holzplatte h\u00e4lt).<\/li>\n<li>Eine runde Holzplatte mit L\u00f6chern (Abb. 3, im Prinzip fungiert die Holzplatte in Verbindung mit dem Abtrockentuch als Filter)<\/li>\n<li>Ein Abtrockentuch (das Tuch l\u00e4sst als Filter nur Sirup, aber keine Zuckerk\u00f6rnchen durch)<\/li>\n<li>Ein Rohr oder ein Schlauch zur Bel\u00fcftung. Dazu zwei Edelstahlschrauben oder eine Edelstahlklemme zur Arretierung (Abb. 4)<\/li>\n<\/ol>\n<h3>Ben\u00f6tigtes Werkzeug<\/h3>\n<h4>f\u00fcr die Holzplatte<\/h4>\n<ol>\n<li>eine Stichs\u00e4ge<\/li>\n<li>eine Bohrmaschine<\/li>\n<li>ein 10er-Bohrer<\/li>\n<li>ein 20mm-F\u00f6rstner Bohrer (oder anderes Ma\u00df entsprechend des Bel\u00fcftungsrohres)<\/li>\n<li>Schleifpapier mit 80er K\u00f6rnung<\/li>\n<\/ol>\n<h4>F\u00fcr die Montage des Quetschhahns<\/h4>\n<ol>\n<li>ein sehr gro\u00dfer Innensechkant<\/li>\n<\/ol>\n<p>oder<\/p>\n<ol>\n<li>eine Hands\u00e4ge (z. B. ein Fuchsschwanz)<\/li>\n<li>ein Kantholz 4cm x 4 cm<\/li>\n<\/ol>\n<h4>Zum Abl\u00e4ngen des Bel\u00fcftungsrohrs<\/h4>\n<ol>\n<li>eine Hands\u00e4ge (z.B. eine Puks\u00e4ge)<\/li>\n<\/ol>\n<h3>Anfertigung der runden Holzplatte<\/h3>\n<p>Die runde Holzplatte dient dazu, eine stabile Unterlage f\u00fcr das Abtrockentuch bereit zu stellen. Geeignet ist z.B. eine Kiefern- oder Fichtenholzplatte in der St\u00e4rke von 2cm. Andere Bauanleitungen verwenden Fichte Nut und Federbretter. Die Holzplatte kann nach dem Anzeichnen z.B. mit einer elektrischen Stichs\u00e4ge ausges\u00e4gt werden. Die Holzplatte sollte einen Durchmesser so haben, dass sie sich an der Grenze zum unteren Drittel des Gef\u00e4\u00dfes einklemmt. Der hier verwendete Hobbock ist leicht konisch und ein Durchmesser von 33,2cm liefert das gew\u00fcnschte Ergebnis. Im Abstand von 4 cm werden L\u00f6cher mit einem Durchmesser von 1cm in die Runde Holzplatte gebohrt.<\/p>\n<p>Die Au\u00dfenkante der runden Holzplatte kann &#8211; wenn die Stichs\u00e4ge das zul\u00e4sst &#8211; leicht konisch, also mit einem kleinen Winkel, ges\u00e4gt werden. Die Au\u00dfenkante (Schnittkante) \u00a0ist nach dem S\u00e4gen sorgf\u00e4ltig mit Schleifpapier abzurunden, so dass die Materialbelastung f\u00fcr das Beh\u00e4ltnis m\u00f6glichst gering ausf\u00e4llt.<\/p>\n<h3>Pr\u00e4paration des Bel\u00fcftungsrohrs<\/h3>\n<p>Das Bel\u00fcftungsrohr wird auf eine L\u00e4nge abgeschnitten, so dass nur wenig in den Bienenfutterbereich hineinragt und oben knapp unter der Kante des Beh\u00e4ltnisses abschlie\u00dft. Damit das Bel\u00fcftungsrohr nicht nach unten durchrutscht, k\u00f6nnen als Arretierung zwei Edelstahlschrauben bei 11cm (oder alternativ eine Edelstahl-Schlauchklemme) angebracht werden.<\/p>\n<h3>Zusammenbau des Hobbocks und des Quetschhahns<\/h3>\n<p>Der Quetschhahn besteht aus zwei Teilen, einem Au\u00dfenteil mit Verschluss und Dichtung, sowie einem Innenteil, dessen Bohrung als Sechskant ausgestaltet ist (Abb. 5). Innenteil und Au\u00dfenteil werden durch die Bohrung in der Au\u00dfenwand des Beh\u00e4ltnisses verschraubt. Der hier verwendete Hobbock weist das passende Loch schon auf. Verwendet man ein anderes Gef\u00e4\u00df, z.B. ein Maischefass, wird f\u00fcr die Bohrung ein entsprechender Topfbohrer ben\u00f6tigt.<\/p>\n<p>Das Verschrauben erfordert ein Werkzeug in Form eines gro\u00dfen Innensechskants. I.d.R. wird ein solches Werkzeug nicht vorhanden sein, in diesem Fall s\u00e4gt man sich aus einem Vierkantholz ein passendes Werkzeug zurecht (siege Abb. weiter unten)<\/p>\n<h3>Einbau der Holzplatte und des Bel\u00fcftungsrohrs<\/h3>\n<p>Legen Sie die runde Holzplatte m\u00f6glichst waagerecht in das Beh\u00e4ltnis hinein (Abb. 8). Dr\u00fccken Sie die Holzplatte zun\u00e4chst Vorsicht, dann fester, so nach unten, dass sie waagerecht im Beh\u00e4ltnis verklemmt. Die Holzplatte ist nun schwer zu entfernen. Sollten Sie die Holzplatte rausnehmen wollen, k\u00f6nnen Sie mit dem Dorn des Stockmei\u00dfels durch ein \u00e4u\u00dferes 1cm-Loch die ben\u00f6tigte Hebelkraft aufbringen (Abb. 9).<\/p>\n<p>Stecken Sie das Rohr in die vorgesehene \u00d6ffnung.<\/p>\n<h3>Einbau des Abtrockentuchs (besser Nylon-Seihtuch)<\/h3>\n<p>Schneiten Sie in die Mitte des Abtrockentuchs \/ des Seihtuchs ein Loch so, dass das Bel\u00fcftungsroh gerade hindurchm\u00fcsst. Das Abtrockentuch legen Sie mittig auf die Holzplatte so, dass die R\u00e4nder an der Gef\u00e4\u00dfwand nach oben anliegen (siehe Abb. 1, Abb. 10). Bei der sp\u00e4teren Erst-Bef\u00fcllung mit Zucker achten Sie darauf, dass die R\u00e4nder vom Zucker an die Geh\u00e4usewand angedr\u00fcckt werden.<\/p>\n<h2>Inbetriebnahme<\/h2>\n<h3>erste Bef\u00fcllung<\/h3>\n<ol>\n<li>F\u00fcllen Sie Zucker zun\u00e4chst so ein, dass sich ein Kegel mit der Kegelspitze am Bel\u00fcftungsrohr bildet.<\/li>\n<li>F\u00fcllen Sie weiteren Zucker am Rand des Gef\u00e4\u00dfes so ein, dass der Rand des Abtrockentuchs an die Gef\u00e4\u00dfwand gedr\u00fcckt wird (Abb. 12). Das stellt im sp\u00e4teren Betrieb die Abdichtung des Filters dar.<\/li>\n<li>F\u00fcr die weiteren Schritte k\u00f6nnen Sie mit Leitungswasser oder mit anges\u00e4uertem Leitungswasser (Abb. 16) oder mit anges\u00e4uertem Leitungswasser mit Invertase (Abb. 15) arbeiten<\/li>\n<li>F\u00fcllen Sie nun das Gef\u00e4\u00df mit Zucker komplett auf, so dass die \u00d6ffnung des Bel\u00fcftungsrohrs frei bleibt. Die Oberfl\u00e4che des Zuckers sollte glatt und waagerecht sein (Abb. 13).<\/li>\n<li>F\u00fcllen Sie nun etwa die H\u00e4lfte des Zuckergewichts an Wasser langsam ein. Ggf. sind dazu zwei Anl\u00e4ufe erforderlich. Nach einiger Zeit sollte Sirup in den Bienenfutterbereich tropfen. Warten Sie einen Moment, bis der erste Sirup durchgelaufen ist.<\/li>\n<li>F\u00fcllen Sie 2kg Zucker nach. Die obere Kante der F\u00fcllung sollte sich abgesenkt haben. Insgesamt ist darauf zu achten, dass die Gesamtzuckerkonzentration inkl. ungel\u00f6stem Zucker nie unter 70% f\u00e4llt.<\/li>\n<li>Entnehmen Sie den Sirup und sch\u00fctten Sie ihn wieder oben in das Gef\u00e4\u00df f\u00fcr den zweiten Durchlauf. Das muss nur bei der Erstbef\u00fcllung erfolgen.<\/li>\n<li>Warten Sie, bis der Sirup wieder nach unten durchgelaufen ist.<\/li>\n<li>F\u00fcllen Sie nun oben wieder mit Zucker bis knapp (5 cm) unter den Rand auf.<\/li>\n<li>F\u00fcllen Sie mit Wasser soweit auf, dass der Zucker soeben mit Wasser bedeckt ist.<\/li>\n<li>Wiederholen Sie die Schritte sooft, bis das Beh\u00e4ltnis bis etwa 5 cm unterhalb des Bel\u00fcftungsrohr gef\u00fcllt ist. Es sollte sich stets ungel\u00f6ster Zucker im Zuckerbereich befinden. Der Zucker sollte stets mit etwas Wasser, sp\u00e4ter Sirup, \u00fcberdeckt sein.<\/li>\n<\/ol>\n<h3>Dauerbetrieb<\/h3>\n<p>F\u00fcllen Sie nach jeder Entnahme von Bienenfutter in Form von Zuckersirup den Bienenfutter-Bereiter wieder auf. Die Zugaben von Zucker und Wasser sollten etwa im Verh\u00e4ltnis 2 zu 1 sein, auf 2kg Zucker 1L Wasser. Ggf. sollten Sie hin und wieder mehr Zucker hinzuf\u00fcgen (z.B. 3:1 entsprechen 75% Zucker), das die Zucker-Konzentration des Bienenfutters 66% \u00fcbersteigen kann.<\/p>\n<h2>Erfahrungsberichte aus der Nutzung<\/h2>\n<p><strong>Erster Feld-Test:<\/strong> Der erste Test f\u00fcr Mini Plus V\u00f6lker erfolgte Ende September \u00a0(es hat sich bei meiner Betriebsweise \u00a0am Niederrhein bew\u00e4hrt, Mini Plus V\u00f6lker behutsam und sp\u00e4t einzuf\u00fcttern). Eine Entnahme aus dem Futterbereich f\u00fcllt einen Kanister mit etwa 8 Liter Invertzuckersirup mit einem Zuckergehalt von 67% (Abb. 18, 19). Nach Tabellen har der Sirup eine Dichte von 1,32 kg\/L. Das entspricht einer Zuckermenge von etwa 7 kg. Der Bienenfutter-Bereiter wurde sofort wieder mit 6kg Zucker und 2 kg Wasser aufgef\u00fcllt (Ziel ist eine L\u00f6sung von mehr als 70% Zucker zu erhalten). Der Sirup flie\u00dft nicht sofort in den Futterbereich nach, sondern tr\u00f6pfelt eher hinein, Realistisch scheint mit der aktuellen Konfiguration eine Abnahme von zwei Kanistern pro Tag. Damit eigentlich sich der Bienenfutter-Bereiter eher f\u00fcr ein paar Ableger, weniger f\u00fcr einen Nebenerwerb mit vielen Wirtschaftsv\u00f6lkern.<br \/>\nDie Bienen waren an dem Futter sofort interessiert. Die Abnahmegeschwindigkeit durch die Bienen bleibt zu beobachten.<\/p>\n<p><strong>Nach drei Wochen:<\/strong> Die Bienen nehmen das Futter gern und auch schnell ab<\/p>\n<p><strong>Beh\u00e4lterhygiene nach mehreren Wochen Betrieb:\u00a0<\/strong>Oben im Zuckerbereich befindet sich nach Neubef\u00fcllung eine Zucketrl\u00f6sung mit unter 50% Zuckergehalt &#8211; der hohe Zuckergehalt stellt sich erst durch den Durchfluss des Wassers durch das Zuckerreservoir ein. Das kann dazu f\u00fchren, dass sich an der oberen Wasserkanten ein unansehnlicher schwarzer Rand und ggf. einzelne schwarze P\u00fcnktchen auf der Fl\u00fcssigkeit bilden. Dabei handelt es sich um den allgegenw\u00e4rtigen Aspergillus niger (siehe Glossar weiter hinten). Inwieweit das sch\u00e4dlich f\u00fcr die Bienen ist, konnte ich noch nicht abschlie\u00dfend kl\u00e4ren. Auch in der Beute ist Aspergillus niger ein st\u00e4ndiger Begleiter. Es gibt K\u00e4fer, die von Aspergillus niger leben und ihn abweiden. ich vermute daher, dass die Bienen gut mit einer geringen Aspegillus niger Belastung\u00a0 zurechtkommen. Trotzdem ist das unsch\u00f6n. Vor jeder Neubef\u00fcllung entferne ich nun den Belag mit einem feuchten K\u00fcchenkrepp.<\/p>\n<p><strong>Funktionsweise nach 11 Monaten Betrieb (bis August 2025):<\/strong>\u00a0 Der Sirup-Bereiter wurde auch im Folgejahr verwendet. Der Sirup kann Monate darin stehen bleiben, aufgrund der hohen Konzentration des Zuckers bildet sich kein Schimmel, die L\u00f6sung ist gut durchinvertiert. Es bildet sich ein Zucker-Satz, der aber mit einem Kunststoff-Pfannenschieber oder einem Schauml\u00f6ffel leicht verr\u00fchrt werden kann. Zuletzt wurde der Sirup verwendet Mitte August, die Bienen an einem Standort hatten eine massive Trachtl\u00fccke.<\/p>\n<h2>Abschluss der Beobachtung und der Nutzung, Fazit (Stand 19.09.2025)<\/h2>\n<p>Im September 2025 wurde der Futterbereiter in dieser Form au\u00dfer Betrieb genommen. Seit dem sind die Komponenten teilweise noch im Einsatz:<br \/>\nDer K\u00fcbel mit dem Ablasshahn, die als Schutzwanne dienende Kiste und die Utensilien wie Trichter, Eimer und R\u00fchrl\u00f6ffel sind weiterhin f\u00fcr die Bienenfutterbereitung im Einsatz. Ebenso werden die Rezepturen weiter angewendet. F\u00fcr nur f\u00fcnf Bienenv\u00f6lker kann der Zuckersirup gut in einem vereinfachten Verfahren hergestellt werden.<\/p>\n<p>F\u00fcr das <strong>neue, vereinfachte Verfahren<\/strong> gibt es einen eigenen Artikel.<\/p>\n<p><strong>Vorteile des Dauer-Futterbereiters<\/strong> &#8211; in der R\u00fcckschau &#8211; sind:<\/p>\n<ol>\n<li>Es steht dauernd eine hoch ges\u00e4ttigte Futterl\u00f6sung zur Verf\u00fcgung<\/li>\n<li>Es muss nur mein neueinstreuend etwas und kurz ger\u00fchrt werden<\/li>\n<li>Es sind keine zus\u00e4tzlichen Ma\u00dfnahmen zur Futterhygiuene erforderlich<\/li>\n<\/ol>\n<p><strong>Nachteile des Dauer-Futterbereiters<\/strong> &#8211; in der R\u00fcckschau &#8211; sind:<\/p>\n<ol>\n<li>Der Futterbereiter belegt dauerhaft Stellplatz. Da er gef\u00fcllt schwer ist, kann er nicht &#8222;mal eben&#8220; umgestellt werden.<\/li>\n<li>Ein vollst\u00e4ndige Leerung ist nur mit gro\u00dfem Aufwand m\u00f6glich<\/li>\n<li>Eine Reinigung der Kiste, in der die Anlage steht, ist nur schwer m\u00f6glich. Die Siruptr\u00f6pfchen, die dort unweigerlich hineingelangen, ziehen irgendwann Fruchtfliegen an &#8230;<\/li>\n<li>&#8222;Mal eben&#8220; zus\u00e4tzliches Futter erzeugen ist nicht m\u00f6glich.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<p>Diese Form des Futterbereiteres ist f\u00fcr eine \u00fcberdurchschnittliche V\u00f6lkerzahl (in Deutschland mehr als sieben) vermutlich sinnvoll.<\/p>\n<p>&nbsp;<\/p>\n<h2>Bilder<\/h2>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Material-der-montierte-Hobbock-mit-Quetschhahn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4670\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Material-der-montierte-Hobbock-mit-Quetschhahn.jpg\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Material-der-montierte-Hobbock-mit-Quetschhahn.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Material-der-montierte-Hobbock-mit-Quetschhahn-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 2: Material: Der Hobbock mit montiertem Quetschhahn<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Matreialien-Lochbrett-Belueftungsrohr-Abtrockentuch.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4671\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Matreialien-Lochbrett-Belueftungsrohr-Abtrockentuch.jpg\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Matreialien-Lochbrett-Belueftungsrohr-Abtrockentuch.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Matreialien-Lochbrett-Belueftungsrohr-Abtrockentuch-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 3: Material: Gelochte Holzplatte, Bel\u00fcftungsrohr und Abtrockentuch. Das Bel\u00fcftungsrohr hat bereits zwei Edelstahlschrauben, so dass es durch das Loch in der Holzplatte nicht ganz durchrutschen kann. ACHTUNG UPDATE: Das Bel\u00fcftungsrohr ist zu <\/em><i>lang. UPDATE: Sobald der Sirup das Bel\u00fcftungsrohr erreicht und verschlie\u00dft, flie\u00dft kaum noch Sirup vom Zuckerbereich nach. Die untere Seite sollte nur so lang sein, dass sie mit dem Brett unten abschlie\u00dft<\/i><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Belueftungsrohr-fuer-Bienenfutter-Bereiter-passend-abgelaengt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4699\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Belueftungsrohr-fuer-Bienenfutter-Bereiter-passend-abgelaengt.jpg\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Belueftungsrohr-fuer-Bienenfutter-Bereiter-passend-abgelaengt.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Belueftungsrohr-fuer-Bienenfutter-Bereiter-passend-abgelaengt-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p>Abb.4 : UPDATE: Das Bel\u00fcftungsrohr abgeh\u00e4ngt und einges\u00e4gt. Dadurch wird sichergestellt. dass jegliche Luft unterhalb des runden Holzbretts entweichen kann. Nur dann tropft Sirup vom Zuckerbereich in den Futterbereich. Mit einem scharfen K\u00fcchenmesser lassen sich die letzten gr\u00fcnen Rohrfitzel entfernen.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Nahansicht-Quetschhahn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4672\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Nahansicht-Quetschhahn.jpg\" alt=\"Bild eines Quetschhahns\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Nahansicht-Quetschhahn.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Nahansicht-Quetschhahn-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 5: Der Quetschhahn aus der N\u00e4he. Zu sehen ist der Innensechskant des inneren Bauteils.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4647\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn.jpg\" alt=\"Das Bild zeigt den Blick von oben in den Hobbock beim Befestigen des Quetschhahns.\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn-300x300.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn-150x150.jpg 150w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Befestigung-Quetschhahn-768x768.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><em>Abb.6 : Der Quetschhahn liegt dem Hobbock bei und ist noch zu montieren. Das \u00e4u\u00dfere St\u00fcck hat flexible Dichtungen, das innere Gegenst\u00fcck hat innen einen gro\u00dfen Sechskant, um es mit dem \u00e4u\u00dferen St\u00fcck verschrauben zu k\u00f6nnen. Das selbstgefertigte Werkzeug aus Holz ist hier im Einsatz gezeigt. Das Bild zeigt den Blick von oben in den Hobbock beim Befestigen des Quetschhahns.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4648\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn.jpg\" alt=\"Das Bild zeigt einen selbstgefertigten Sechskantschlussel aus Holz.\" width=\"1024\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn-300x300.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn-150x150.jpg 150w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Werkzeug-fuer-Quetschhahn-768x768.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p><em>Abb.7 : Sechskant-Werkzeug. Zur Befestigung des Imgut-Quetschhahns im Hobbock wird im Prinzip ein riesiger Innensechskant-Schl\u00fcssel ben\u00f6tigt. Einen solchen Schl\u00fcssel werden die wenigsten Imker haben. Mit einem Kantkolz und einem Fuchsschwanz ist dieses Werkzeug jedoch schnell gebaut. Kreuzweise L\u00f6cher nehmen einen gro\u00dfen Schraubendreher als Hebel auf.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Lochbrell-und-Belueftungsrohr-montiert.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4668\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Lochbrell-und-Belueftungsrohr-montiert.jpg\" alt=\"Bild Bienenfutterbereiter mit Lochbrett und Bel\u00fcftungsrohr\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Lochbrell-und-Belueftungsrohr-montiert.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Lochbrell-und-Belueftungsrohr-montiert-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 8: Die montierte runde Holzplatte mit dem Bel\u00fcftungsrohr<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Loesen-desLochbrettes-mit-Stockmeissel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4669\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Loesen-desLochbrettes-mit-Stockmeissel.jpg\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Loesen-desLochbrettes-mit-Stockmeissel.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Loesen-desLochbrettes-mit-Stockmeissel-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 9: Falls die runde Holzplatte einmal entfernt werden soll, ist ein Stockmei\u00dfel mit Dorn wertvoll Die Holzplatte klemmt sehr fest im Hobbock und kann ohne Werkzeug nicht mehr entfernt werden.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-das-Tuch-wird-eingelegt.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4666\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-das-Tuch-wird-eingelegt.jpg\" alt=\"Bild zeigt das Einlegen des Filtertuchs in den Bienenfutterautomat\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-das-Tuch-wird-eingelegt.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-das-Tuch-wird-eingelegt-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 10: Das Abtrockentuch erh\u00e4lt in der Mitte ein Loch f\u00fcr das Bel\u00fcftungsrohr und wird auf die gelochte Holzplatte gelegt. ACHTUNG UPDATE: Der Fluss durch das Abtrockentuch ist sehr langsam. Ggf. ist ein Honig-Seihtuch besser geeignet. Das wird noch getestet. UPDATE Ein Nylon Seihtuch scheint etwas schneller zu sein.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Nylon-Gewebe-als-Seih-Tuck.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4700\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Nylon-Gewebe-als-Seih-Tuck.jpg\" alt=\"Bild zeigt ein feines Nylongegewebe\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Nylon-Gewebe-als-Seih-Tuck.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/240930-Nylon-Gewebe-als-Seih-Tuck-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p>Abb. 11: UPDATE anderes Filtertuch. Nach dem ersten Test wurde dieses Nylon-Seihtuch statt des Abtrockentuchs eingebaut. Damit scheint es nun etwas schneller zu funktionieren.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-vorsichtig-an-das-Tuch-anarbeiten.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4674\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-vorsichtig-an-das-Tuch-anarbeiten.jpg\" alt=\"Bild der ersten Bef\u00fcllung des Bienenfutterautomaten mit Zucker\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-vorsichtig-an-das-Tuch-anarbeiten.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-vorsichtig-an-das-Tuch-anarbeiten-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 12: Zucker wird sorgf\u00e4ltig eingef\u00fcllt so, dass er das Tuch an die Gef\u00e4\u00dfwand dr\u00fcckt. ACHTUNG UPDATE: Das ist f<\/em><i>ummelig. bei pr\u00e4zise ges\u00e4gten runden Brettern gen\u00fcgt es ggf., das Tuch vor dem Einlegen um die Kante zu schlagen. Das wird noch getestet.\u00a0<\/i><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-glatt-rakeln.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4673\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-glatt-rakeln.jpg\" alt=\"Bild des Bienenfutterautomats mit seiner ersten Zuckerf\u00fcllung von 15 kg\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-glatt-rakeln.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-Zucker-glatt-rakeln-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p>Abb. 13: Die erste Bef\u00fcllung mit Zucker bis knapp unter die Kante oben. 15kg passen initial in diesen hier gezeigten Aufbau. Mit einem Kunststoffschaber k\u00f6nnen Sie den Zucker sch\u00f6n waagerecht glatt streichen.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-der-Hobbock-mit-Deckel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4667\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-der-Hobbock-mit-Deckel.jpg\" alt=\"\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-der-Hobbock-mit-Deckel.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Winterfutterautomat-der-Hobbock-mit-Deckel-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 14: Damit zwischen den Arbeitsschritten kein Staub in den Bienenfutter-Bereiter f\u00e4llt, wird der Deckel aufgelegt.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Schutzkiste-fuer-den-Bienenfutter-Bereiter.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4689\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Schutzkiste-fuer-den-Bienenfutter-Bereiter.jpg\" alt=\"Das Bild zeigt einen Schutz gegen ausgelaufenen Zuckersirup\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Schutzkiste-fuer-den-Bienenfutter-Bereiter.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Schutzkiste-fuer-den-Bienenfutter-Bereiter-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. 15: Eine Schutzkiste f\u00fcr den Bienenfutter-Bereiter. Das Gef\u00e4\u00df wird frostsicher im Keller aufgestellt. Damit ein Missgeschick nicht zum GAU &#8211; 40 Liter Zuckersirup ausgelaufen im Keller &#8211; wird, kommt der Bienenfutter-Bereiter auf ein Ikea-H\u00f6ckerchen (32 Jahre alt) und in eine Eurobox (140 Liter, 40 x 60 x60). Ein Abf\u00fcllkanister hat darin auch noch Platz. ACHTUNG UPDATE: Wer Platz hat sollte eine gr\u00f6\u00dfere Kiste w\u00e4hlen. Es funktioniert so, der Platz f\u00fcr den Kanister ist allerdings begrenzt und erfordert Aufmerksamkeit beim \u00d6ffnen des Quetschhahns.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Invertin-240925.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4646\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Invertin-240925.jpg\" alt=\"Das Bild zeigt einen Liter Invertase, Im Handel oft Invertier genannt.\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Invertin-240925.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Invertin-240925-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb. : Ein Liter Invertase, ausreichend f\u00fcr 500kg bis 1000kg Zucker. Die Invertase ist ein Enzym, das Haushaltszucker (chemisch Saccharose) teilweise in Fruchtzucker (Fruktose) und Traubenzucker (Glukose) aufspaltet. Wird der Zuckersirup in der Warmen Stube bereitet, schaffen 1-2ml pro kg Zucker das schon in eineinhalb Tagen. Bei k\u00fchlen Temperaturen hat Zuckerwasser hoher Konzentration nicht mehr die Gelegenheit, teilweise in Glukose und Fruktose aufzuspalten. Das von den Bienen eingelagerte Futter hat dann einen hohen Sachcharoseanteil und kann \u00fcber den Winter auskristallisieren. Als Folge k\u00f6nnen die Bienen ihr Futter nicht aufnehmen und &#8222;Verhungern auf der vollen Wabe&#8220;. Das kommt zumindest am Niederrhein selten vor, aber es kommt vor. Vorinvertiertes Futter verhindert das, da Sirup mit einem h\u00f6heren Fruktoseanteil so gut wie nicht auskristallisiert. Invertase hat ein Aktivit\u00e4tsoptimum bei einem PH-Wert von 4,5 bis 5 (Schafer 2012, S.47) und einer Temperatur von etwa 40\u00b0C.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Zitronensaeure-pH-Wert-Konzentration-empirisch.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4686\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Zitronensaeure-pH-Wert-Konzentration-empirisch.jpg\" alt=\"Bild zeigt den Test des pH-Wertes von Zitronens\u00e4urekonzentrationen\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Zitronensaeure-pH-Wert-Konzentration-empirisch.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Zitronensaeure-pH-Wert-Konzentration-empirisch-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb.16 : Empirische Ermittlung des pH-Wertes von Zitronens\u00e4ure der Abh\u00e4ngigkeit von der Gewichtskonzentration. Zur einfacheren Handhabung wurde zun\u00e4chst eine 10% Zitronens\u00e4urel\u00f6sung hergestellt (900g Wasser und 100g Zitronens\u00e4ure. Einem Liter Wasser wird in 2ml-Schritten die L\u00f6sung zugegeben und der PH-Wert mit Indikatorpapier gepr\u00fcft. Honig hat einen pH-Wert von im Schnitt 3,9. Invertase hat ein Aktivit\u00e4tsmaximum von 4,5. Das spricht daf\u00fcr, Wasser f\u00fcr Bienenfutter auf einen PH-Wert von 4,5 einzustellen und dazu 10 Liter Wasser etwa 40ml Zitronens\u00e4urel\u00f6sung 10% zuzusetzen.<\/em><\/p>\n<pre>ml Zugabe ph-Wert auf 10L Wasser\r\n 0        7,0       0 ml\r\n 2        6,0.     20 ml\r\n 3        5,0.     30 ml\r\n 4        4,5      40 ml  \r\n 6        4,0      60 ml\r\n 8        3,5      80 ml\r\n10        3,0     100 ml<\/pre>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Haushaltszucker-240525.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4645\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Haushaltszucker-240525.jpg\" alt=\"Das Bild zeigt eine Kiste mit 25 Paketen Haushaltszucker\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Haushaltszucker-240525.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Haushaltszucker-240525-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p><em>Abb.17 : Haushaltszucker ist Ende September 2024 mit 0,89\u20ac wieder erschwinglich. Damit lohnt es sich f\u00fcr Imker, das Winterfutter selber anzumischen. Das Bild zeigt eine Kiste mit 25 kg-Pakete Haushaltszucker. Chemisch ist Haushaltszucker reine Saccharose. Die Bienen f\u00fcgen bei der Verarbeitung Invertase aus k\u00f6rpereigenen Dr\u00fcsen hinzu, damit das eingelagerte Futter teilweise in Fruktose und Glukose umgewandelt wird.<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Refraktometer-Sirup-Bienenfutterbereiter.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4702\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Refraktometer-Sirup-Bienenfutterbereiter.jpg\" alt=\"Blick in ein Refraktometer mit Brix Skala.\" width=\"1024\" height=\"576\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Refraktometer-Sirup-Bienenfutterbereiter.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Refraktometer-Sirup-Bienenfutterbereiter-300x169.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Refraktometer-Sirup-Bienenfutterbereiter-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Abb.18 : Nach dem zweiten Durchlauf hat das Bienenfutter schon einen Zuckgehalt von 67 Grad Brix (=67 Gewichtsprozent ). das entspricht einem Wassergehalt von 32%. Mit einem &#8222;billigen&#8220; Refraktometer kann man das messen. Das Bild zeigt eine Aufnahme des Blicks in das Refraktometer mit einem preiswerten WLAN-Mikroskop.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Aufbau-Refraktometer-Aufnahme.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4701\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Aufbau-Refraktometer-Aufnahme.jpg\" alt=\"Dokumentationsaufbau mit Refraktometer und WLAN-Mikroskop\" width=\"576\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Aufbau-Refraktometer-Aufnahme.jpg 576w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Aufbau-Refraktometer-Aufnahme-169x300.jpg 169w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/a><\/p>\n<p>Abb. 19: Der Aufbau zur Dokumentation des Zuckergehaltes des frisch bereitete Bienenfutters. Das Refraktometer liegt etwas erh\u00f6ht auf einer Unterlage (orange im Bild), Davor wird das WLAN-Mikroskop positioniert und in der Sch\u00e4rfe eingestellt. Die Bilder landen dann auf dem Smartphone.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/241012-Bienenfutterbereiter-oben-bildet-sich-Aspergillus-niger.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-4789\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/241012-Bienenfutterbereiter-oben-bildet-sich-Aspergillus-niger.jpg\" alt=\"Das Bild zeigt den allgegenw\u00e4rtigen Aspergillus niger.\" width=\"1024\" height=\"576\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/241012-Bienenfutterbereiter-oben-bildet-sich-Aspergillus-niger.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/241012-Bienenfutterbereiter-oben-bildet-sich-Aspergillus-niger-300x169.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/241012-Bienenfutterbereiter-oben-bildet-sich-Aspergillus-niger-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Abb. 20: An der Grenzschicht zwischen Fl\u00fcssigkeitsspiegel und Luft im Zuckerbereich ist die Zuckerkonzentration geringer und Feuchtigkeit kondensiert an der Beh\u00e4lterwandung. Dadurch kann sich ein schwarzer Belag &#8211; Aspergillus niger &#8211; bilden. Vor jeder Neubef\u00fcllung kann der Belag leicht mit einem angefeuchteten K\u00fcchenkrepp entfernt werden. Flecken auf dem Zucker nimmt man mit einem Teel\u00f6ffel ab.<\/p>\n<h2>Anhang<\/h2>\n<h3><strong>Quellen und weiterf\u00fchrende Informationen<\/strong><\/h3>\n<p>Hiervon wurde dieser Beitrag inspiriert: <a href=\"https:\/\/www.bienenundnatur.de\/imkerpraxis\/spaetsommerpflege\/winterfutterautomat-von-hermann-spiegel-703\">Winterfutterautomat von Herrmann Spiegel<\/a><\/p>\n<p>Materialien<\/p>\n<p>Hobbock (40L) mit Quetschhahn <a href=\"https:\/\/www.holtermann-shop.de\/Honigernte\/abfuell-eimer-haehne\/Abfuell-Hobbock-40-kg.html\">https:\/\/www.holtermann-shop.de\/Honigernte\/abfuell-eimer-haehne\/Abfuell-Hobbock-40-kg.html\u00a0<\/a><\/p>\n<p>Polypropylenrohr zur Bel\u00fcftung <a href=\"https:\/\/www.bauhaus.info\/rohrleitungen\/schweissrohr\/p\/13562806\">https:\/\/www.bauhaus.info\/rohrleitungen\/schweissrohr\/p\/13562806<\/a><\/p>\n<p>F\u00fcr die Holzplatte wurde ein 40 Jahre altes Brett des Ikea Ivar Lagerregals ausges\u00e4gt. Googelsuche mit &#8222;Ikea Ivar boden 50&#8220; <a href=\"https:\/\/www.ikea.com\/de\/de\/p\/ivar-boden-kiefer-80318165\/\">https:\/\/www.ikea.com\/de\/de\/p\/ivar-boden-kiefer-80318165\/<\/a><\/p>\n<p>Zur Invertase-Aktivi\u00e4t: Sch\u00e4fer, Barbara (2012) Untersuchungen zur Regulation der Invertaseaktivit\u00e4t und zu Invertaseinhibitoren aus Pflanzenextrakten. W\u00fcrzburg, Dissertation. online Ressource: <a href=\"https:\/\/opus.bibliothek.uni-wuerzburg.de\/opus4-wuerzburg\/frontdoor\/deliver\/index\/docId\/5924\/file\/Promotion_Schaefer_2012.pdf\">https:\/\/opus.bibliothek.uni-wuerzburg.de\/opus4-wuerzburg\/frontdoor\/deliver\/index\/docId\/5924\/file\/Promotion_Schaefer_2012.pdf<\/a><\/p>\n<p>Zitronens\u00e4ure beim Lebensmittelchemischen Institut in K\u00f6ln: <a href=\"https:\/\/www.lci-koeln.de\/deutsch\/veroeffentlichungen\/lci-focus\/organische-saeuren-teil-ii-citronensaeure\">https:\/\/www.lci-koeln.de\/deutsch\/veroeffentlichungen\/lci-focus\/organische-saeuren-teil-ii-citronensaeure<\/a>.<\/p>\n<h3>Glosasar<\/h3>\n<h4>Hobbock<\/h4>\n<p>Ein Hobbock ist ein Eimer ohne Henkel und mit zwei seitlichen Tragegriffen. Hobbocks werden f\u00fcr den Transport und die Lagerung z.B. chemisch-technischer F\u00fcllg\u00fcter oder Lebensmittel wie Honig verwendet und aus Blech oder Kunststoff gefertigt. Der Begriff \u201eHobbock\u201c geht auf das Fischerdorf Hoboken nahe New York zur\u00fcck &#8211; . Die Fischer sollen die Fische in Metallbeh\u00e4ltern mit seitlichen Griffen \u00a0zu den M\u00e4rkten getragen haben. Der Duden hingegen leitet die Bezeichnung von der englischen Firma Hubbuck (landwirtschaftliche Ger\u00e4te) ab.<\/p>\n<h4>Quetschhahn<\/h4>\n<p>Ein Quetschhahn ist eine Vorrichtung zur Regelung des Abflusses von Fl\u00fcssigkeiten wie Wasser, Sirup oder Honig. In der Imkerei findet man Quetschh\u00e4hne an Honig-Abf\u00fcllbeh\u00e4ltern.<\/p>\n<h4>Saccharose<\/h4>\n<p>Saccharose (auch: Sucrose) ist ein Zweifachzucker oder Disaccharid. Handels\u00fcblicher Zucker (Haushaltszucker, Kristallzucker) besteht aus 100% Saccharose.. Saccharose besteht aus chemisch aus gleichen Anteilen von Glukose und Fruktose. Saccharose wird in Deutschland meist aus der Zuckerr\u00fcbe gewonnen, kann aber auch mit Zuckerrohr erzeugt werden.<\/p>\n<h4>Glukose<\/h4>\n<p>Glukose (auch: Dextrose, Glucose, Traubenzucker) ist ein Einfachzucker oder Monosachcharid. Glukose ist die Hauptenergiequelle f\u00fcr das Gehirn und wesentlicher Bestandteil im Muskel-Stoffwechsel. Glukose kann durch Investierung aus Saccharose gewonnen werden. Bei Menschen und Tieren wird Glukose in Form von Glykogen gespeichert, bei Pflanzen als St\u00e4rke.<\/p>\n<h4>Fruktose<\/h4>\n<p>Fruktose ist, so wie Glukose, ein Monosaccharid oder Einfachzucker. Gemeinsam bilden ein Fruktose- und ein Glukose-Molek\u00fcl Haushaltszucker (Saccharose). Fruktose schmeckt sehr s\u00fc\u00df und wird daher in der Getr\u00e4nkeindustrie eingesetzt. Einige Studien lassen vermuten, dass hohe Aufnahmen von Fruktose nachteilige Ver\u00e4nderungen im Energiestoffwechsel des K\u00f6rpers verursachen k\u00f6nnen. Fruktose wird als ein Ausl\u00f6ser f\u00fcr Diabetes verd\u00e4chtigt. Die meisten Menschen vertragen gr\u00f6\u00dferer Mengen von Fruktose schlecht. Fruktose hat technisch g\u00fcnstige Eigenschaften, so wird es als Feucwhthaltemittel in Lebensmitteln eingesetzt.<\/p>\n<h4>Invertase (Invertin, E1103)<\/h4>\n<p>Das Enzym Invertase spaltet Haushaltszucker (Saccharose) in Fruchtzucker und Traubenzucker auf. Der so gebildete Invertzucker neigt im Gegensatz zu Haushaltszucker in L\u00f6sungen nicht zur Kristallbildung. Invertzucker ist hygroskopisch und wird z.B. als Feucwhthaltemittel in Marzipan eingesetzt. Invertase gilt als gesundheitlich unbedenklich. In der EU ist Invertase als Lebensmittelzusatzstoff mit der Nummer E 1103 f\u00fcr alle Lebensmittel, die f\u00fcr Zusatzstoffe zugelassen sind, ohne H\u00f6chstmengenbeschr\u00e4nkung zugelassen. Die Invertaseaktivit\u00e4t von Honig ist ein Qualit\u00e4tsmerkmal und weist auf nicht w\u00e4rmebehandelten Honig hin.<\/p>\n<h4>Zitronens\u00e4ure (E330, Summenformel: C6H8O7)<\/h4>\n<p>Zitronens\u00e4ure geh\u00f6rt zu den Fruchts\u00e4uren und wurde 1784 zum ersten Mal von Carl Wilhem Scheele isoliert, die Struktur wurde 1838 durch Justus Liebig aufgekl\u00e4rt. Kristalline Zitronens\u00e4ure schmilzt \u00a0bei 100 \u00b0C. In Wasser ist Zitronens\u00e4ure \u00a0leicht l\u00f6slich (L\u00f6slichkeit 145 g\/100 g Wasser). \u00a0Zitronens\u00e4ure l\u00f6st sich \u00a0auch in Alkohol, nicht in organischen L\u00f6sungsmitteln wie Ether oder Chloroform. Zitronens\u00e4ure wird von Bienen leicht verstoffwechselt, im Citratcyclus bei Menschen werden bis zu 2kg pro Tag umgesetzt. In geringen Mengen eingenommen f\u00f6rdert Zitronens\u00e4ure indirekt das Knochenwachstum, in gr\u00f6\u00dferen Mengen wirkt sie jedoch toxisch (LD50 bei Ratten: 3 g\/kg). Zitronens\u00e4ure wird als S\u00e4uerungsmittel f\u00fcr Lebensmittel eingesetzt. Zitronensaft enth\u00e4lt 5\u20137 % Zitronens\u00e4ure.<\/p>\n<h4>Aspergillus niger<\/h4>\n<p>Aspergillus niger ist allgegenw\u00e4rtig. Aspergillus niger ist ein Schimmelpilz, der im Bad auf Silikondichtungen oder bei Hautunreinheiten als kleine schwarze P\u00fcnktchen beobachtet werden kann. In Fahrrad-Trinkflaschen stelle er sich auch bald ein, wenn man nicht nur klares Wasser, sondern isotonische Getr\u00e4nke einf\u00fcllt. Auch Zuckerwasser 1:1 in Kanistern f\u00fchrt zu schwarzen Flecken im Kanister. Trivialnamen f\u00fcr Aspergillus niger sind z.B. Gie\u00dfkannenschimmel oder Schwarzschimmel. Aspergillus niger ist ein opportunistischer Krankheitserreger, der also in einer Vielzahl von Innen- und Au\u00dfenbereichen vorkommt (Rintala et al. 2012). Die Sporen von A. niger k\u00f6nnen leicht aerosoliert (in Luft verwirbelt) werden (Li et. al. 2019) und haben das Potenzial, sich in den Bronchiolen der menschlichen Atemwege abzulagern (White et al. 2020). Zu Beeintr\u00e4chtigungen f\u00fchrt das i.d.R. nur bei einer \u00dcberempfindlichkeit.\u00a0 Bei erwachsenen Menschen mit intaktem Immunsystem kommen akute Aspergillosen nicht vor, bei Kindern sind sie sehr selten (Wikipedia, o.D.). Durch A. niger verursachte Infektionen k\u00f6nnen zur Entwicklung einer allergischen bronchopulmonalen Aspergillose (ABPA) oder einer invasiven Aspergillose f\u00fchren, die beide bei anf\u00e4lligen Patientengruppen t\u00f6dlich verlaufen k\u00f6nnen (Barac et al. 2018, Person et al. 2010). Einige der 40 Aspergillus-Arten k\u00f6nnen auch f\u00fcr Insekten sch\u00e4dlich sein: Einige Aspergillus Arten k\u00f6nnen als fakultative Endoparasiten in Insekten leben. Die Pilze dringen dabei in die Insekten ein und ern\u00e4hren sich von der H\u00e4molymphe. Aspergillus flavus beispielsweise bef\u00e4llt Schmetterlingsarten wie den Maisz\u00fcnsler (Ostrinia nubilalis) oder Hyalophora cecropia, wurde aber auch schon in Springschrecken (Orthoptera) nachgewiesen, die wiederum auch regelm\u00e4\u00dfig von Aspergillus parasiticus befallen werden. Wirtschaftlichen Schaden verursachen vor allem Aspergillus fumigatus und Aspergillus ochraceus, die Honigbienen (Apis) befallen. Aspergillus Arten sind f\u00fcr das Auftreten der Steinbrut in Bienenst\u00f6cken verantwortlich (Seyedmousavi et al. 2015). Inwieweit Aspergillus niger in geringen Konzentrationen Honigbienen sch\u00e4digt, ist nicht abschlie\u00dfend gekl\u00e4rt.<\/p>\n<p>Quellen:<\/p>\n<p>Rintala H, Pitk\u00e4ranta M, T\u00e4ubel M. (2012) Microbial communities associated with house dust. Adv Appl Microbiol 78:75\u2013120. doi: 10.1016\/B978-0-12-394805-2.00004-X.<\/p>\n<p>Li X, Zhang T, Wang S. (2019)\u00a0 Aerosolization of Aspergillus niger spores from colonies on different positions of a circular tube. E3S Web Conf 111:e02030. doi: 10.1051\/e3sconf\/201911102030.<\/p>\n<p>White JK, Nielsen JL, Madsen AM. (2020) Potential respiratory deposition and species composition of airborne culturable, viable, and non-viable fungi during occupancy in a pig farm. Atmosphere (Basel) 11:639. doi: 10.3390\/atmos11060639.<\/p>\n<p>Barac A, Ong DSY, Jovancevic L, Peric A, Surda P, Spiric VT, Rubino S. (2018) Fungi-induced upper and lower respiratory tract allergic diseases: one entity. Front Microbiol 9:583. doi: 10.3389\/fmicb.2018.00583.<\/p>\n<p>Person AK, Chudgar SM, Norton BL, Tong BC, Stout JE. (2010) Aspergillus niger: an unusual cause of invasive pulmonary aspergillosis. J Med Microbiol 59:834\u2013838. doi: 10.1099\/jmm.0.018309-0.<\/p>\n<p>Seyedmojtaba Seyedmousavi, Jacques Guillot, Pascal Arn\u00e9, G. Sybren de Hoog, Johan W. Mouton, Willem J. G. Melchers, Paul E. Verweij,\u00a0<em>Aspergillus<\/em>\u00a0and aspergilloses in wild and domestic animals: a global health concern with parallels to human disease,\u00a0<em>Medical Mycology<\/em>, Volume 53, Issue 8, November 2015, Pages 765\u2013797,\u00a0<a href=\"https:\/\/doi.org\/10.1093\/mmy\/myv067\" data-google-interstitial=\"false\">https:\/\/doi.org\/10.1093\/mmy\/myv067<\/a><\/p>\n<p>Wikipedia (ohne Datum) Gie\u00dfkannenschimmel. online Ressource <a href=\"https:\/\/de.wikipedia.org\/wiki\/Gie%C3%9Fkannenschimmel\">https:\/\/de.wikipedia.org\/wiki\/Gie%C3%9Fkannenschimmel<\/a> .<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=2675\/\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine bebilderte Anleitung f\u00fcr den Bau f\u00fcr einen Bienenfutter-Bereiter. Nachdem nun Haushaltszucker wieder erschwinglich ist, lohnt es sich f\u00fcr Imker, insbesondere das Winterfutter f\u00fcr Ableger selbst herzustellen. Achtung: Der Sirup-Durchlauf-Prozess &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1104,1105,1108,1109,922,1106,1107,482,481,691,1055],"class_list":["post-4644","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-bienenfutter","tag-bienenfutterbereiter","tag-fruktose","tag-glukose","tag-invertase","tag-invertier","tag-saccharose","tag-sirup","tag-winterfutter","tag-zucker","tag-zuckerwasser"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik<\/title>\n<meta name=\"description\" content=\"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik\" \/>\n<meta property=\"og:description\" content=\"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T19:40:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T17:51:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"25\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Bienenfutter-Bereiter selber bauen &#8211; Zuckersirup ohne r\u00fchren\",\"datePublished\":\"2024-09-25T19:40:30+00:00\",\"dateModified\":\"2025-09-19T17:51:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/\"},\"wordCount\":4030,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bienenfutterbereiter-Schemazeichnung.png\",\"keywords\":[\"Bienenfutter\",\"Bienenfutterbereiter\",\"Fruktose\",\"Glukose\",\"Invertase\",\"Invertier\",\"Saccharose\",\"Sirup\",\"Winterfutter\",\"Zucker\",\"Zuckerwasser\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/\",\"name\":\"Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bienenfutterbereiter-Schemazeichnung.png\",\"datePublished\":\"2024-09-25T19:40:30+00:00\",\"dateModified\":\"2025-09-19T17:51:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bienenfutterbereiter-Schemazeichnung.png\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Bienenfutterbereiter-Schemazeichnung.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienenfutter-Bereiter selber bauen &#8211; Zuckersirup ohne r\u00fchren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik","description":"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/","og_locale":"de_DE","og_type":"article","og_title":"Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik","og_description":"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.","og_url":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/","og_site_name":"Bienen und Technik","article_published_time":"2024-09-25T19:40:30+00:00","article_modified_time":"2025-09-19T17:51:25+00:00","og_image":[{"width":1024,"height":678,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png","type":"image\/png"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"25\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Bienenfutter-Bereiter selber bauen &#8211; Zuckersirup ohne r\u00fchren","datePublished":"2024-09-25T19:40:30+00:00","dateModified":"2025-09-19T17:51:25+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/"},"wordCount":4030,"image":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png","keywords":["Bienenfutter","Bienenfutterbereiter","Fruktose","Glukose","Invertase","Invertier","Saccharose","Sirup","Winterfutter","Zucker","Zuckerwasser"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/","url":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/","name":"Bienenfutter-Bereiter selber bauen - Zuckersirup ohne r\u00fchren - Bienen und Technik","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png","datePublished":"2024-09-25T19:40:30+00:00","dateModified":"2025-09-19T17:51:25+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Der Bienenfutterbereiter stellt ohne r\u00fchren eine ges\u00e4ttigte Zuckerwasserl\u00f6sung als Bienenfutter zur Verf\u00fcgung.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2024\/09\/Bienenfutterbereiter-Schemazeichnung.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/bienenfutterbereiter-selber-bauen-zuckersirup-ohne-ruehren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Bienenfutter-Bereiter selber bauen &#8211; Zuckersirup ohne r\u00fchren"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=4644"}],"version-history":[{"count":39,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4644\/revisions"}],"predecessor-version":[{"id":5505,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/4644\/revisions\/5505"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=4644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=4644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=4644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}