{"id":3491,"date":"2023-06-04T23:02:36","date_gmt":"2023-06-04T21:02:36","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=3491"},"modified":"2025-03-23T19:49:51","modified_gmt":"2025-03-23T18:49:51","slug":"bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/","title":{"rendered":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen"},"content":{"rendered":"<p><em>F\u00fcr das Mini Plus Beutensystem gibt es fast alles, leider keine Bienenfluchten f\u00fcr das sonst sehr praktische \u00dcberwinterungs-System, in dem ich mehrj\u00e4hrig Bienen halte. Eine Bienenflucht selber bauen f\u00fcr das Mini Plus \u00dcberwinterungs-System schafft hier Abhilfe. Auch mit nur wenig handwerklichem Geschick gelingt das schnell. Der Beitrag zeigt, wie das geht.<\/em><\/p>\n<p>Das Titelbild zeigt zwei Mini Plus \u00dcberwinterungszargen mit dazwischngelegter Bienenflucht.<\/p>\n<p><span style=\"color: #3366ff;\">Zitierung: Brell, Claus (2023) Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen. online Ressource, abrufbar unter https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/<\/span><\/p>\n<p>Stand 04.06.2023<\/p>\n<p>Update 21.03.2025 (vereinfachte Bauform, weniger Material, Beschreibung Porter Bienenflucht)<\/p>\n<p>Zu diesem Beitrag gibt es ein <a href=\"https:\/\/www.youtube.com\/watch?v=vr6dVYaX4c4\">youtube-Video &#8222;Selbstgebaute Bienenflucht in Mini Plus U\u0308berwinterungs-System&#8220;<\/a><\/p>\n<h2>Wie funktioniert eine Bienenflucht?<\/h2>\n<h3>Die Bienenflucht als Bienen-Einweg-Ventil<\/h3>\n<p>Die Bienenflucht besteht aus eine Trennplatte, die zwischen Zargen kommt, und einem Bauteil, das Bienen nur in einer Richtung (gut) durchl\u00e4sst. Das funktioniert heute bei den meisten Bienenfluchten mit spitz zulaufenden G\u00e4ngen. Sie sind anfangs breit und werden zum Ende hin immer enger. Das macht es f\u00fcr die Bienen leicht, hineinzulaufen, erschwert ihnen jedoch den R\u00fcckweg. Damit die Bienen den Eingang finden, sind gegen\u00fcber des Eingangs oft kleine L\u00f6cher angebracht, so dass Bienen die K\u00f6nigin riechen k\u00f6nnen. Sind sie erst mal im Eingang, ist der Luft- und Pheromonstrom aus Richtung des Ausgangs noch st\u00e4rker, so dass sie in dies Richtung laufen. Prinzipiell k\u00f6nnten Bienen auch zur\u00fcck, aber i.d.R. haben sie daf\u00fcr wenig Veranlassung, somit bekommt man mit einer Bienenflucht eine Honigzarge in 12-24 Stunden fast bienenfrei.<\/p>\n<p>Heute sind die Bienenfluchten aus Kunststoff.\u00a0 Erfunden hat sie Rufus Porter, die ersten Versionen waren aus Metall.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/01\/porter-bee-escape.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4905 size-medium\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/01\/porter-bee-escape-300x202.jpg\" alt=\"Porter Bee Escape, Porter-Bienenflucht, Prinzipskizze by Claus Brell\" width=\"300\" height=\"202\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/01\/porter-bee-escape-300x202.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/01\/porter-bee-escape-768x518.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2025\/01\/porter-bee-escape.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Abb. 1: Das Grundprinzip einer Bienenflucht<\/em><\/p>\n<h3>Bienenflucht nach Porter<\/h3>\n<p>Bei der Porter-Bienenflucht aus dem Jahr 1891, patentiert von Rufus Porter 1893 Patent No. 489,254, kamen zum Beispiel d\u00fcnne Metallfedern zum Einsatz, die die Bienen beim Passieren etwas auseinanderdr\u00fcckten. Diese mussten vor jedem Einsatz noch passgenau eingestellt werden. War die \u00d6ffnung zu eng, verstopfte sie schnell, war sie zu weit, konnten die Bienen zur\u00fcck gelangen. Manche Imker bohrten zus\u00e4tzlich ein paar kleine L\u00f6cher in den metallenen Fluchtaufsatz, damit der Stockgeruch besser hindurch dringen konnte &#8211; und daraus entstanden die heutigen Bienenfluchten aus Kunststoff.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Porter-Bienenflucht-Patent-1893.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-5203\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Porter-Bienenflucht-Patent-1893.png\" alt=\"Das Bild zeigt einen Auszug aus dem Patent von Rufus Porter Bienenflucht\" width=\"548\" height=\"294\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Porter-Bienenflucht-Patent-1893.png 548w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Porter-Bienenflucht-Patent-1893-300x161.png 300w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/a><\/p>\n<p><em>Abb. 1: Zungenventil f\u00fcr Bienen, aus der Patentschrift von Rufus Porter<\/em><\/p>\n<h2>Ausgangslage<\/h2>\n<h4>Bedarf<\/h4>\n<p>Nur wenige imkern &#8222;richtig&#8220; im Mini Plus \u00dcberwinterungssystem, eine Honigernte bleibt \u00fcberschaubar.<\/p>\n<p>Jedoch habe ich &#8211; in der erlebnisorientierten Imkerei &#8211; Bedarf an Futterwaben, die ich zum Ende des Winters den Bienen zur\u00fcck geben kann. Dazu friere ich die Waben ein. Da ich mit Naturbau arbeite, schmeckt der Wabenhonig sehr gut und hin und wieder entnehme ich ein R\u00e4hmchen mit Honig f\u00fcr den Eigenbedarf. Das macht mehr Freude mit unbebr\u00fcteten Waben, daher setze ich auch in Mini Plus Absperrgitter ein. Die Entnahme der kleinen Honigzargen ist f\u00fcr Bienen und Imker:in schonender, wenn eine Bienenflucht eingesetzt wird. <a href=\"https:\/\/cbrell.de\/blog\/honigzarge-fuer-mini-plus-ueberwinterungssystem-selber-bauen\/\">Honigzargen f\u00fcr das Mini Plus \u00dcberwinterungssystem kann man auch selber bauen<\/a>.<\/p>\n<h4>Konstruktionsprinzip<\/h4>\n<p>Nur wenige unterschiedliche Teile sind n\u00f6tig.<\/p>\n<p>Der Aufbau ben\u00f6tigt keine Spezialwerkzeuge und ist f\u00fcr jeden Heimwerker (Maker) machbar.<\/p>\n<p>Oberhalb und unterhalb der Bienenflucht ist ein beespace implementiert.<\/p>\n<h2>Material<\/h2>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-Material.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3495\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-Material-300x217.jpg\" alt=\"Bild Material Bienenflucht selber bauen\" width=\"300\" height=\"217\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-Material-300x217.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-Material-768x555.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-Material.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Abb. 2: Die Einzelteile vor dem Verleimen.<\/em><\/p>\n<p>Ben\u00f6tigt werden:<\/p>\n<ol>\n<li>1 Sperrholzbrett (Pappel) 50,9cm x 27,4cm x Dicke 8mm (mit 6mm funktioniert es auch)<\/li>\n<li>4 Rechteck-Kiefernleisten 10mm x 20mm x L\u00e4nge 48,9cm (2 f\u00fcr die vereinfachte Variante)<\/li>\n<li>4 Rechteck- Kiefernleisten 10mm x 20mm x L\u00e4nge 25,4cm (2 f\u00fcr die einfachte Variante)<\/li>\n<li>2 Imgut Bienenfluchteins\u00e4tze klein.<\/li>\n<li>etwas Wei\u00dfleim wasserfest (ich verwende gerne Ponal)<\/li>\n<li>Etwas Lein\u00f6l-Firniss, um die Au\u00dfenkanten wetterfester zu machen. Pappel-Sperrholz sollte nicht unbehandelt der Witterung ausgesetzt werden. Alternativ k\u00f6nnen die Au\u00dfenkanten auch mit wasserfestem Leim versiegelt werden. Fensterlasur oder Acryl-Lack funktionieren auch.<\/li>\n<\/ol>\n<h3>vereinfachte Bauform, Update 20.03.2025<\/h3>\n<p>Die Mini Plus \u00dcberwinterungszargen z.B. von Wagner oder Bieno natur haben den Beespace in der Zarge an der R\u00e4hmchenauflage, Dadurch kann man den unteren Leistensatz (zum Brutraum) weglassen. Die Bienenflucht verzieht sich trotzdem nicht. Die Rechteckleisten auf der Oberseite der Bienenflucht sind weiterhin erforderlich, da die R\u00e4hmchen in den Zargen mit dem Untertr\u00e4ger unten b\u00fcndig absclie\u00dfen. Die oben beschriebene Versiegelung der dem Wetter ausgesetzten Kanten hat sich bew\u00e4hrt,\u00a0 f\u00fcr mich w\u00e4re es jedoch einfacher, auf dem ersten Blick von weitem zu erkennen, wo ich eine Bienenflucht untergesetzt habe. Bei der vereinfachten Variante habe ich die Au\u00dfenkanten des Pappelsperrholzes mit einer klaren Fensterlasur (Sikkens) stabilisiert und mit farbigem Acryl-Lack\u00a0 &#8211; hier rot . gekennzeichnet. Absperrgitter bekommen einen hellgelben Kantenanstrich.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-vereinfacht-250321.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5201 size-medium\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-vereinfacht-250321-300x166.jpg\" alt=\"Das Bild zeigt eine Bienenflucht f\u00fcr das Mini Plus \u00dcberwinterungssystem in einer vereinfachten Bauform\" width=\"300\" height=\"166\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-vereinfacht-250321-300x166.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-vereinfacht-250321-768x424.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-vereinfacht-250321.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Abb. 3. Die Bienenflucht in einer vereinfachten Bauform. Die Rechteckleisten sind nur noch nach oben zum Honigraum hin. Die Kanten sind rot angestrichen &#8211; so erkennt man sofort, wo Bienenfluchten untergesetzt sind, der Lack bietet au\u00dferdem einen zus\u00e4tzlichen Verwitterungsschutz.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Werkzeug<\/h2>\n<ol>\n<li>Es gehr auch ohne, aber einfache Leimklemmen zum Fixieren sind praktisch und sparen Nerven beim Zusammenleimen.<\/li>\n<li>Eine Puks\u00e4ge, um die Kiefernleisten zu l\u00e4ngen.<\/li>\n<li>Ein Fuchsschwanz f\u00fcr die geraden S\u00e4geschnitte, um\u00a0 ggf.\u00a0 Pappel-Restsperrholz zu s\u00e4gen.<\/li>\n<li>Eine Stichs\u00e4ge, um den runden Ausschnitt f\u00fcr die Aufnahme der Bienenfluchteins\u00e4tze zu fertigen.<\/li>\n<li>80er Schmirgelpapier<\/li>\n<\/ol>\n<h2>Arbeitsablauf<\/h2>\n<ol>\n<li>Kiefernleisten abl\u00e4ngen<\/li>\n<li>Pappelsperrholz zurechts\u00e4gen, sofern nicht im Zuschnitt beschafft.<\/li>\n<li>Runde Ausschnitte mit dem Zirkel anzeichnen.<\/li>\n<li>Mit einem 8er Bohrer innen an der kante der zuk\u00fcnftigen Ausschnitte bohren.<\/li>\n<li>Beginnend am Bohrloch die runden Ausschnitte mit der Stichs\u00e4ge fertigen. Hier rentiert sich Sorgfalt, bei pr\u00e4zisem S\u00e4geschnitt k\u00f6nnen die Binenfluchteins\u00e4tze einfach eingesteckt werden und sie halten von selbst.<\/li>\n<li>Eine Seite der Holzplatte mit den Rechteckleisten versehen. Leim etwa 40 Minuzten trocknen lassen.<\/li>\n<li>Die andere Seite mit den Rechteck-Leiten versehen. Nun insgesamt 4 Stunden trocknen lassen.<\/li>\n<li>Alle Au\u00dfenkanten mit Schmirgelpapier brechen und gl\u00e4tten.<\/li>\n<li>Bienenfluchteins\u00e4tze in die Ausschnitte dr\u00fccken.<\/li>\n<\/ol>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-fertig.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3496\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-fertig-300x169.jpg\" alt=\"Bild Bienenflucht fertig\" width=\"300\" height=\"169\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-fertig-300x169.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-fertig-768x432.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-Mini-Plus-Ueberwinterung-fertig.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><em>Abb. 4: Die fertige Bienenflucht.<\/em><\/p>\n<h1>Glossar zu Bienenflucht selber bauen<\/h1>\n<h2>Absperrgitter<\/h2>\n<p>Ein Absperrgitter ist ein Hilfsmittel, um den Bewegungsbereich der Bienen innerhalb des Bienenstocks zu begrenzen. Es besteht aus einem Rahmen mit einem Gitter aus Metall oder Kunststoff. Das Gitter hat\u00a0 eine Maschenweite, die gro\u00df genug ist, um Arbeitsbienen hindurch zu lassen, aber klein genug, um die gr\u00f6\u00dfere K\u00f6nigin davon abzuhalten, hindurchzugehen. Mit Hilfe des Absperrgitters wird eine Honigzarge brutfrei gehalten.<\/p>\n<h2>Bienenflucht<\/h2>\n<p>Eine Bienenflucht ist eine Bienen-schonende und Imker:in-schonende Vorrichtung, die Bienen aus einer Honigzarge hinaus in die Brutzarge hinein leitet. Sie beinhaltet eine Art Einweg-Labyrinth. Die Bienen finden aus der Honigzarge hinaus, aber nicht mehr in die Honigzarge hinein. Oft ist dadurch der Honigraum schon nach 12 Stunden bienenfrei.<\/p>\n<p>Die Bienenflucht besteht in der Regel aus einem Plastik- oder MetallKanal. Die Bienenflucht wird zwischen dem Honigraum, in dem sich der zu erntende Honig befindet, und dem Brutraum platziert. Die Bienen werden vom Geruch der K\u00f6nigin angezogen &#8211; da die Bienen der K\u00f6nigin folgen, verlassen sie den Honigraum durch die Bienenflucht, um zu der K\u00f6nigin im Brutraum zu gelangen. Auf diese Weise kann Imker:in nach wenigen Stunden den Honigraum \u00f6ffnen und Honigwaben entnehmen, ohne die Bienen zu st\u00f6ren.<\/p>\n<h1>Quellen und Links<\/h1>\n<p><a href=\"https:\/\/cbrell.de\/blog\/imker-glossar\/\">Imker-Glossar<\/a><\/p>\n<p><a href=\"https:\/\/www.imkertechnik-wagner.de\/shop\/mini-plus\/mini-plus-ueberwinterung-modifiziert.html\">Ein Hersteller des Mini Plus \u00dcberwinterungssystem<\/a><\/p>\n<p><a href=\"https:\/\/patentimages.storage.googleapis.com\/0b\/5e\/67\/4f43578af5fecf\/US489754.pdf\">Die Patentschrift bee-escape von Rufus Porter aus 1893<\/a><\/p>\n<p>Eine <a href=\"https:\/\/www.holtermann-shop.de\/beutenzubehoer\/bienenfluchten\/kleine-bienenflucht-aus-kunststoff.html\">Bezusquelle (Holtermann) f\u00fcr Bienenflucht-Eins\u00e4tze von Imgut,<\/a> die bei mir gut funktionieren. Die Eins\u00e4tze gibt es bei fast allen Versendern von Imkereizubeh\u00f6r, auch im station\u00e4ren Handel.<\/p>\n<h2>Autor und Lizenz<\/h2>\n<p><strong>Autor:<\/strong> Prof. Dr. rer. nat. Claus Brell, aktuelle Projekte: <a href=\"https:\/\/clabremo.de\/steel4bees\/\">Steel4Bees<\/a>, <a href=\"http:\/\/bieneviernull.de\">Biene40<\/a>, <a href=\"https:\/\/ai4bee.de\">AI4Bee, <\/a>Bienensachverst\u00e4ndiger NRW, <a href=\"https:\/\/kivkv.de\/obmann-fuer-neue-methoden-der-bienenhaltung\/\">Obmann f\u00fcr neue Methoden der Bienenhaltung im Imkerkreisverband Krefeld\/Viersen<\/a><br \/>\n<strong>Lizenz:<\/strong> CC BY <img decoding=\"async\" src=\"https:\/\/licensebuttons.net\/l\/by\/3.0\/88x31.png\" \/><br \/>\nInhalte des Beitrages k\u00f6nnen entsprechen der Lizenz verwendet werden. Unter dieser Lizenz ver\u00f6ffentlichte Werke d\u00fcrfen von jedermann f\u00fcr private, gewerbliche und sonstige Zwecke genutzt, ver\u00e4ndert und auch neu ohne CC-Lizenz vermarktet werden. Als Urheber mache ich keine Rechte geltend. \u00dcber eine namentliche Nennung w\u00fcrde ich mich freuen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=7521\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr das Mini Plus Beutensystem gibt es fast alles, leider keine Bienenfluchten f\u00fcr das sonst sehr praktische \u00dcberwinterungs-System, in dem ich mehrj\u00e4hrig Bienen halte. Eine Bienenflucht selber bauen f\u00fcr das &#8230;<\/p>\n","protected":false},"author":1,"featured_media":3509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[183,896,1220,280,344,895,278,1218,1217,894,1219],"class_list":["post-3491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-bienen","tag-bienenflucht","tag-einweg","tag-honig","tag-honigbienen","tag-honigernte","tag-mini-plus","tag-patent","tag-porter","tag-ueberwinterung","tag-ventil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen<\/title>\n<meta name=\"description\" content=\"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen\" \/>\n<meta property=\"og:description\" content=\"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-04T21:02:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-23T18:49:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"575\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"9\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen\",\"datePublished\":\"2023-06-04T21:02:36+00:00\",\"dateModified\":\"2025-03-23T18:49:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/\"},\"wordCount\":1303,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg\",\"keywords\":[\"Bienen\",\"Bienenflucht\",\"Einweg\",\"Honig\",\"Honigbienen\",\"Honigernte\",\"Mini-Plus\",\"Patent\",\"Porter\",\"\u00dcberwinterung\",\"Ventil\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/\",\"name\":\"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg\",\"datePublished\":\"2023-06-04T21:02:36+00:00\",\"dateModified\":\"2025-03-23T18:49:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg\",\"width\":1024,\"height\":575,\"caption\":\"Bild Bienenflucht selbstgebaut im Mini Plus \u00dcberwinterungssystem\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen","description":"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/","og_locale":"de_DE","og_type":"article","og_title":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen","og_description":"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.","og_url":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/","og_site_name":"Bienen und Technik","article_published_time":"2023-06-04T21:02:36+00:00","article_modified_time":"2025-03-23T18:49:51+00:00","og_image":[{"width":1024,"height":575,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg","type":"image\/jpeg"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"9\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen","datePublished":"2023-06-04T21:02:36+00:00","dateModified":"2025-03-23T18:49:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/"},"wordCount":1303,"image":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg","keywords":["Bienen","Bienenflucht","Einweg","Honig","Honigbienen","Honigernte","Mini-Plus","Patent","Porter","\u00dcberwinterung","Ventil"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/","url":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/","name":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg","datePublished":"2023-06-04T21:02:36+00:00","dateModified":"2025-03-23T18:49:51+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Eine Bienenflucht leitet Bienen aus einer Honigzarge in die Brutzarge Der Selbstbau f\u00fcr den Mini Plus \u00dcberwinterungskasten ist ganz einfach.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/06\/Bienenflucht-fuer-das-Mini-Plus-Ueberwinterungssystem.jpg","width":1024,"height":575,"caption":"Bild Bienenflucht selbstgebaut im Mini Plus \u00dcberwinterungssystem"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/bienenflucht-selber-bauen-fuer-mini-plus-ueberwinterungs-system\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Bienenflucht f\u00fcr Mini Plus \u00dcberwinterungs-System selber bauen"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=3491"}],"version-history":[{"count":19,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3491\/revisions"}],"predecessor-version":[{"id":5212,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3491\/revisions\/5212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/3509"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=3491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=3491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=3491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}