{"id":3337,"date":"2023-03-04T10:09:54","date_gmt":"2023-03-04T09:09:54","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=3337"},"modified":"2023-03-04T11:46:34","modified_gmt":"2023-03-04T10:46:34","slug":"bluehmelder-fuer-imkervereine-projektidee","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/","title":{"rendered":"Bl\u00fchmelder f\u00fcr Imkervereine &#8211; Projektidee"},"content":{"rendered":"<p><em>Etwa 170.000 Imker:innen i Deutschland interessieren sich jedes Jahr aufs Neue f\u00fcr den Bl\u00fchbeginn in ihrer Region. F\u00fcr Imkervereine k\u00f6nnte ein vereinseigener und vereinsbezogener Bl\u00fchmelder ein Instrument sein, Mitglieder zur binden und im Vereinsdialog zu halten.<\/em><\/p>\n<p>Die Projektidee soll auch eine Komponente f\u00fcr das Vorhaben <a href=\"http:\/\/bieneviernull.de\">Biene40 -Entwicklung digitaler vernetzter Sensoren f\u00fcr vitalere Bienen<\/a> liefern.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/iot-und-webanwendungen-aktuelle-ideen-fuer-studentische-projekte\/\">Hier gehts zur \u00dcbersicht der Projektideen f\u00fcr das Modul Webanwendungen.<\/a><\/p>\n<p><em>Stand: 04.03.2023<\/em><\/p>\n<h2>Ausgangslage und Motivation<\/h2>\n<p>Der Bl\u00fchbeginn von sogenannten Zeigerpflanzen ist f\u00fcr Imker:iinnen und Landwirte gleicherma\u00dfen interessant. Der Beginn der Bl\u00fcte ist regional sehr unterschiedlich. Pflanzen und Tiere, insbesondere Honigbienen, orientieren sich im Jahresverlauf nicht an irgend einem Kalender, sondern an den sogenannten ph\u00e4nologischen Erscheinungen. Durch Kenntnis des Bl\u00fchbegins in der Region k\u00f6nnen Imkerinnen absch\u00e4tzen, wann die Bienen mit dem Nektareintrag (und damit der Honigproduktion) beginnen werden. Ihre notwendigen Arbeiten an den Bienen k\u00f6nnen sie damit im Jahresverlauf planen.<\/p>\n<p>Es gibt bereits Systeme im Internet, die ein Bl\u00fchmonitoring erm\u00f6glichen:<\/p>\n<p><a href=\"https:\/\/www.bienenkunde.rlp.de\/Bienenkunde\/Sonstiges\/Monitoring\/Uebersichtskarte\">https:\/\/www.bienenkunde.rlp.de\/Bienenkunde\/Sonstiges\/Monitoring\/Uebersichtskarte<\/a><\/p>\n<p>Die Projektidee hier fokussiert auf einen Dienst f\u00fcr Vereine und die Mitgliederbindung im Verein.<\/p>\n<h2>Ziel<\/h2>\n<p>Es existiert ein internetbasiertes System, das<\/p>\n<ol>\n<li>eine einfache M\u00f6glichkerit zur Eingabe von Bl\u00fchmeldungen bereitstellt,<\/li>\n<li>die Daten statistisch aufbereitet,<\/li>\n<li>eine Einbettung in Vereinsseiten erm\u00f6glicht.<\/li>\n<\/ol>\n<p>Dabei sind die Designparadigmen<\/p>\n<ol>\n<li>besonders niederschwelliger Zugang f\u00fcr Bl\u00fchmeldende<\/li>\n<li>kein &#8222;verwaltungsaufwand&#8220; (keine Nutzende-Verwaltung etc.)<\/li>\n<li>mobile first<\/li>\n<li>&#8222;\u00dc50&#8220; geeignet<\/li>\n<li>Betrieb auf beliebigen Webspaceangeboten<\/li>\n<\/ol>\n<p>ma\u00dfgeblich.<\/p>\n<h2>Konzeptideen<\/h2>\n<h3>Anwendungsf\u00e4lle<\/h3>\n<p>Der Bl\u00fchmelder soll die Anwendungsf\u00e4lle<\/p>\n<ol>\n<li>Eingabe eines Pflanzennamens und \/ oder<\/li>\n<li>Hochladen eines Smartphonephotos der bl\u00fchenden Pflanze<\/li>\n<li>Eingabe des tages der Sichtung<\/li>\n<li>Eingabe des eigenen Namens (und Vornamens)<\/li>\n<li>Kontrolle und Ansehen der eigenen Eingabe<\/li>\n<li>\u00dcbersicht \u00fcber die Eingaben anderer<\/li>\n<\/ol>\n<p>erm\u00f6glichen.<\/p>\n<p>Ein Zusatzangebot ist die Anzeige von Wetterdaten auf Karten in der Umgebung des Vereins.Hierzu ist ein Dienst der clabremo GmbH zu nutzen. Die erforderlichen Geokoordinaten entsprechen den Koordinaten des Vereinsstandortes.<\/p>\n<p>Aus Sicht des Vereins ist eine Einbindung in die Vereinswebseite mit Vereinspersonalsierung (Logo und Name des Vereins) vorzusehen. Die ggf. notwendige Administration (Einpflegen der Vereinsparameter) soll nicht im Self-Service erfolgen, sondern durch die zentrale Bereitstellung der Applikation.<\/p>\n<h3>Benutzungsoberfl\u00e4che<\/h3>\n<p>Zur Eingabe ist erforderlich: Name oder Spitzname, Vorname (opional), Name der Pflanze, alternativ oder erg\u00e4nzend Hochladen eines Smartphonephotos.<\/p>\n<p>Eingabefelder: Name (Spitzname), Vorname, Pflanzenname, Aufnahmetag<\/p>\n<p>Anzeige: Anwendungsname (B40 Bl\u00fchmelder), Vereinslogo, Angaben aus der Bl\u00fchmeldung, Wetter aus der Umgebung des Vereins<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-1-Eingabe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3342\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-1-Eingabe.jpg\" alt=\"Bild Mockup Bl\u00fchmelder Eingabebildschirm\" width=\"768\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-1-Eingabe.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-1-Eingabe-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p>Abb. 1: Mockup \/ Visualisierung des Eingabebildschirms<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-2-Ergebnis.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3343\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-2-Ergebnis.jpg\" alt=\"Bild Mockup Bl\u00fchmelder Ergebnisbildschirm\" width=\"768\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-2-Ergebnis.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-2-Ergebnis-225x300.jpg 225w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p>Abb. 2: Mockup \/ Visualisierung des Ergebnisbildschirms<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-3-Statitik.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3344\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-3-Statitik.jpg\" alt=\"Bild Mockup Bl\u00fchmelder Ergebnisseite\" width=\"951\" height=\"1024\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-3-Statitik.jpg 951w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-3-Statitik-279x300.jpg 279w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Mockup-Bluehmelder-3-Statitik-768x827.jpg 768w\" sizes=\"auto, (max-width: 951px) 100vw, 951px\" \/><\/a><\/p>\n<p>Abb. 3: Mockup \/ Visualisierung eine \u00dcbersicht \/ Statistik \u00fcber die Bl\u00fchmeldungen<\/p>\n<h3>Toplogie<\/h3>\n<p>Der Weg der Daten k\u00f6nnte wie folgt aussehen:<\/p>\n<pre>Mensch -&gt; Browser -&gt;  ))) WLAN, LTE o\u00e4 ((( Router -&gt; Internet -&gt; Webserver[Webservice-&gt;Datenbank-&gt;Visualisierung]-&gt; Internet-&gt; Browser-&gt;Mensch<\/pre>\n<h2>Rahmenbedingungen<\/h2>\n<h3>Programmierumgebung<\/h3>\n<p>Als Programmierumgebung ist HTML, CSS, Javascript auf der Clientseite und PHP, Datenhaltung in flachen Dateien (TXT oder CSV, in begr\u00fcndeten Ausnahmef\u00e4llen JSON oder XML) oder in SQLite zul\u00e4ssig.<\/p>\n<p>Auf die Einbettung von Fremdbibliotheken ist zu verzichten. JQuery und Bootstrap ist mit Begr\u00fcndung zul\u00e4ssig, die erforderlichen dateien sind dem Speicherort der Anwendung hinzuzuf\u00fcgen.<\/p>\n<p>Auf die Verwendung von Fremdbildern, Schriften oder Diensten Dritter ist zu verzichten. Einzige Ausnahme sind die durch clabremo GmbH zur verf\u00fcgung gestellten Wetterdaten.<\/p>\n<h2>Glossar<\/h2>\n<h3>Bl\u00fchbeginn<\/h3>\n<p>Als Bl\u00fchbeginn bezeichnet man das Einsetzen der Bl\u00fcte. Wichtig f\u00fcr Landwirte und Imker:innen (f\u00fcr Honigbienen, Wildbienen und Hummeln sowie weiteren Best\u00e4uberinsekten wie Schwebfliegen) sind\u00a0 Obstb\u00e4umen, Str\u00e4uchen und anderen Zeigerpflanzen. Der Bl\u00fchbeginn ist ein wichtiges ph\u00e4nologisches Merkmal und abh\u00e4ngig von der <a href=\"https:\/\/cbrell.de\/blog\/waermesumme\/\">Temperatursumme (oder W\u00e4rmesumme)<\/a>, die je nach Pflanzenart einen bestimmten Betrag erreichen muss, ehe die Bl\u00fcte beginnt. Der Hauptbl\u00fchbeginn liegt im Fr\u00fchling, ab dem Fr\u00fchherbst ist der Bl\u00fchbeginn f\u00fcr alle Pflanzen abgeschlossen. Im Winter herrscht normalerweise allgemeine Vegetationsruhe, es gibt allerdings Pflanzen (Rosen, Rosmarin u.a.) die an gesch\u00fctzten Pozitionen auch Weihnachten bl\u00fchen.<\/p>\n<h3>Ph\u00e4nologie<\/h3>\n<p>Ph\u00e4nologie oder Erscheinungslehre bezeichnet die Lehre von witterungs- bzw. klimaabh\u00e4ngigen Lebens\u00e4u\u00dferungen von Organismen im Jahresablauf. Das k\u00f6nnen\u00a0 Wachstumserscheinungen bei Pflanzen sein, wie z.B. das oberirdische Erscheinen, Knospung (Knospe), Bl\u00fctenbildung sprich Bl\u00fchbeginn oder Laubfall (Blattfall), oder um das Auftreten fliegender Insekten, Paarungszeiten und Zug bei V\u00f6geln (Vogelzug) oder Winterschlaf bei S\u00e4ugern. Die beobachtung der Ph\u00e4nologie ist f\u00fcr alle wichtig, die irgendwie mit der belebten Natur arbeiten (landwirte, Tierwirte, Imker).<\/p>\n<h3>Topologie<\/h3>\n<p>Eine Topologie ist eine grafische Darstellung der Ger\u00e4te und Programme eines Anwendungssystems. Eine Topologie dient dazu Restriktionen und Rahemnbedingungen in einem Projekt zu identifizieren und den Projektbeteiligten ein &#8222;Bild&#8220; der Anwednung zu geben.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/topologie\/\">Eine detailliertere Beschreibung Toloplogie finden Sie hier.<\/a><\/p>\n<h3>Visualisierung<\/h3>\n<p>Visualisierung ist die Verwendung von Bildern, Graphiken oder Diagrammen, um komplexe Informationen darzustellen und verst\u00e4ndlich zu machen. Es handelt sich dabei um eine Methode, um Daten und Informationen schneller und einfacher zu erfassen und zu verstehen. Visualisierung kann in vielen Bereichen wie Wissenschaft, Wirtschaft, Medien und Design verwendet werden. Einige Beispiele f\u00fcr die Verwendung von Visualisierung sind:<\/p>\n<ul>\n<li>Graphen und Diagramme in Finanzberichten, um Finanzdaten darzustellen.<\/li>\n<li>Karten und Infografiken in Nachrichtenberichten, um geografische Daten zu verdeutlichen.<\/li>\n<li>medizinischen Bildgebung, um z.B. R\u00f6ntgenaufnahmen oder MRT-Scans f\u00fcr das Patientengespr\u00e4ch anzureichern.<\/li>\n<\/ul>\n<p>Es gibt verschiedene Arten von Visualisierungstechniken, wie z.B. die Verwendung von Farben, Formen, Gr\u00f6\u00dfen und Layout, um Daten hervorzuheben und zu strukturieren. Eine gute Visualisierung sollte pr\u00e4zise, verst\u00e4ndlich und aussagekr\u00e4ftig sein und es den Betrachtern erm\u00f6glichen, schnell und einfach wichtige Informationen zu erfassen.<\/p>\n<div><\/div>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=9737\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Etwa 170.000 Imker:innen i Deutschland interessieren sich jedes Jahr aufs Neue f\u00fcr den Bl\u00fchbeginn in ihrer Region. F\u00fcr Imkervereine k\u00f6nnte ein vereinseigener und vereinsbezogener Bl\u00fchmelder ein Instrument sein, Mitglieder zur &#8230;<\/p>\n","protected":false},"author":1,"featured_media":3346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[576,842,577,674],"class_list":["post-3337","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","tag-bienenhaltung","tag-bluehbeginn","tag-imkerei","tag-phaenologischer-kalender"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee<\/title>\n<meta name=\"description\" content=\"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee\" \/>\n<meta property=\"og:description\" content=\"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-04T09:09:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-04T10:46:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Bl\u00fchmelder f\u00fcr Imkervereine &#8211; Projektidee\",\"datePublished\":\"2023-03-04T09:09:54+00:00\",\"dateModified\":\"2023-03-04T10:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/\"},\"wordCount\":908,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Bluehmelder-Phaenologie.jpg\",\"keywords\":[\"Bienenhaltung\",\"Bl\u00fchbeginn\",\"Imkerei\",\"phaenologischer Kalender\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/\",\"name\":\"Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Bluehmelder-Phaenologie.jpg\",\"datePublished\":\"2023-03-04T09:09:54+00:00\",\"dateModified\":\"2023-03-04T10:46:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Bluehmelder-Phaenologie.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/Bluehmelder-Phaenologie.jpg\",\"width\":1024,\"height\":439,\"caption\":\"Bild Bl\u00fchmelder und Ph\u00e4nologie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/bluehmelder-fuer-imkervereine-projektidee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bl\u00fchmelder f\u00fcr Imkervereine &#8211; Projektidee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee","description":"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/","og_locale":"de_DE","og_type":"article","og_title":"Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee","og_description":"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.","og_url":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/","og_site_name":"Bienen und Technik","article_published_time":"2023-03-04T09:09:54+00:00","article_modified_time":"2023-03-04T10:46:34+00:00","og_image":[{"width":1024,"height":439,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg","type":"image\/jpeg"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Bl\u00fchmelder f\u00fcr Imkervereine &#8211; Projektidee","datePublished":"2023-03-04T09:09:54+00:00","dateModified":"2023-03-04T10:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/"},"wordCount":908,"image":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg","keywords":["Bienenhaltung","Bl\u00fchbeginn","Imkerei","phaenologischer Kalender"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/","url":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/","name":"Bl\u00fchmelder f\u00fcr Imkervereine - Projektidee","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg","datePublished":"2023-03-04T09:09:54+00:00","dateModified":"2023-03-04T10:46:34+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Ein Bl\u00fchmelder erm\u00f6glicht, die Beobachtung von Bl\u00fchbeginnen in einer Datenbank zu erfassen. Der Mehrwert ergibt sich, wenn viele mitmachen.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2023\/03\/Bluehmelder-Phaenologie.jpg","width":1024,"height":439,"caption":"Bild Bl\u00fchmelder und Ph\u00e4nologie"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/bluehmelder-fuer-imkervereine-projektidee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Bl\u00fchmelder f\u00fcr Imkervereine &#8211; Projektidee"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=3337"}],"version-history":[{"count":5,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3337\/revisions"}],"predecessor-version":[{"id":3345,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/3337\/revisions\/3345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/3346"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=3337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=3337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=3337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}