{"id":2965,"date":"2022-11-08T18:41:33","date_gmt":"2022-11-08T17:41:33","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=2965"},"modified":"2022-11-21T12:45:16","modified_gmt":"2022-11-21T11:45:16","slug":"programmier-entwicklungsumgebungen-im-vergleich","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/","title":{"rendered":"Programmier-Entwicklungsumgebungen im Vergleich"},"content":{"rendered":"<p><em>Um Algorithmen im Computer zu implementieren, k\u00f6nnen Sie sich verschiedener Werkzeuge bedienen. Die Spannbreite reicht von einfachen Texteditoren bis zu schwergewichtigen Umgebungen. In loser Reihenfolge lernen Sie hier verschiedene Programmier-Entwicklungsumgebungen kennen. Dabei wird &#8211; wenn m\u00f6glich und sinnvoll, eine kurze Einsch\u00e4tzung f\u00fcr die Eignung je nach Anwendungsfall gegeben.<\/em><\/p>\n<p>Stand 21.11.2022<\/p>\n<h2>Texteditor vs. IDE<\/h2>\n<p>Eine IDE (integrated development environment) nimmt Ihnen vieles an operativen Arbeiten bei der Programmierung ab. Das f\u00fchrt bei Programmieranf\u00e4ngern zu dem Umstand, dass diese oft ihre Programm nur in der Umgebung laufen lassen k\u00f6nnen und nicht in der Lage sind, die Programme weiterzugeben (prominente Beispiele: Visual Studio Community, Eclipse). Wer hingegen in der Lage ist, mit einem Texteditor ein Programm zu schreiben und manuell zu kompilieren, hat meist auch den Entwicklungsprozess als solchen verstanden. In didaktische Sujets (Schule, Hochschule) sollte daher grunds\u00e4tzlich erst mit einfachen Werkzeugen begonnen werden. Der unmittelbare Einsatz schwergewichtiger Entwicklungsumgebungen macht Lerner in der Regel dumm.<\/p>\n<p>Bei der Verwendung von einfachen Texteditoren, die Syntax-Highlighting beherrschen (prominente Beispiele sind Notepad++ oder Sublime Text) stellt sich meist schnell eine Verst\u00e4ndnis f\u00fcr den Programmerstellungsablauf ein. Die farbliche Markierung des Quelltextes ist eine gro\u00dfe Hilfe bei der Fehlersuche.<\/p>\n<p>Es geht aber auch &#8222;ganz ohne&#8220; mit rudiment\u00e4ren Editoren wie nano im Linux-Terminal oder Notepad unter Windows.<\/p>\n<h2>Einfachste Texteditoren<\/h2>\n<h3>nano<\/h3>\n<p>nano ist ein einfacher Texteditor im Linux- oder Mac-Terminal. nano kann auch \u00fcber einen ssh-Login z.B. auf einem Raspberry Pi genutzt werden. Um ein kleines Python Programm auszuprobieren, ist nano ausreichend und besonders geeignet, wenn gar keine grafische Oberfl\u00e4che zur Verf\u00fcgung steht. Rudiment\u00e4r hat nano auch Syntax-Highlighting.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3015 size-full\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg\" alt=\"Screenshot des Editors Nano\" width=\"732\" height=\"491\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg 732w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121-300x201.jpg 300w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/a><\/p>\n<p>Abb. 1: nano im Terminal \u00fcber ssh, Python-Programmierung auf dem Raspberry<\/p>\n<h2>Texteditoren mit grafischer Benutzungsoberfl\u00e4che<\/h2>\n<h3>Notepad++<\/h3>\n<h3>Sublime Text<\/h3>\n<p>Sublime Text ist ein Editor mit Unterst\u00fctzung f\u00fcr viele Programmiersprachen und Betriebssysteme.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3016 size-large\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121-1024x727.jpg\" alt=\"Screenshot Editor Sublime Text auf dem Mac\" width=\"1024\" height=\"727\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121-300x213.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121-768x545.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-sublime-text-221121-1536x1091.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Abb. 2: Sublime Text im Einsatz auf MacOS, PHP-Programmierung<\/p>\n<h3>Atom<\/h3>\n<h3>Brackets<\/h3>\n<h2>Einfachere Entwicklungsumgebungen<\/h2>\n<h3>Arduino-IDE<\/h3>\n<p>Die Arduino-IIDE ist urspr\u00fcnglich die Entwicklungsumgebung f\u00fcr den Microcontroler Arduino. Die Programmierung erfolgt in C\/C++. Die Arduino IDE ist relativ offen, so dass mittlerweile fast alle Controller (ESP32, STMxxx, Raspberry Pico u.v.m.) damit programmiert werden k\u00f6nnen.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-arduino-ide-221121.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3017 size-full\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-arduino-ide-221121.jpg\" alt=\"Screenshot Arduino IDE\" width=\"838\" height=\"617\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-arduino-ide-221121.jpg 838w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-arduino-ide-221121-300x221.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-arduino-ide-221121-768x565.jpg 768w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" \/><\/a><\/p>\n<p>Abb. 3: Arduino IDE auf dem Mac<\/p>\n<h3>Thonny<\/h3>\n<p>Thonny ist ein Python-Editor, der eine einfache Anbindung von Microcontrollern wie dem Raspberry Pico erm\u00f6glicht. Thonny l\u00e4uft auch auf schw\u00e4cheren Rechnern wie dem Raspberry Pi. Thonny wird direkt mit der aktuellen PythonVersion ( 3.10 ) ausgeliefert, so dass nur ein einfaches Installationsprogramm erforderlich ist, um das Programmieren zu lernen. Die Benutzeroberfl\u00e4che ist aufger\u00e4umt und frei von allen Funktionen, die insbesondere Anf\u00e4nger ablenken.<\/p>\n<p>Thonny l\u00e4sst sich einfach installieren und l\u00e4uft auf Windows 11, 10, 8, 7 , machOS und Linux. Unter Windows belegt Thonny mit Python etwa 390 MB.<\/p>\n<p>Download-Link: <a href=\"https:\/\/thonny.org\">https:\/\/thonny.org<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-thonny-IDE-221121.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3019 size-full\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-thonny-IDE-221121.jpg\" alt=\"Screenshot Thony IDE\" width=\"1182\" height=\"938\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-thonny-IDE-221121.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-thonny-IDE-221121-300x238.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-thonny-IDE-221121-768x609.jpg 768w\" sizes=\"auto, (max-width: 1182px) 100vw, 1182px\" \/><\/a><\/p>\n<p>Abb. 4: Thonny IDE auf dem Mac mit einem einfachen Python Programm<\/p>\n<p>&nbsp;<\/p>\n<h2>Integrierte Umgebungen f\u00fcr Frameworks<\/h2>\n<h3>Visual Studio (Community \/ Enterprise)<\/h3>\n<p>Visual Studio ist die professionelle Umgebung von Microsoft. zur Entwicklung im Dot Net Framework.<\/p>\n<h3>Visual Studio Code<\/h3>\n<p>Visual Studio Code ist ein freier Editor von Microsoft und ist insbesondere im Zusammenspiel mit dem Dot-Net Framework geeignet.<\/p>\n<h3>Eclipse<\/h3>\n<p>Eclipse ist eine Umgebung f\u00fcr und mit Java, hat allerdings den Anspruch, f\u00fcr alle Frameworks und Umgebungen geeignet zu sein.<\/p>\n<h2>Spezialumgebungen<\/h2>\n<h3>Jupyter Notebook (Nachfolger: Jupyter Lab)<\/h3>\n<p>Der Name Jupyter setzt sich aus den Anfangsbuchstaben der Programmiersprachen <a class=\"inf-text-link\" href=\"https:\/\/www.bigdata-insider.de\/was-ist-julia-a-863261\/\">Julia<\/a>,\u00a0<a class=\"inf-text-link\" href=\"https:\/\/www.bigdata-insider.de\/was-ist-python-a-730480\/\">Python<\/a> und der Statistiksprache R zusammen. allerdings unterst\u00fctzt Jupyter aber auch zahlreiche weitere Sprachen wie C++, Ruby, Haskell, PHP, Java. Kernprodukt des J\u00fapyter-Universums ist Jupyter Notebook. Jupyter Notebook gibt es seit 2015 uns ist\u00a0 eine Software zum kollaborativem Verarberiten interaktiver Arbeitsbl\u00e4tter nach dem Client-Server-Prinzip arbeitet. In einem Jupyter Notebook ausf\u00fchrbarer Programmcode mit Ergebnissen wie\u00a0 Zahlen, Texte, Grafiken bereitstellen. Der Zugriff erfolgt mittels Webbrowser. Jupyter Notebooks werden als\u00a0 JSON-(JavaScript Object Notation)Dateien gespeichert. Typische Anwendungsm\u00f6glichkeiten sind Datenanalysen und -visualisierungen sowie Machine Learning.<\/p>\n<p>Jupyter Notebook kann auf dem eigenen Rechner installiert werden. Ebenso ist eine Nutzung \u00fcber ein Google Konto m\u00f6glich (Google colab).<\/p>\n<h2>Fazit Programmier-Entwicklungsumgebungen<\/h2>\n<p>Programmier-Neulinge und erfahrene Entwickler:innen k\u00f6nnen sich aus einem breitgef\u00e4cherten Portfolio an Entwicklungsumgebungen bedienen.<\/p>\n<p>F\u00fcr den Prorammier-Einstieg sei zun\u00e4chst ein einfacher Editor empfohlen.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=8127\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um Algorithmen im Computer zu implementieren, k\u00f6nnen Sie sich verschiedener Werkzeuge bedienen. Die Spannbreite reicht von einfachen Texteditoren bis zu schwergewichtigen Umgebungen. In loser Reihenfolge lernen Sie hier verschiedene Programmier-Entwicklungsumgebungen &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[583,743,730,746,729,731,744,111,728,110,705,745],"class_list":["post-2965","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-arduino","tag-atom","tag-c-c","tag-eclipse","tag-ide","tag-java","tag-notepad","tag-php","tag-programierung","tag-python","tag-thonny","tag-visual-studio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Programmier-Entwicklungsumgebungen im Vergleich<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Programmier-Entwicklungsumgebungen im Vergleich\" \/>\n<meta property=\"og:description\" content=\"Um Algorithmen im Computer zu implementieren, k\u00f6nnen Sie sich verschiedener Werkzeuge bedienen. Die Spannbreite reicht von einfachen Texteditoren bis zu schwergewichtigen Umgebungen. In loser Reihenfolge lernen Sie hier verschiedene Programmier-Entwicklungsumgebungen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-08T17:41:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T11:45:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Programmier-Entwicklungsumgebungen im Vergleich\",\"datePublished\":\"2022-11-08T17:41:33+00:00\",\"dateModified\":\"2022-11-21T11:45:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/\"},\"wordCount\":694,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/screenshot-editor-nano-221121.jpg\",\"keywords\":[\"Arduino\",\"Atom\",\"C\\\/C++\",\"Eclipse\",\"IDE\",\"Java\",\"Notepad\",\"PHP\",\"Programierung\",\"Python\",\"Thonny\",\"Visual Studio\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/\",\"name\":\"Programmier-Entwicklungsumgebungen im Vergleich\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/screenshot-editor-nano-221121.jpg\",\"datePublished\":\"2022-11-08T17:41:33+00:00\",\"dateModified\":\"2022-11-21T11:45:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/screenshot-editor-nano-221121.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/screenshot-editor-nano-221121.jpg\",\"width\":732,\"height\":491,\"caption\":\"Screenshot des Editors Nano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/programmier-entwicklungsumgebungen-im-vergleich\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programmier-Entwicklungsumgebungen im Vergleich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Programmier-Entwicklungsumgebungen im Vergleich","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/","og_locale":"de_DE","og_type":"article","og_title":"Programmier-Entwicklungsumgebungen im Vergleich","og_description":"Um Algorithmen im Computer zu implementieren, k\u00f6nnen Sie sich verschiedener Werkzeuge bedienen. Die Spannbreite reicht von einfachen Texteditoren bis zu schwergewichtigen Umgebungen. In loser Reihenfolge lernen Sie hier verschiedene Programmier-Entwicklungsumgebungen ...","og_url":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/","og_site_name":"Bienen und Technik","article_published_time":"2022-11-08T17:41:33+00:00","article_modified_time":"2022-11-21T11:45:16+00:00","og_image":[{"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg","type":"","width":"","height":""}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Programmier-Entwicklungsumgebungen im Vergleich","datePublished":"2022-11-08T17:41:33+00:00","dateModified":"2022-11-21T11:45:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/"},"wordCount":694,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg","keywords":["Arduino","Atom","C\/C++","Eclipse","IDE","Java","Notepad","PHP","Programierung","Python","Thonny","Visual Studio"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/","url":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/","name":"Programmier-Entwicklungsumgebungen im Vergleich","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg","datePublished":"2022-11-08T17:41:33+00:00","dateModified":"2022-11-21T11:45:16+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2022\/11\/screenshot-editor-nano-221121.jpg","width":732,"height":491,"caption":"Screenshot des Editors Nano"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/programmier-entwicklungsumgebungen-im-vergleich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Programmier-Entwicklungsumgebungen im Vergleich"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=2965"}],"version-history":[{"count":7,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2965\/revisions"}],"predecessor-version":[{"id":3021,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2965\/revisions\/3021"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=2965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=2965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=2965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}