{"id":2434,"date":"2022-02-08T21:37:17","date_gmt":"2022-02-08T20:37:17","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=2434"},"modified":"2022-02-08T21:54:00","modified_gmt":"2022-02-08T20:54:00","slug":"senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/","title":{"rendered":"Senatspreis 2013 kesh f\u00fcr iOS &#8211; Entwicklung eines mobilen Bezahlsystems mit agilen Methoden"},"content":{"rendered":"<p><em>Achtung, die Internetverweise in dieser historischen Unterlage sind mittlerweile nicht mehr erreichbar.<\/em><\/p>\n<p><strong>Senatspreis 2013<\/strong><\/p>\n<p>Kandidat: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Alexander N\u00f6ske<\/p>\n<p>Studiengang: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Wirtschaftsinformatik<\/p>\n<p>Gutachter: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Prof. Dr. Claus\u00a0 Brell (HSN),\u00a0 Johannes Holz, M. A. (Fa. XCOM)<\/p>\n<p>&nbsp;<\/p>\n<p>Bachelor-Arbeit:<\/p>\n<p><strong>kesh f\u00fcr iOS &#8211; Entwicklung \/ Migration eines mobilen Bezahlsystems mit agilen Methoden<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Mit der Verf\u00fcgbarkeit von leistungsf\u00e4higen Smartphones verlagern sich zunehmend gesch\u00e4ftliche Aktivit\u00e4ten \u2013 dazu geh\u00f6ren Einkaufen, Bezahlen und allgemeine Geldtransaktionen \u2013 auf mobile Endger\u00e4te. Einige Funktionen, wie z.B. die elektronische Brieftasche, werden durch Smartphones erst praktikabel oder \u00fcberhaupt realisierbar; es gibt also im Zuge dieser Entwicklung Bestrebungen von Banken und Handelsunternehmen, neben Bargeld und EC\/Kreditkarte weitere einfache Bezahlm\u00f6glichkeiten zu schaffen.<\/strong><\/p>\n<p><strong>Herr N\u00f6ske hat mit seine Bachelorarbeit und seiner Umsetzung von kesh f\u00fcr das Iphone und das Ipad einen wesentlichen Beitrag dazu geliefert, dass die neuen Gesch\u00e4ftsfelder um mobile Bezahlsysteme auch in der Region und somit in Einzugsbereich der Hochschule Niederrhein erschlossen werden. kesh<\/strong><a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a><strong> wurde als Bezahlsystem des <\/strong>Unternehmens XCOM AG in Willich f\u00fcr die hauseigenen Bank f\u00fcr Investments und Wertpapiere (biw) entwickelt. \u00dcber das System k\u00f6nnen Nutzer Zahlungsaufforderungen erhalten, diese begleichen und selber Zahlungen initiieren und anfordern. Dies ist sowohl im Bereich von Business-to-Customer (B2C) als auch im Bereich von Customer-to-Customer (C2C) m\u00f6glich. Man kann damit \u2013 und das ist das Novum bei kesh \u2013 nicht nur in Gesch\u00e4ften bezahlen, sondern auch an andere Privatpersonen schnell Geldbetr\u00e4ge \u00fcbertragen.<\/p>\n<p>kesh hat erst k\u00fcrzlich den \u00dcbergang von Testlauf zum Markteintritt vollzogen und es ist damit zu rechnen, dass sich kesh als mobiles Bezahlsystem auch \u00fcberregional etablieren wird.<\/p>\n<p><strong>Im Rahmen der Entwicklung der kesh-Applikation hat Herr N\u00f6ske hinsichtlich der eingesetzten Methoden Neuland betreten und einen wichtigen Beitrag f\u00fcr die wissenschaftliche Herangehensweise f\u00fcr die Entwicklung mobiler Applikationen geleistet. Die Entwicklung mobiler Anwendungen (Apps) ist derzeit \u00a0noch gepr\u00e4gt durch oft methodenfreies Agieren einzelner Programmierer. Herr N\u00f6ske setzte in seiner Arbeit agile Entwicklungsmethoden (SCRUM) ein und evaluierte in diesem Rahmen das sog. Pair-Programming. Herr N\u00f6ske hat hierdurch nicht nur einen neuen Weg zu einer Professionalisierung der App-Entwicklung beschritten, sondern auch Erkenntnisse erzielt, die schon im kommenden Semester Eingang in die Lehre finden werden.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Wir bitten daher um eine Ber\u00fccksichtigung der Arbeit von Herrn N\u00f6ske beim Senatspreis 2013.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>(Prof. Dr. Claus Brell)<\/p>\n<p>&nbsp;<\/p>\n<p>&#8230;..<\/p>\n<p>Bisherige Senatspreise: 2<\/p>\n<p>Vorgeschlagen: gesamt 4<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/senatspreis-2021-digitalisierung-der-bienenhaltung-vorschlag\/\">Hier gehts zum Senatspreis 2021 Digitalisierung der Bienenhaltung<\/a><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/senatspreis-2020-vorschlag-digitalisierung-in-der-landwirtschaft\/\">Hier gehts zum Senatspreis (Vorschlag)<\/a><a href=\"https:\/\/cbrell.de\/blog\/senatspreis-2020-vorschlag-digitalisierung-in-der-landwirtschaft\/\"> 2020 Digitalisierung in der Landwirtschaft<\/a><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/senatspreis-2014-vorschlag-secloud-konzept-zur-verschlu%cc%88sselten-datensicherung-der-private-cloud-in-einer-public-cloud\/\">Hier gehts zum Senatspreis (Vorschlag) 2014\u00a0<\/a>Konzept zur Verschl\u00fcsselung in der private Cloud<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/\">Hier gehts zum Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems<\/a><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/presseberichte-ueber-claus-brell\/\">\u00dcbersicht der Pressemeldungen<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=7210\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Achtung, die Internetverweise in dieser historischen Unterlage sind mittlerweile nicht mehr erreichbar. Senatspreis 2013 Kandidat: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Alexander N\u00f6ske Studiengang: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Wirtschaftsinformatik Gutachter: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Prof. Dr. Claus\u00a0 Brell (HSN),\u00a0 Johannes Holz, &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2434","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems\" \/>\n<meta property=\"og:description\" content=\"Achtung, die Internetverweise in dieser historischen Unterlage sind mittlerweile nicht mehr erreichbar. Senatspreis 2013 Kandidat: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Alexander N\u00f6ske Studiengang: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Wirtschaftsinformatik Gutachter: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Prof. Dr. Claus\u00a0 Brell (HSN),\u00a0 Johannes Holz, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-08T20:37:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-08T20:54:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/zaehler\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Senatspreis 2013 kesh f\u00fcr iOS &#8211; Entwicklung eines mobilen Bezahlsystems mit agilen Methoden\",\"datePublished\":\"2022-02-08T20:37:17+00:00\",\"dateModified\":\"2022-02-08T20:54:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/\"},\"wordCount\":445,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/\",\"name\":\"Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"datePublished\":\"2022-02-08T20:37:17+00:00\",\"dateModified\":\"2022-02-08T20:54:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senatspreis 2013 kesh f\u00fcr iOS &#8211; Entwicklung eines mobilen Bezahlsystems mit agilen Methoden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/","og_locale":"de_DE","og_type":"article","og_title":"Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems","og_description":"Achtung, die Internetverweise in dieser historischen Unterlage sind mittlerweile nicht mehr erreichbar. Senatspreis 2013 Kandidat: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Alexander N\u00f6ske Studiengang: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Wirtschaftsinformatik Gutachter: \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Prof. Dr. Claus\u00a0 Brell (HSN),\u00a0 Johannes Holz, ...","og_url":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/","og_site_name":"Bienen und Technik","article_published_time":"2022-02-08T20:37:17+00:00","article_modified_time":"2022-02-08T20:54:00+00:00","og_image":[{"url":"https:\/\/cbrell.de\/zaehler","type":"","width":"","height":""}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Senatspreis 2013 kesh f\u00fcr iOS &#8211; Entwicklung eines mobilen Bezahlsystems mit agilen Methoden","datePublished":"2022-02-08T20:37:17+00:00","dateModified":"2022-02-08T20:54:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/"},"wordCount":445,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/","url":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/","name":"Senatspreis 2013 Entwicklung eines mobilen Bezahlsystems","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","datePublished":"2022-02-08T20:37:17+00:00","dateModified":"2022-02-08T20:54:00+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#primaryimage","url":"https:\/\/cbrell.de\/zaehler","contentUrl":"https:\/\/cbrell.de\/zaehler"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/senatspreis-2013-kesh-fuer-ios-entwicklung-eines-mobilen-bezahlsystems-mit-agilen-methoden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Senatspreis 2013 kesh f\u00fcr iOS &#8211; Entwicklung eines mobilen Bezahlsystems mit agilen Methoden"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=2434"}],"version-history":[{"count":2,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2434\/revisions"}],"predecessor-version":[{"id":2441,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2434\/revisions\/2441"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=2434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=2434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=2434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}