{"id":2417,"date":"2022-02-02T21:15:10","date_gmt":"2022-02-02T20:15:10","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=2417"},"modified":"2022-02-02T21:29:33","modified_gmt":"2022-02-02T20:29:33","slug":"pitch-video-fuer-programmierprojekte-bewertungskriterien","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/","title":{"rendered":"Pitch-Video f\u00fcr Programmierprojekte &#8211; Bewertungskriterien"},"content":{"rendered":"<p><em>Sie sollen f\u00fcr Ihr &#8222;Produkt&#8220; ein Pitch-Video erstellen? Hier sind ein paar Kriterien, wie Videos in den Modulen <a href=\"https:\/\/cbrell.de\/blog\/game-design-und-programmierung\/\">Game Design und Programmierung<\/a> sowie <a href=\"https:\/\/cbrell.de\/blog\/modul_webanwendungen\/\">Webanwendungen<\/a> an der Hochschule Niederrhein bewertet werden. Auch erhalten Sie ein paar Tipps f\u00fcr den Start.<\/em><\/p>\n<p>Stand: 02.02.2022<\/p>\n<h2><strong>Tipps f\u00fcr die Erstellung (Inhalt und Anmutung)<\/strong><\/h2>\n<ul>\n<li>Die Zuschauerin \/ der Zuschauer sollen sich beim Zuschauen wohlf\u00fchlen.\u00a0 Tun Sie alles, damit das passieren kann, vermeiden Sie alles, was das verhindern k\u00f6nnte.<\/li>\n<li>Achten Sie auf eine gute Tonqualit\u00e4t. Verzerrte Sprache, deutliche Kompressionseffekte in der Sprache (tauchen manchmal bei Bluetooth-Headsets auf), starkes rauschen oder Summen mindern die Freude bei der Betrachtung eines Videos.<\/li>\n<li>Langweilen Sie Ihre Zuschauer nicht, stellen Sie aber auch kein Bein. Eine L\u00e4nge zwischen einer Minute und vier Minuten hat sich in der vergangenheit bew\u00e4hrt.<\/li>\n<li>Menschen sehen gerne Menschen, Gesichter und \/ oder H\u00e4nde in Teilsequenzen tun fast allen Videos gut.<\/li>\n<\/ul>\n<h2><strong>Tipps f\u00fcr die Erstellung (Technik)<\/strong><\/h2>\n<ul>\n<li>Top Videoqualit\u00e4t ist nur f\u00fcr Naturdokumentationen erforderlich. F\u00fcr alles andere gen\u00fcgt i.d.R. ein Smartphone. Eine Videoqualit\u00e4t von 720p gen\u00fcgt ebenfalls.<\/li>\n<li>Einfache Schnittprogramme sind ausreichend. Auf Windows Movie Maker, auf Mac iMovie &#8211; die Programme geh\u00f6ren zum Betriebssystem dazu.<\/li>\n<li>Auch mit Viedokonferenzl\u00f6sungen wie zoom lassen sich brauchbare Videos erstellen.<\/li>\n<\/ul>\n<h2>Aktuelle Bewertungskriterien<\/h2>\n<p>Als m\u00f6gliche Gesamtpunktzahl f\u00fcr das Video setze ich einen Wert fest zwischen 5 und 20 Punkten (da Video ist meist nur eine Komponente einer Gesamt-Pr\u00fcfungsleistung im Umfang von 120 Punkten). Zun\u00e4chst gehe ich von einem &#8222;perfekten&#8220; Video aus, also H\u00f6chstpunktzahl. Davon k\u00f6nnen nach folgenden Kriterien Punkte abgezogen werden. Die Kriterien:<\/p>\n<ul>\n<li>Das Video hat eine dem Inhalt angemessene L\u00e4nge. Nicht zu knapp (so dass nichts erkl\u00e4rt werden kann)\u00a0 noch zu langatmig. (3 Punkte)<\/li>\n<li>St\u00f6rende Element sind vermieden (laute oder unpassende Musik, oder \u00fcberhaupt Musik, vordergr\u00fcndige Schmuckelemente, die vom Inhalt ablenken &#8230;)(3 Punkte)<\/li>\n<li>youtube geeignet, insbesondere ohne ver\u00f6ffentlichungssch\u00e4dliche Elemente wie unfreie Bilder, ungefragte Fremd-Logos, peinliche Inhalte&#8230; (3 Punkte)<\/li>\n<li>M\u00fche und Engagement ist deutlich erkennbar (Schnitt, Choreografie &#8230;) (5 Punkte)<\/li>\n<li>Menschen, insbesondere Gesichter und \/ oder H\u00e4nde sind in Teilsequenzen zu sehen. (3 Punkte)<\/li>\n<li>Es gibt eine zus\u00e4tzliche pfiffige Idee, die das Pitch-Video aus der Menge heraushebt.<\/li>\n<\/ul>\n<h3>Beispiele<\/h3>\n<p>Auf youtube gibt es bereits viele Videos von meinen Studierenden. Hier sind ein paar Beispiele:<\/p>\n<p><a href=\"https:\/\/youtu.be\/ohxd_i5gLzg\">Raspberry Pico als Feuchtemesser &#8211; Robin Klebs hat dazu eine Online-Anleitung f\u00fcr einen Lehrerworkshop geschrieben<\/a> und bewirbt sie mit diesem Video. Es sind H\u00e4nde zu sehen und Sie sp\u00fcren: dahinter steckt ein Mensch.<\/p>\n<p><a href=\"https:\/\/youtu.be\/F8Iiyc5Iing\">Drei Studentinnen habe ein Outdoor-Suchspiel programmiert und bewerben das in Ihrem Pitch-Video.<\/a> Insbesondere in der Eingangssequenz machen die drei die Motivation hinter iherr Entwicklung deutlich.<\/p>\n<p><a href=\"https:\/\/youtu.be\/GeUwnR-KsZE\">Ein Reaktionsspiel haben zwei Studentinnen programmiert und stellen es in einer fiktiven Unterrichtssituation dar.<\/a> Es ist darauf zu achten, dass bei sehr jungen Protagonisten eine Einverst\u00e4ndniserkl\u00e4rung der Erziehungsberechtigten vorliegt.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=2329\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sie sollen f\u00fcr Ihr &#8222;Produkt&#8220; ein Pitch-Video erstellen? Hier sind ein paar Kriterien, wie Videos in den Modulen Game Design und Programmierung sowie Webanwendungen an der Hochschule Niederrhein bewertet werden. &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,306,200],"tags":[574,102,69,108],"class_list":["post-2417","post","type-post","status-publish","format-standard","hentry","category-gamification","category-lehre","category-motivation","tag-pitch","tag-projekt","tag-studium","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien<\/title>\n<meta name=\"description\" content=\"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien\" \/>\n<meta property=\"og:description\" content=\"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T20:15:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-02T20:29:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/zaehler\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Pitch-Video f\u00fcr Programmierprojekte &#8211; Bewertungskriterien\",\"datePublished\":\"2022-02-02T20:15:10+00:00\",\"dateModified\":\"2022-02-02T20:29:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/\"},\"wordCount\":478,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"keywords\":[\"Pitch\",\"Projekt\",\"Studium\",\"Video\"],\"articleSection\":[\"Gamification\",\"Lehre\",\"Motivation\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/\",\"name\":\"Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"datePublished\":\"2022-02-02T20:15:10+00:00\",\"dateModified\":\"2022-02-02T20:29:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/pitch-video-fuer-programmierprojekte-bewertungskriterien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pitch-Video f\u00fcr Programmierprojekte &#8211; Bewertungskriterien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien","description":"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/","og_locale":"de_DE","og_type":"article","og_title":"Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien","og_description":"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.","og_url":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/","og_site_name":"Bienen und Technik","article_published_time":"2022-02-02T20:15:10+00:00","article_modified_time":"2022-02-02T20:29:33+00:00","og_image":[{"url":"https:\/\/cbrell.de\/zaehler","type":"","width":"","height":""}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Pitch-Video f\u00fcr Programmierprojekte &#8211; Bewertungskriterien","datePublished":"2022-02-02T20:15:10+00:00","dateModified":"2022-02-02T20:29:33+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/"},"wordCount":478,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","keywords":["Pitch","Projekt","Studium","Video"],"articleSection":["Gamification","Lehre","Motivation"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/","url":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/","name":"Pitch-Video f\u00fcr Programmierprojekte - Bewertungskriterien","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","datePublished":"2022-02-02T20:15:10+00:00","dateModified":"2022-02-02T20:29:33+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Pitch-Video erstellen und keinen Plan? Hier bekommen Sie ein paar Tipps, das sollte zumindest in meinen Lehrveranstaltungen helfen. Viel Spa\u00df.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#primaryimage","url":"https:\/\/cbrell.de\/zaehler","contentUrl":"https:\/\/cbrell.de\/zaehler"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/pitch-video-fuer-programmierprojekte-bewertungskriterien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Pitch-Video f\u00fcr Programmierprojekte &#8211; Bewertungskriterien"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=2417"}],"version-history":[{"count":3,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2417\/revisions"}],"predecessor-version":[{"id":2420,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2417\/revisions\/2420"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=2417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=2417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=2417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}