{"id":2209,"date":"2021-09-25T22:41:02","date_gmt":"2021-09-25T20:41:02","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=2209"},"modified":"2022-10-18T17:58:37","modified_gmt":"2022-10-18T15:58:37","slug":"projektliste-game-design-und-programmierung","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/","title":{"rendered":"Projektliste Game Design und Programmierung"},"content":{"rendered":"<p><em>Hier ist die Projektliste Game Design und Programmierung. Die Liste aktualisiere ich jedes Semester. In Zweierteams suchen Sie sich in Absprache mit mir ein Projekt aus &#8230;<\/em><\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/game-design-und-programmierung\/\">Zur Beschreibung des Moduls.<\/a><\/p>\n<p>Stand 18.10.2022<\/p>\n<p>Achtung, aus Kapazit\u00e4tsgr\u00fcnden k\u00f6nnen KEINE Projekte angeboten werden mit UNITY, ANGULAR, REACT. Javascript-Projekte sind nativ &#8211; ohne Fremdbibliotheken &#8211; zu gestalten. (Ggf begr\u00fcndete Ausnahme: jQuery, Bootstrap)<\/p>\n<h2>Programmier-Projekte, die Sie im laufenden Semester bearbeiten k\u00f6nnen (Achtung, Liste kann sich im Oktober noch \u00e4ndern)<\/h2>\n<h3>neu: PW22W19: Spielzeug f\u00fcr Gartenbesitzer &#8211; die IR-WLAN-\u00dcberwachung<\/h3>\n<p>Mit einem Microcontroller und einem PIR (IR-Bewegungsschalter, wie er in Gartenlampen verbaut ist)\u00a0 soll ein System aufgebaut werden, das Bewegungsaktivit\u00e4ten \u00fcber WLAN im Internet loggt. So kann ein Gartenbesitzer pr\u00fcfen, ob etwas (Rehe, Katzen, Einbrecher) nachts im Garten herumgelaufen sind. Als Microcontroller k\u00f6nnen wahlweise eigesetzt werden: ESP8286 oder ESP32 (Programmierung mit Arduino IDE) oder Raspberry Pico W (Programmierung mit Python und Thonny IDE oder C und Arduino IDE). Ein einfacher Webservice und eine Anzeigeseite (in PHP) runden das Projekt ab.<br \/>\n<a href=\"https:\/\/www.youtube.com\/watch?v=wCpDMFV9Uno&amp;t=3s\" target=\"_blank\" rel=\"noopener\">Ein vergleichbares Projekt (mit zus\u00e4tzlicher Bildaufnahme) wurde bereits mit dem Raspberry Pi realisiert &#8211; Pitchvideo auf youtube.<\/a><\/p>\n<h3>neu: PW22W120: Spielzeug f\u00fcr Helikopter-Eltern- die WLAN-Kinderzimmer-Licht-An-\u00dcberwachung<\/h3>\n<p>Mit einem Microcontroller und einem LDR (Lichtempfindlichen Widerstand)\u00a0 soll ein System aufgebaut werden, das \u00c4nderungen der\u00a0 Lichtst\u00e4rke an einen Webservice \u00fcbertr\u00e4gt. Einsatzm\u00f6glichkeiten w\u00e4re die \u00dcberwachung im Kinderzimmer (schlafen die lieben Kleinen?) oder Absch\u00e4tzung der Beleuchtungsst\u00e4rken auf dem Garagendach im Vorfeld der Planung einer Solar-PV-Anlage. Die g\u00e4ngigen Microconroller haben einen Analog-Digital-Wandler an Bord.<br \/>\nDamit wird es ganz einfach, die Hardware (Controller, LDR und eine Widerstand) auf einem Steckbrett aufzubauen. Als Microcontroller k\u00f6nnen wahlweise eigesetzt werden: ESP8286 oder ESP32 (Programmierung mit Arduino IDE) oder Raspberry Pico W (Programmierung mit Python und Thonny IDE oder C und Arduino IDE). Ein einfacher Webservice und eine Anzeigeseite (in PHP) runden das Projekt ab.<\/p>\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=_Gu618SM7AA\" target=\"_blank\" rel=\"noopener\">Wie so etwas (Spannungsmessung) grunds\u00e4tzlich funktioniert (hier mit dem Calliope Mini als Microconroler) ist in einem youtube Video zu sehen.<\/a><\/p>\n<h3>P22W1: Wordle-Klon<\/h3>\n<p>Sie erstellen einen Wordle Klon als Browsergame.<\/p>\n<p>Programmierumgebung: Javascript, Statistiken mit PHP und CSV oder SQLite, Kommunikation AJAX<br \/>\nEin existierendes Beispiel: <a href=\"https:\/\/wordlegame.org\/de\">https:\/\/wordlegame.org\/de<\/a><\/p>\n<h3>P22W2: Varroa Simulator<\/h3>\n<p>Voraussetzung: etwas Grundkenntnisse in der Bienenhaltung<\/p>\n<p>Spielziel: Herausfinden, wie Spieler:innen mit mit m\u00f6glichst wenig Interventionen eine stabilen Zustand eine Bienenvolkes hinbekommen. Zur Vereinfachung: Behandlungszeitpunkt angeben, Prozentsatz der Varroareduktion.<\/p>\n<p>Wichtig: grafische R\u00fcckmeldung \u00fcber den &#8222;Systemzustand&#8220;, so z. B. Volksst\u00e4rke und St\u00e4rke des Varroabefalls.<\/p>\n<p>(Weitere Informationen gibts, wenn sich ein Team daf\u00fcr interessiert)<\/p>\n<h3>P22W3: Bienenstock Simulator<\/h3>\n<p>Es soll eine einfacher Bienenstock-Simulator entwickelt werden. Zum Spielstart werden ein paar Parameter (Legeleistung der K\u00f6nigin, Ergiebigeit der Nahrungsquellen, Wahrscheinlichkeit f\u00fcr Flugtage) eingegeben, die Simulation l\u00e4uft dann selbstt\u00e4tig.<\/p>\n<p>Hier hat sich schon jemand ein paar Gedanken gemacht: <a href=\"https:\/\/imsc.uni-graz.at\/keeling\/modI_ss09\/projekten\/KnielyRosenbergerEnd.pdf\">https:\/\/imsc.uni-graz.at\/keeling\/modI_ss09\/projekten\/KnielyRosenbergerEnd.pdf<\/a><\/p>\n<p>(Weitere Informationen gibts, wenn sich ein Team daf\u00fcr interessiert)<\/p>\n<h3>P22W4: Spielzeug f\u00fcr Imker IV: beeWild Bienenwebcam ESP32<\/h3>\n<p>Mit dem Raspberry wurde bereits ein Webcamsystem aufgesetzt (https:\/\/cbrell.de\/naturwatchcam). Zur Beobachtung am Bienenstock soll ein einfaches System mit der ESP32-Cam erstellt werden, das \u00fcber WLAN alle 5 Minuten ein Bild an einen Webservice \u00fcbertr\u00e4gt.<\/p>\n<p>Programmierung: Webservice und Bildanzeigescript in PHP, ESP-Programm vermutlich in C (Arduino-IDE)<\/p>\n<h3>P21W1: Konzeption und Vorbereitung eines Lehrerworkshops mit dem Raspberry Pico (WH)<\/h3>\n<p>Lehrerworkshops in kurzen Formaten (2*1,5 Stunden) haben sich bew\u00e4hrt, um die Kooperationen des Fachbereichs mit Schulen zu st\u00e4rken (siehe Pressemeldung). Ein Erfolg war der <a href=\"https:\/\/cbrell.de\/blog\/calliope-mini-lehrerworkshop\/\">Calliope-Mini-Workshop<\/a> mit einem analogen Bodenfeuchtesensor (<a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/04\/Calliope_Mini_Workshop_Anleitung-210614.pdf\">Anleitung f\u00fcr die Lehrer<\/a>). Mit dem <a href=\"https:\/\/www.raspberrypi.org\/products\/raspberry-pi-pico\/\">Raspberry Pico<\/a> erobert ein neues Spielzeug die Maker-Szene, und es entwickelt sich ein gro\u00dfes \u00d6kosystem. Analog zum Calliope Workshop soll ein Workshop mit dem Raspberry Pico konzipiert werden, Da der Pico keine Anzeige wie der Calliope hat, soll eine LED Ampel alternativ genutzt werden. Der Workshop bzw. die Vorbereitung soll folgende Eigenschaften haben:<\/p>\n<ul>\n<li>Geringe Anforderungen an die Voraussetzungen bei der Durchf\u00fchrung (so wenig Zusatzsoftware wie m\u00f6glich&#8230;)<\/li>\n<li>Geringe Anforderungen an die manuellen Fertigkeiten<\/li>\n<li>Schrittweises Vorgehen &#8211; schnelle Erfolgserlebnisse<\/li>\n<\/ul>\n<p>(Wenn verf\u00fcgbar, wird der neue Pico mit WLAN und Bluetooth eingesetzt)<\/p>\n<p>Programmierung: wenn Python, dann mit Thonny-IDE, wenn C\/C++, dann Arduino IDE<\/p>\n<h3><strong>P21W2: <\/strong>Konzeption und Vorbereitung eines Lehrerworkshops mit dem Arduino<\/h3>\n<p>Wie P21W1, allerdings mit dem Arduino Nano.<\/p>\n<p>ACHTUNG: WENN DIE BESCHAFFUNG 11.2022 IMMER NOCH SCHWIERIG IST, DANN DIESES PROJEKT NICHT.<\/p>\n<h3>P21W3: Spielzeuge f\u00fcr Imker I: Front-End \/ User Experience f\u00fcr unterschiedliche existierende Daten<\/h3>\n<p>Seit dreieinhalb Jahren werden von Sensoren aus Bienenst\u00f6cken Daten gesammelt, z.B. hier:<br \/>\n<a href=\"https:\/\/cbrell.de\/biene40\/\">https:\/\/cbrell.de\/biene40\/<\/a><\/p>\n<p>Mittlerweile hat sich daraus ein vom BMEL gef\u00f6rdertes Forschungsprojekt ergeben. Informationen dazu gibt es auf der Projektseite <a href=\"http:\/\/bieneviernull.de\">http:\/\/bieneviernull.de<\/a><\/p>\n<p>Auf dem Smartphone sieht das zur Zeit (Oktober 2022) so aus: <a href=\"http:\/\/bieneviernull.de\/dashboard\">Biene40 Dashboard<\/a>.<\/p>\n<p>Wie k\u00f6nnte das &#8222;sch\u00f6ner&#8220; aussehen, vielleicht auch &#8222;verspielter&#8220; (z.B. im <a href=\"https:\/\/praxistipps.focus.de\/steampunk-bedeutung-und-merkmale_111067\">Steampunk-<\/a>Design), ohne den informativen Charakter zu verlieren? Wie w\u00e4re es mit einem Steampunk-Dashboard &#8230; F\u00fcr bestehende Datenpools sind ETL-Prozesse in PHP zu programmieren, der Front-End vorzugsweise in Javascript \/ AJAX), Die Daten und eine Schnittstelle dazu werden zur verf\u00fcgung gestellt.<br \/>\nGeeignet f\u00fcr Menschen, die sich mit <a href=\"https:\/\/www.gruenderszene.de\/lexikon\/begriffe\/user-experience\" target=\"_blank\" rel=\"noopener noreferrer\">User Experience<\/a>\u00a0 auseinandersetzen wollen.<\/p>\n<h3>P21W4: Spielzeuge f\u00fcr Imker II: Arduino Stocktemperatur<\/h3>\n<p>Gerade Neuimker schauen gern zu oft in den Bienenstock. Jedes \u00d6ffnen schaden den Bienen. Mit drei vertikal angebrachten Temperatursensoren erf\u00e4hrt man &#8211; ohne Bienenstock \u00f6ffnen &#8211; ob das Volk noch lebt, ob es br\u00fctet oder ob das Futter knapp wird. (Brell, Claus (2020)\u00a0<i>Genug Futter im Stock? &#8211; Temperaturmessung zeigt`s an.<\/i> In: bienen&amp;natur 03.2020, M\u00fcnchen. S. 36-37.<a href=\"http:\/\/claus-brell.de\/materialien\/Brell,Claus(2020)Genug-Futter-im-Stock-bienen-und-natur.pdf\"> Artikel Volltext <\/a>). Mit Hilfe einen <a href=\"https:\/\/www.arduino.cc\/en\/pmwiki.php?n=Main\/ArduinoBoardNano\">Arduino nano<\/a>, eines 4-Zeilen-Displays (I2C) und vierTemperatursensoren DS18B20 (1-Wire) soll ein System aufgebaut werden, das dem Imker au\u00dfen am Stock anzeigt, was sich drinnen abspielt.<br \/>\nGeeignet f\u00fcr Menschen, die sich mit Microcontrollern, speziell dem Arduino,\u00a0 auseinandersetzen wollen. Programmierung in C mit der Arduino IDE.<\/p>\n<h3>P21W5: Spielzeuge f\u00fcr Imker III: Raspberry Pico Stocktemperatur<\/h3>\n<p>Inhaltlich wie P21W5, aber mit dem <a href=\"https:\/\/www.raspberrypi.org\/products\/raspberry-pi-pico\/\">Raspberry Pico<\/a>. Mit Hilfe eines Raspberry Pico, eines 4-Zeilen-Displays (I2C) und drei Temperatursensoren DS18B20 (1-Wire) soll ein System aufgebaut werden, das dem Imker au\u00dfen am Stock anzeigt, was sich drinnen abspielt.<br \/>\nGeeignet f\u00fcr Menschen, die sich mit Microcontrollern, speziell dem Raspberry Pico\u00a0 auseinandersetzen wollen.<\/p>\n<h3>P21W6: Feedbacksystem f\u00fcr soziale Roboter<\/h3>\n<p>Analog zum Anki Cozmo sollen &#8222;emotionale Zust\u00e4nde&#8220; \u00fcber Augen visualisiert werden. Dazu ist ein Anzeigemedium (128 x 64 Pixel, entweder als Ajax-Anwendung mit Javascript und PHP (bevorzugt) oder Mini-Display mit Raspberry oder ESP32 oder bei Verf\u00fcgbarkeit mit Raspberry Pico W zu programmieren, das einen emotionalen Zustand von einem Webservice holt und visualisiert.<br \/>\nDie passenden Webservices und eine Eingabem\u00f6glichkeit f\u00fcr die emotionalen Zust\u00e4nde sind zu erstellen.<\/p>\n<p>Geeignet f\u00fcr Menschen, die sich mit <a href=\"https:\/\/www.it-daily.net\/analysen\/22727-social-robots-blindes-vertrauen-und-sicherheitsrisiken\">social robots<\/a> und <a href=\"https:\/\/www.uni-bamberg.de\/hci\/\">human computer interaction (hci)<\/a> auseinandersetzen wollen<\/p>\n<p>Quellen: Youtube Videos zum Anki Cozmo, <a href=\"https:\/\/cbrell.de\/augen\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/cbrell.de\/augen<\/a>, <a href=\"https:\/\/spectrum.ieee.org\/automaton\/robotics\/humanoids\/what-people-see-in-157-robot-faces\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/spectrum.ieee.org\/automaton\/robotics\/humanoids\/what-people-see-in-157-robot-faces<\/a>.<\/p>\n<h3>P21W7: Social Feedback mit Neopixel<\/h3>\n<p>Mit Hilfe eines Raspberry Pi und einer farbigen LED-Anzeige (WS2801 oder WS2012\/NeoPixel)\u00a0 soll ein Anzeigeger\u00e4t entwickelt werden, das von zwei Personen die Gem\u00fctzust\u00e4nde anzeigt (&#8222;Mir geht es heute &#8230;.&#8220;) Gef\u00fcttert wird das System \u00fcber eine einfache Webseite. Bwen\u00f6tigtv wird auch ein Webservice in PHP. Die Daten l\u00e4dt sich der Raspberry jede Minute.<\/p>\n<h3>P12W8: PiNK reloaded: Datenvisualisierung mit eInk-Display<\/h3>\n<p>Manchmal m\u00f6chten Menschen eine einfache Anzeigestation statt Webseiten. Mit Hilfe eines Raspberrys (Python), (Alternative: ESP-01) eines kleinen eInk-Displays und ein paar PHP-Webservices soll ein System aufgebaut werden, dass Daten aus eines Sensordatenbank erh\u00e4lt, daraus eine Grafik erzeugt und diese auf dem Display anzeigt. Hier ist das Pitch-Video des <a href=\"https:\/\/www.youtube.com\/watch?v=QPZkYx7tsXI\">Vorl\u00e4uferprojektes leider mit Musik<\/a>.<\/p>\n<h3>P21W9: Checkliste Craftbier brauen Schritt f\u00fcr Schritt<\/h3>\n<p>Spielerische online Unterst\u00fctzung f\u00fcr Hobby-Bierbrauer . Anhand der einfachen Literatur \u00fcber das Bierbrauen und der Brauprotokolle soll eine Art internetbasierte Checkliste f\u00fcr das Bierbrauen entwickelt werden. Der &#8222;Spieler&#8220; wird dadurch in kleinen Schritten durch den Brauprozess gef\u00fchrt und kann abhaken, wann er bestimmte Schritte erledigt hat. Das kann auch spielerisch auf eine Canvas erfolgen. Zu jedem Brauprozessschritt gibt es eine kleine Anleitung, was zu tun ist. Technik: AJAX.<\/p>\n<h3>P21W10: Craftbier Escape Room- Flucht vor der M\u00f6rderhefe<\/h3>\n<p>In Anlehnung an reale Escape-Rooms oder der EXIT-Spiele (Verlag KOSMOS) soll eine (einfache) Web-Version eines solchen Spiels erstellt werden. Die Spieler l\u00f6sen die Aufgaben\/Puzzle und entkommen der b\u00f6sartigen Bierhefe &#8230; oder sonst irgend etwas,\u00a0 Technik: AJAX.<\/p>\n<h3>P21W12: QR-Code Rallye<\/h3>\n<p>F\u00fcr den Campus M\u00f6nchengladbach soll eine einfache QR-Code-Rallye entwickelt werden. Spielziel ist, nacheinander die aufgeh\u00e4ngten QR-Codes zu finden und so gleich den Campus kennen zu lernen. Daf\u00fcr scannt eine Browseranwendung den QR-Code, und holt die Beschreibung zum Finden des n\u00e4chsten Codes vom Webservice.<br \/>\nWer es sich zutraut, kann alternativ mit GeoFences arbeiten.<\/p>\n<p>Trennen Sie Inhalt vom Programm &#8211; denken Sie den Fall mit, dass man das Gleiche vielleicht auch in Krefeld &#8211; mit ge\u00e4nderten Texten &#8211; einsetzen m\u00f6chte.<br \/>\nPitch-Video eines Vorl\u00e4uferprojektes:<\/p>\n<p><em>Der Quartiersver\u00f6dung entgegenwirken. Jonas Heimann und Merlin Stottmeister haben in einem studentischen Projekt ein spielerisches System entwickelt, das Besuche von Ladenlokalen attraktiver machen kann.<\/em> <a href=\"https:\/\/youtu.be\/nMVg484O5Lo\">Pitchvideo auf youtube<\/a><\/p>\n<p><a href=\"https:\/\/youtu.be\/SGKkloHZOsI\">Pitch-Video meines Beitrages zum NUK Businessplan-Wettbewerb auf youtube<\/a><\/p>\n<h3>P21W13: Das virtuelle Flummiglas (Gamification)<\/h3>\n<p>Entwicklung einer <b>Gamificationplattform f\u00fcr analoge Realwelten<\/b>\u00a0(Ajax bevorzugt). Erl\u00e4uterung hierzu siehe\u00a0<a href=\"https:\/\/www.informatik-aktuell.de\/management-und-recht\/projektmanagement\/wie-gamification-den-methodenapparat-der-wirtschaftsinformatik-bereichert.html\">Abschnitt &#8222;Gedankenspiel zur Implementierung von Gamification&#8220; im Artikel auf Informatik-aktuell. [Link]<\/a><\/p>\n<h3>P21W15: Interaktives Lernbild &#8222;Imker Grundwissen&#8220;<\/h3>\n<p>Ein Bild zum Klicken mit Hintergrundinformationen, die beim Klicken angezeigt werden. Zum Abschluss kann ein Test absolviert werden (ca 10 MC-Fragen) Die Anzahl der richtigen Antworten und die falschen Antworten werden angegeben.<\/p>\n<h3>P21W17: Spielzeug f\u00fcr Bergwanderer<\/h3>\n<p>GPS-Track hochladen und auswerten. Mit Visualisierung des Tracks.<br \/>\nVarianten:<br \/>\na) mit Leaflet<br \/>\nb) Javascript ohne Library<br \/>\nc) auf dem Server OpenStreetMap und PHP<\/p>\n<p>3 GPS-Routen zum Hochladen werden zur Verf\u00fcgung gestellt.<\/p>\n<h3>P21W18: Reaktionstest &#8211; ein Party-und Trinkspiel<\/h3>\n<p>Sie bauen mit HTML, CSS, und Javascript ein Reaktionstest-Spiel auf.<\/p>\n<p>Eine Spielsequenz: im Browserfenster erscheint eine Blase, auf die man klicken muss. Trifft man die Blase, gibts einen Trefferpunkt, trifft man nicht, gibts einen Fehlpunkt. Die Blase ist nur 2 Sekunden sichtbar. Dann erscheint die Blase an einer anderen Stelle, ist aber nur 1,8 Sekunden sichtbar. Und so weiter bin 0,2 Sekunden, dann werden die Intervalle wieder gr\u00f6\u00dfer bis 2 Sekunden.<\/p>\n<p>Fragestellungen: Wie oft hat man getroffen und wie oft nicht? Wird die Trefferquote bei Alkoholkonsum schlechter? H\u00e4ngt die Trefferquote von der Sprungweite der Blase ab? L\u00e4sst sich das Ganze trainieren? Was w\u00fcrde passieren, wenn zus\u00e4tzlich Blasen eine anderen, nicht zu klickenden Farbe erscheinen?<\/p>\n<p>Um die Fragen zu beantworten, m\u00fcssen die Daten gespeichert werden. Idealerweise auf dem Webserver, auf dem es dann ein einfaches Auswerteprogramm gibt. Serverprogrammierung in PHP.<\/p>\n<h3>Spiel-Ideen<\/h3>\n<p><span style=\"color: #000000;\"><strong>&#8222;Dungeon Cubes&#8220;<\/strong><\/span><\/p>\n<p>Neu 08.10.2022: eine <a href=\"https:\/\/cbrell.de\/blog\/dungeon-cubes-idee-fuer-ein-einfaches-spiel\/\">Spielidee &#8222;Dungeon Cubes&#8220;,<\/a> die im Modul ausgearbeitet oder teilweise als Brosergame umgesetzt werden k\u00f6nnte. Sie ist in einem separatem Beitrag beschrieben<\/p>\n<h4>&#8222;eat them all&#8220;<\/h4>\n<p>Ein einfaches Browserspiel f\u00fcr zwei Personen. Jeder Spieler hat einen farbigen Kreis, mit dem er versucht, schneller als der Mitspieler kleine Quadrate zu &#8222;essen&#8220; (zu \u00fcberfahren &#8230;). Die Kreise k\u00f6nnen wahlweise mit den Pfeiltasten auf der Tastatur oder mit der Maus gesteuert werden. Je Spiele werden die gegessenen Quadrate gez\u00e4hlt. Beim Spielstart werden Quadrate automatisch auf dem Spielfeld verteilt. Wichtig f\u00fcr einen Spieler: was macht der Mitspieler, wird er schneller bei den ausgew\u00e4hlten Quadraten sein?<\/p>\n<p>Interessant w\u00e4re eine &#8222;Gameboy-like&#8220; reduzierte Variante mit einem Textfeld. Auf einem Textfeld von 16 * 16 Buchstaben gibt es zwei Spieler A und B, die Quadrate sind einfach nur ein x. Ob die Programmierung einfacher ist, ist noch unklar.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Kreise.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1413 size-medium\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Kreise-300x199.jpg\" alt=\"\" width=\"300\" height=\"199\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Kreise-300x199.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Kreise-768x511.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Kreise.jpg 910w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Abb. 1: Variante mit Kreisen und Quadraten (Mockup)<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Buchstaben.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1414\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Buchstaben-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Buchstaben-300x225.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Buchstaben-768x576.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/eatthemall-Buchstaben.jpg 1008w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Abb. 2: Variante mit einem Buchstabenfeld (Mockup)<\/p>\n<h4>&#8222;bubble run&#8220;<\/h4>\n<p>Vorschlag: F\u00fcr einfache Jump&amp;Run Spiele muss es keine aufwendige Grafik sein. Der Protagonist kann auch eine einfacher Kreis (div mit CSS) sein, die Hindernisse einfache Rechtecke (div mit Farbf\u00fcllung). Im einfachsten Fall kann die Blase nur springen (Space-Taste), mit mehrfach Dr\u00fccken kommt die Blase h\u00f6her. Wird nicht gedr\u00fcckt, sinkt die Blase wieder bis auf eine Grundline. Die Blase befindet sich horizontal in der Mitte oder in der linke H\u00e4lfte des Bildschirms, die &#8222;Landschaft&#8220;, z. B. zuf\u00e4llig verteilte Rechtecke, zieht von rechts nach links vorbei.<\/p>\n<h2>Aktuelle Seminararbeiten, die alternativ zu den Projekten bearbeitet werden k\u00f6nnen<\/h2>\n<p>Alternativ k\u00f6nnen zu den Projekten (volle Punktzahl) auch Seminararbeiten (reduzierte Punktzahl, als beste Note h\u00f6chstens 2,0 erreichbar) geschrieben werden. Auch die Seminararbeiten sind f\u00fcr zwei-Personen-Teams vorgesehen. Die meisten Fragen, die gestellt werden, erfordern eine ordentliche Recherche. Bei jeder Behauptung in den Ausarbeitungen werde ich fragen: woher wissen Sie das?<\/p>\n<h3>S21W1: Konzept: EXIT-Spiele webbasiert umsetzen<\/h3>\n<p>Sie brauchen noch Mitstreiter -. und spielen zun\u00e4chst ein EXIT-Spiel durch. Analyse: Halten Sie alle R\u00e4tsel\/Spielideen fest und dokumentieren Sie diese. Bewertung: \u00dcberlegen Sie, welche man davon \u00fcberhaupt in ein Browsergame umsetzen k\u00f6nnte. Konzerption: \u00dcberlegen Sie sich f\u00fcr Ihre Auswahl Mockups und ein Datenmodell. Stellen Sie sich dabei vor, Sie m\u00fcssten es auch programmieren. Vorteilhaft w\u00e4re, wenn Sie die Mockups als Klick-Dummy umsetzen (HTML). haben Sie dabei einen Investor vor Augen, der Ihnen im Anschluss Geld f\u00fcr die Realisierung \/ Programmierung geben soll.<br \/>\nListe der &#8222;zugelassenen&#8220; EXIT-Spiele:<br \/>\n1. Die Station im ewigen Eis<br \/>\n2.<br \/>\n3.<br \/>\n4.<br \/>\n5.<\/p>\n<h3>S21W2: Methodische Literaturrecherche zum aktuellen Stand der Forschung zu Gamification<\/h3>\n<p>Stand der Forschung und praktische Anwendungen &#8211; eine Recherche zun\u00e4chst nach Quellen j\u00fcnger als 2 Jahre. Es ist f\u00fcr die <a href=\"https:\/\/cbrell.de\/blog\/literaturrecherche-planen-und-durchfuehren-mit-checkliste\/\">Literaturrecherche<\/a> eine geeignete <a href=\"https:\/\/cbrell.de\/blog\/methode-was-ist-das-und-warum-braucht-man-sie\/\">Methodik<\/a> auszusuchen und zu beschreiben.<\/p>\n<h3><span class=\"\">S21W3:<\/span><b><span class=\"\"> Steam. Wie funktioniert die Plattform f\u00fcr Spieleerfinder?<br \/>\n<\/span><\/b><\/h3>\n<p><span id=\"yui_3_17_2_1_1604324062081_33\" class=\"\">Wie &#8222;funktioniert&#8220; Steam? (Technische Grundlage, Gesch\u00e4ftsmodell &#8230;.)\u00a0 Wie geht man als Spielentwickler vor? Welche Verdienstm\u00f6glichkeiten gibt es? Ein kleiner Leitfaden f\u00fcr Neueinsteiger &#8230;<\/span><\/p>\n<h3>S21W4: WordPress mit Gamification anreichern<\/h3>\n<p>Welche Gamification-Plugins f\u00fcr WordPress gibt es? Ist das wirklich Gamification oder etwas anderes? F\u00fcr welche Anwendungsszenarien kann es \u00fcberhaupt sinnvoll sein, das einzusetzen? (Anmerkung: das Thema ist relativ offen)<\/p>\n<h3><span class=\"\">S21W5: S<\/span><span class=\"\">hopsysteme f\u00fcr Einsteiger<\/span><\/h3>\n<p><span class=\"\">Wer selber einen Internet-Shop aufbauen m\u00f6chte, wird auf viele H\u00fcrden sto\u00dfen. Legt man Motivationstheorien (Insbes. Flow-Konzept) zugrunde: welche Shopsysteme sind insbesondere f\u00fcr wenig IT-affine Gr\u00fcnder geeignet und warum? Bitte besziehen Sie WOO Commerce auf jeden fall in Ihre Recherchen mit ein.<\/span><\/p>\n<h3>S21W6: Fundgrube Brett- und Gesellschaftsspiele<\/h3>\n<p>Gibt es Game-Design-Elemente in Brettspielen, die immer wieder kehren?\u00a0 Wie kann man diese in Kategorien ordnen? Wie kann eine Bewertungsmatrix aussehen, welche Game-Design-Elemente f\u00fcr Online-Spiele adaptierbar sind? Wie kann eine Bewertungsmatrix aussehen, um die Game-Design-Elemente in Gamification-Szenarien einzusetzen?<\/p>\n<h3>S21W7: Wie &#8222;minimal&#8220; kann ein online-Spiel sein?<\/h3>\n<p>Ergebnis: Konzept (Anforderungsanalyse und Architektur) f\u00fcr ein &#8211; generisches-online Spiel, bei dem man nichts mehr weglassen kann. Begr\u00fcndung nach Jesse Shell. (Achtung, Seminararbeit f\u00fcr Kreative)<\/p>\n<h2>Im Wintersemester 2022 wird NICHT angeboten<\/h2>\n<h3>P21W11: Eignung von Javascript Frameworks f\u00fcr Jump&amp;Run<\/h3>\n<p>Mittlerweile gibt es eine Vielzahl von Javascript- Frameworks: Die vier Frameworks: Angularjs, Vue.js, React, Ember.js. Ebenso gibt es Spiele-Frameworks &#8211; manche verschwinden aber auch schnell wieder.<\/p>\n<p>Entweder mit einem einfachen 2D-Jump&amp;Run (selber ausdenken) oder einer einfach Spielidee (&#8222;eat them all&#8220;, siehe weiter unten unter &#8222;Spiel-Ideen&#8220;) soll untersucht werden, welche Javascript-Frameworks f\u00fcr einfache Browserspiele geeignet sein k\u00f6nnten. Dazu ist die Spielidee mit dem Framework und mit Javascript &#8222;nativ&#8220; zu entwickeln und die Erfahrungen bei der Entwicklung kritisch zu vergleichen.<\/p>\n<h3>P21W16: Interaktives Lernbild &#8222;Medienkompetenz f\u00fcr Sch\u00fcler&#8220;<\/h3>\n<p>Wie P21W11a.<\/p>\n<p>&nbsp;<\/p>\n<h3>P21W14: Geschenkemanagement &#8222;virtueller Weihnachtsmann&#8220;<\/h3>\n<p>Jeder kann seine Wunschliste auf einer Internetplattform einstellen und auch \u00e4ndern. Jeder kann alle Wunschlisten sehen. Jeder kann einen Kommentar zu einem ANDEREN Wunsch schreiben und dort diskutieren. Jeder sieht alles, aber nicht die Kommentare zu den eigenen w\u00fcnschen. Dadurch wird sich dann herauskristallisieren, wer sich um welches Geschenk k\u00fcmmert und es bleibt eine \u00dcberraschung. Kein kompliziertes Rechtemanagement. Nur selbstgew\u00e4hlten Benutzernahmen. Es geht nicht darum, ein vermarktbares Produkt zu bauen, sondern einen Prototypen, an dem man testen kann, wie sich das anf\u00fchlt. Realisierung in AJAX. Spiel-Design-Elemente: Community-Building, Instand Feedback.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1452\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann-1024x464.jpg\" alt=\"Mockup virtueller Weihnachtsmann\" width=\"1024\" height=\"464\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann.jpg 1024w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann-300x136.jpg 300w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann-768x348.jpg 768w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2020\/08\/201114-Mockup-virtueller-Weihnachtsmann-1536x696.jpg 1536w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>Abb. Mockup virtueller Weihnachtsmann. So kann es aussehen, muss es aber nicht.<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=2695\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hier ist die Projektliste Game Design und Programmierung. Die Liste aktualisiere ich jedes Semester. In Zweierteams suchen Sie sich in Absprache mit mir ein Projekt aus &#8230; Zur Beschreibung des &#8230;<\/p>\n","protected":false},"author":1,"featured_media":2384,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,306,253,77,259],"tags":[109,97,191,520,519,688,5,112,720,521,111,618,488,295,522,687],"class_list":["post-2209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gamification","category-lehre","category-programmieren","category-programmierung","category-spiel","tag-ajax","tag-biene","tag-bienenstock","tag-escape-room","tag-exit","tag-game","tag-gamification","tag-javascript","tag-microcontroller","tag-partyspiel","tag-php","tag-serious-game","tag-simulation","tag-sqlite","tag-trinkspiel","tag-wordle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projektliste Game Design und Programmierung<\/title>\n<meta name=\"description\" content=\"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projektliste Game Design und Programmierung\" \/>\n<meta property=\"og:description\" content=\"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-25T20:41:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-18T15:58:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"617\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Projektliste Game Design und Programmierung\",\"datePublished\":\"2021-09-25T20:41:02+00:00\",\"dateModified\":\"2022-10-18T15:58:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/\"},\"wordCount\":2694,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Fantasy-Spielfiguren.jpg\",\"keywords\":[\"AJAX\",\"Biene\",\"Bienenstock\",\"escape room\",\"exit\",\"Game\",\"gamification\",\"Javascript\",\"Microcontroller\",\"Partyspiel\",\"PHP\",\"Serious Game\",\"Simulation\",\"SQLite\",\"Trinkspiel\",\"Wordle\"],\"articleSection\":[\"Gamification\",\"Lehre\",\"Programmieren\",\"Programmierung\",\"Spiel\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/\",\"name\":\"Projektliste Game Design und Programmierung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Fantasy-Spielfiguren.jpg\",\"datePublished\":\"2021-09-25T20:41:02+00:00\",\"dateModified\":\"2022-10-18T15:58:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Fantasy-Spielfiguren.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/Fantasy-Spielfiguren.jpg\",\"width\":1024,\"height\":617,\"caption\":\"Bild Fantasy Figuren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/projektliste-game-design-und-programmierung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projektliste Game Design und Programmierung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projektliste Game Design und Programmierung","description":"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/","og_locale":"de_DE","og_type":"article","og_title":"Projektliste Game Design und Programmierung","og_description":"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.","og_url":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/","og_site_name":"Bienen und Technik","article_published_time":"2021-09-25T20:41:02+00:00","article_modified_time":"2022-10-18T15:58:37+00:00","og_image":[{"width":1024,"height":617,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg","type":"image\/jpeg"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Projektliste Game Design und Programmierung","datePublished":"2021-09-25T20:41:02+00:00","dateModified":"2022-10-18T15:58:37+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/"},"wordCount":2694,"image":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg","keywords":["AJAX","Biene","Bienenstock","escape room","exit","Game","gamification","Javascript","Microcontroller","Partyspiel","PHP","Serious Game","Simulation","SQLite","Trinkspiel","Wordle"],"articleSection":["Gamification","Lehre","Programmieren","Programmierung","Spiel"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/","url":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/","name":"Projektliste Game Design und Programmierung","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg","datePublished":"2021-09-25T20:41:02+00:00","dateModified":"2022-10-18T15:58:37+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Programmier-Projekte f\u00fcr das Modul Game Design. Studierende k\u00f6nnen in Zweierteams ein Projekt aussuchen und bearbeiten.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2021\/09\/Fantasy-Spielfiguren.jpg","width":1024,"height":617,"caption":"Bild Fantasy Figuren"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/projektliste-game-design-und-programmierung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Projektliste Game Design und Programmierung"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=2209"}],"version-history":[{"count":18,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2209\/revisions"}],"predecessor-version":[{"id":2924,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2209\/revisions\/2924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/2384"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=2209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=2209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=2209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}