{"id":2049,"date":"2021-07-12T15:32:57","date_gmt":"2021-07-12T13:32:57","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=2049"},"modified":"2021-07-12T15:35:51","modified_gmt":"2021-07-12T13:35:51","slug":"checkliste-abschlussarbeit","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/","title":{"rendered":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung"},"content":{"rendered":"<p><em>Die folgende Checkliste Abschlussarbeit verwende ich bei der Begutachtung von Abschlussarbeiten. Sie kann Studierenden auch als Hilfe dienen, um selbst ihre eigene Arbeit vor Abgabe noch einmal zu \u00fcberpr\u00fcfen &#8211; dieser Prozess wirkt sich erfahrungsgem\u00e4\u00df positiv auf die Note aus. Diese Checkliste kommt am Ende einer Abschlussarbeit zum Einsatz. <a href=\"https:\/\/cbrell.de\/blog\/abschlussarbeit\/\">Hier lesen Sie, wie der Start einer Abschlussarbeit gelingen kann.<\/a><\/em><\/p>\n<p><em>Stand 12.07.2021<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Prof. Dr. Claus Brell, Hochschule Niederrhein<\/p>\n<p>&nbsp;<\/p>\n<p>F\u00fcr: &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;., Datum: &#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;&#8230;.<\/p>\n<p>Legende: \u00fcberdurchschnitt ***, erwartet **, unterdurchschnitt *, nicht ausreichend erf\u00fcllt=-, nicht beobachtbar=0<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Formale Aspekte<\/strong><\/p>\n<p>&#8230;&#8230;&#8230;.. Seiten<\/p>\n<p>&#8230;&#8230;&#8230;.. Abbildungen<\/p>\n<p>&#8230;&#8230;&#8230;.. Tabellen<\/p>\n<p>&#8230;&#8230;&#8230;.. Quellenangaben, davon<\/p>\n<p>&#8230;&#8230;&#8230;. B\u00fccher<\/p>\n<p>&#8230;&#8230;&#8230;. Journals und Publikumszeitschriften<\/p>\n<p>&#8230;&#8230;&#8230;. Internetquellen<\/p>\n<table>\n<tbody>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Formales und Schreibstil<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist die Arbeit nahezu frei von Rechtschreibfehlern?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind Kommas richtig und sinnf\u00f6rdernd gesetzt?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die S\u00e4tze und Formulierungen verst\u00e4ndlich? Wird auf verquaste Satzkonstruktionen verzichtet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Passen die Inhalte zu den jeweiligen Gliederungs\u00fcberschriften?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die Abbildungen und Tabellen im Text referenziert?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Zitierung: wurden alle Aussagen ausreichend belegt?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Zitierung: Ist die Zitierung einheitlich<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Zitierung: Wird ein g\u00e4ngiger Zitierstil verwendet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Zitierung: Ist das Quellenverzeichnis nach B\u00fcchern, Zeitschriftenartikeln und Internetquellen getrennt?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wurden die Richtlinien f\u00fcr die Erstellung von Abschlussarbeiten beachtet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wurde auf einen vern\u00fcnftigen Schreibstil geachtet (vgl. Schneider: Deutsch f\u00fcr junge Profis)<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist die Sprache dem Habitus \u201eSchreiber einer Abschlussarbeit\u201c angemessen?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Macht es auch ab der zweiten H\u00e4fte der Arbeit Spa\u00df sie zu lesen?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wird die Arbeit durch EIGENE Abbildungen sinnvoll gest\u00fctzt?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist der Text sinnvoll durch Zwischen\u00fcberschriften \/\u00a0 Hervorhebungen gegliedert?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wenn man etwas Bestimmtes (wieder-)<em>sucht, findet<\/em> man es schnell?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Management Summary<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Gibt es ein Management \/ Executive Summary?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die wesentlichen Outcomes der Arbeit aufgelistet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die Ziele noch einmal zusammengefasst?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind wesentliche Aspekte des &#8222;methodischen Gangs&#8220; der Arbeit wiedergegeben?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist das Management Summary so verfasst, dass der Leser schon recht umfassend wei\u00df, was alles in der Arbeit drinstehen wird?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist das Management Summary so verfasst, dass ein Leser &#8222;unbedingt&#8220; die ganze Arbeit lesen will?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Ziele<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die Ziele der Arbeit so beschrieben, dass am Ende zweifelsfrei festgestellt werden kann, inwieweit die Ziele erreicht wurden?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wurden die Ziele hinreichend begr\u00fcndet? (&#8230; aus der Theorie \/ aus vorigen Arbeiten \/ aus sonstigen Erkenntnissen abgeleitet?)<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die Ziele S.M.A.R.(T.) ? (T in Klammern, da Abgabetermin der Arbeit klar ist.)<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>\u00a0<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Methoden (Theorieteil)<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die verwendeten Methoden explizit benannt?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist der &#8222;methodische Gang der Arbeit&#8220; stringent aus den Zielen abgeleitet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist herausgestellt, warum diese Methoden und keine anderen verwendet werden?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die verwendeten Methoden ausreichend beschrieben? (passendes Gewicht in der Arbeit &#8230;)<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind zu den Methoden Quellen angegeben?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wurden f\u00fcr die Methoden bedeutende etablierte\/alte Quellen verwendet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Wurden f\u00fcr die Methoden aktuelle Quellen verwendet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind (verschiede) Aussagen zu einem Thema aus der Literatur \/ aus Quellen beschrieben?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Werden die Methoden im weiteren Gang der Arbeit auch verwendet?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Sind die Aussagen noch einmal so aufbereitet oder zusammengefasst, dass Sie f\u00fcr den Leser schnell erfassbar sind?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Fazit (oder Zusammenfassung)<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Werden die wesentlichen Ergebnisse und die Ableitung aus Theorieteil und \/oder Intervention noch einmal zusammengefasst?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\"><strong>Ausblick<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Gibt\u2019s einen Ausblick?<\/td>\n<\/tr>\n<tr>\n<td width=\"85\"><strong>\u00a0<\/strong><\/td>\n<td width=\"508\">Ist der Ausblick aus den Ergebnissen der Arbeit abgeleitet<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=5087\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die folgende Checkliste Abschlussarbeit verwende ich bei der Begutachtung von Abschlussarbeiten. Sie kann Studierenden auch als Hilfe dienen, um selbst ihre eigene Arbeit vor Abgabe noch einmal zu \u00fcberpr\u00fcfen &#8211; &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[84,306],"tags":[292,418,472,419],"class_list":["post-2049","post","type-post","status-publish","format-standard","hentry","category-lebenslanges-lernen","category-lehre","tag-abschlussarbeit","tag-bachelorarbeit","tag-checkliste","tag-masterarbeit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe<\/title>\n<meta name=\"description\" content=\"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe\" \/>\n<meta property=\"og:description\" content=\"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-12T13:32:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-12T13:35:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/zaehler\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Checkliste Abschlussarbeit f\u00fcr die Begutachtung\",\"datePublished\":\"2021-07-12T13:32:57+00:00\",\"dateModified\":\"2021-07-12T13:35:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/\"},\"wordCount\":508,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"keywords\":[\"Abschlussarbeit\",\"Bachelorarbeit\",\"Checkliste\",\"Masterarbeit\"],\"articleSection\":[\"lebenslanges Lernen\",\"Lehre\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/\",\"name\":\"Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"datePublished\":\"2021-07-12T13:32:57+00:00\",\"dateModified\":\"2021-07-12T13:35:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/zaehler\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/zaehler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/checkliste-abschlussarbeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Checkliste Abschlussarbeit f\u00fcr die Begutachtung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe","description":"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/","og_locale":"de_DE","og_type":"article","og_title":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe","og_description":"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.","og_url":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/","og_site_name":"Bienen und Technik","article_published_time":"2021-07-12T13:32:57+00:00","article_modified_time":"2021-07-12T13:35:51+00:00","og_image":[{"url":"https:\/\/cbrell.de\/zaehler","type":"","width":"","height":""}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung","datePublished":"2021-07-12T13:32:57+00:00","dateModified":"2021-07-12T13:35:51+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/"},"wordCount":508,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","keywords":["Abschlussarbeit","Bachelorarbeit","Checkliste","Masterarbeit"],"articleSection":["lebenslanges Lernen","Lehre"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/","url":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/","name":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung - eine Hilfe zur Selbsthilfe","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/zaehler","datePublished":"2021-07-12T13:32:57+00:00","dateModified":"2021-07-12T13:35:51+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Die Nutzung der Checkliste Abschlussarbeit kann sich positiv auf die Note auswirken. Ich verwende sie zur Begutachtung von Abschlussarbeiten.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#primaryimage","url":"https:\/\/cbrell.de\/zaehler","contentUrl":"https:\/\/cbrell.de\/zaehler"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/checkliste-abschlussarbeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Checkliste Abschlussarbeit f\u00fcr die Begutachtung"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=2049"}],"version-history":[{"count":3,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2049\/revisions"}],"predecessor-version":[{"id":2052,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/2049\/revisions\/2052"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=2049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=2049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=2049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}