{"id":1672,"date":"2021-03-07T14:13:20","date_gmt":"2021-03-07T13:13:20","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=1672"},"modified":"2024-11-17T22:16:22","modified_gmt":"2024-11-17T21:16:22","slug":"raspberry-pi-sensoren-und-aktoren-anschliessen","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/","title":{"rendered":"Raspberry Pi Pinbelegung &#8211; Sensoren und Aktoren anschlie\u00dfen"},"content":{"rendered":"<p><em>Mit seinen GPIO bietet der Raspberry vielf\u00e4ltige M\u00f6glichkeiten, Sensoren und Aktoren (zur Ausautomation, oder einfache LED &#8230;) anzuschlie\u00dfen. Der Blogbeitrag gibt ein paar beispielhafte Hinweise, wie das gelingen kann und wie Sie mit der Raspberry Pi Pinbelegung umgehen k\u00f6nnen.<\/em><\/p>\n<h2>GPIO &#8211; Raspberry Pi Pinbelegung<\/h2>\n<p>Die 40 Anschl\u00fcsse des Raspberry Pi hei\u00dfen GPIO (General Purpose In- an Output) und liefern eine Vielzahl von Steuerungsm\u00f6glichkeiten. Der Raspberry Pi hat allerdings nur digitale Eing\u00e4nge. Wollen Sie beispielsweise analoge Spannung messen, ist etwas Zusatzaufwand erforderlich. Abb. 1 zeigt die Bedeutung der Anschl\u00fcsse des Raspberry Pi. Wichtig ist hierbei, dass sich die Nummerierung der Anschl\u00fcsse und die GPIO-Nummern unterscheiden.<\/p>\n<pre>Raspberry Pi Pinbelegung\r\nSD-Karten-Seite\r\n+------------+------+-----+------+------+------------+\r\n|            |GPIO  |Pin  |Pin   |GPIO  |            |\r\n+============+======+=====+======+======+============+\r\n|3,3V        |      | 1   | 2    |      |5V.         |\r\n+------------+------+-----+------+------+------------+\r\n|SDA1        | 2    | 3   | 4    |      |5V          |\r\n+------------+------+-----+------+------+------------+\r\n|SCL1        | 3    | 5   | 6    |      |GND         |\r\n+------------+------+-----+------+------+------------+\r\n|GPCLK0.     | 4    | 7   | 8    | 14   |TXD         |\r\n+------------+------+-----+------+------+------------+\r\n|GND         |      | 9   |10    | 15   |RXD         |\r\n+------------+------+-----+------+------+------------+\r\n|CE1_1       |17    |11   |12    |18    |PWM0,CE0_1  |\r\n+------------+------+-----+------+------+------------+\r\n|            |27    |13   |14    | 7    |GND         |\r\n+------------+------+-----+------+------+------------+\r\n|            |22    |15   |16    |23    |            |\r\n+------------+------+-----+------+------+------------+\r\n|3,3V        |      |17   |18    |24    |            |\r\n+------------+------+-----+------+------+------------+\r\n|MOSI_0      |      |10   |19    |20    |GND         |\r\n+------------+------+-----+------+------+------------+\r\n|MISO_0      | 9    |21   |22    |25    |            |\r\n+------------+------+-----+------+------+------------+\r\n|SCLK_0      |11    |23   |24    | 8    |CE0_0 (SPI) |\r\n+------------+------+-----+------+------+------------+\r\n|GND         |      |25   |26    | 7    |CD1_0 (SPI) |\r\n+------------+------+-----+------+------+------------+\r\n|DNC         |      |27   |28    |      |DNC         |\r\n+------------+------+-----+------+------+------------+\r\n|GPCLK1      | 5    |29   |30    |      |GND         |\r\n+------------+------+-----+------+------+------------+\r\n|GPCLK2      | 6    |31   |32    |12    |PWM0        |\r\n+------------+------+-----+------+------+------------+\r\n|PWM1        |13    |33   |34    |      |GND         |\r\n+------------+------+-----+------+------+------------+\r\n|PWM1\/MISO_1 |19    |35   |36    |16    |CE2_1       |\r\n+------------+------+-----+------+------+------------+\r\n|            |26    |37   |38    |20    |MOSI_1      |\r\n+------------+------+-----+------+------+------------+\r\n|GND         |      |39   |40    |21    |SCLK_1      |\r\n+------------+------+-----+------+------+------------+\r\n<\/pre>\n<p>Abb. 1: Die Belegung der Anschl\u00fcsse m Raspberry Pi (als Text)<\/p>\n<h2>LED mit dem Raspberry steuern<\/h2>\n<p>wird noch erstellt<\/p>\n<h2>W\u00e4gemodul\/AD-Wandler HX711 anschlie\u00dfen<\/h2>\n<p>Einige Anleitungen im Internet schlie\u00dfen die Datenleitung und die Signalsierung an die GPIO 5 und 6 an, allerdings ohne daf\u00fcr einen Grund anzugeben. Vermutlich kommen diese Anschl\u00fcsse des Raspberry besser mit dem Timing des HX711 zurecht. Der Versuch, einen gr\u00fcne Breakout-Platine mit dem Aufdruck XFW an den GPIO 2 und 3 zu betreiben, ergab stark schwankende und unsinnige Werte. Auch ein Wechsel von 5 V auf 3,3 V brachte keine Besserung, erst der Wechsel zur\u00fcck auf GPIO 5 und 6.<\/p>\n<p>Update 29.04.2021: gute Ergebnisse wurden mit GPIO 23 und 24 erzielt.<\/p>\n<p><a href=\"https:\/\/cbrell.de\/blog\/waegezelle-wie-funktionieren-preiswerte-personenwaagen-zellen\/\">Hinweise zum Anschluss preiswerter W\u00e4gezellen gibt es hier.<\/a> So schalten Sie mehrere (vier) W\u00e4gezellen aus Personenwaagen zusammen.<\/p>\n<p><a href=\"https:\/\/honey-pi.de\/a-d-wandler-hx711\/\">Viele Hinweise gibts auch auf den Honey-Pi-Seiten.<\/a> Der Honey-Pi ist ein Selbstbauprojekt. Mit dem Honey-Pi k\u00f6nnen Sie die Abf\u00fcllung von Bienenenhonig in Gl\u00e4ser f\u00fcr den Verkauf halb automatisieren.<\/p>\n<h2>I2C Ger\u00e4te anschlie\u00dfen<\/h2>\n<p>wird noch erstellt<\/p>\n<h2>Die serielle Schnittstelle<\/h2>\n<p>wird noch erstellt<\/p>\n<h2>433 MHz Funk empfangen und senden<\/h2>\n<p>wird noch erstellt<\/p>\n<h2>Beispiel f\u00fcr eine Mutisensor-Beschaltung<\/h2>\n<p>Zum Zeitpunkt 29.04.2021 noch im Test. Geplant ist der Anschluss folgender Sensoren:<br \/>\n&#8211; BME280 &#8211; Klima<br \/>\n&#8211; alternativ DHT22-1 &#8211; Klima ohne Druck<br \/>\n&#8211; 3*DS18B20 &#8211; Brutraum Honigbienen<br \/>\n&#8211; HX711 &#8211; Gewicht Honigbienen<br \/>\n&#8211; DHT22-2 &#8211; Feuchte Honigraum<br \/>\n&#8211; Schalter &#8211; Einfaches Umschalten zur Wartung<\/p>\n<pre>Raspberry Pi Pinbelegung\r\nSD-Karten-Seite\r\n       +------------+------+-----+------+------+------------+\r\n       |            |GPIO  |Pin  |Pin   |GPIO  |            |\r\n       +============+======+=====+======+======+============+\r\n       |3,3V        |      | 1   | 2    |      |5V.         |\r\n       +------------+------+-----+------+------+------------+\r\nBME2080|SDA1        | 2    | 3   | 4    |      |5V          |\r\n       +------------+------+-----+------+------+------------+\r\nBME2080|SCL1        | 3    | 5   | 6    |      |GND         |\r\n       +------------+------+-----+------+------+------------+ \r\nDHT22-1|GPCLK0.     | 4    | 7   | 8    | 14   |TXD         |\r\n       +------------+------+-----+------+------+------------+\r\n       |GND         |      | 9   |10    | 15   |RXD         |\r\n       +------------+------+-----+------+------+------------+\r\nDS18B20|CE1_1       |17    |11   |12    |18    |PWM0,CE0_1  |Schalter\r\n       +------------+------+-----+------+------+------------+\r\nDHT22-2|            |27    |13   |14    | 7    |GND         |\r\n       +------------+------+-----+------+------+------------+\r\n       |            |22    |15   |16    |23    |            |HX711\r\n       +------------+------+-----+------+------+------------+\r\n       |3,3V        |      |17   |18    |24    |            |HX711\r\n       +------------+------+-----+------+------+------------+\r\n<\/pre>\n<p>Umsetzung auf eine lineare Steckerleiste:<\/p>\n<pre> Pin - Leiste - Sensor\r\n   1 -        - BME280 Plus, DHT22-1 Plus\r\n   3 -SDA1    - BME280 SDA,  \r\n   5 -SLC1    - BME280 SCL\r\n   9 -        - BME280 GND,  DHT22-1 GND\r\n   9 -     1  - DS18B20 GND, Plus\r\n  11 -17   2  - DS18B20 Data (parasit\u00e4r)\r\n   9 -     3  - DS18B20 GND, Plus\r\n   1 -     4  - DHT22-2 Plus\r\n  13 -27   5  - DHT22-2 Data\r\n   9 -     6  - DHT22-2 GND\r\n   1 -     7  - HX711 Plus\r\n  16 -23   8  - HX711 Data\r\n  18 -24   9  - HX711 Clock\r\n   9 -    10  - HX711 GND<\/pre>\n<p><img decoding=\"async\" src=\"http:\/\/cbrell.de\/zaehler\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit seinen GPIO bietet der Raspberry vielf\u00e4ltige M\u00f6glichkeiten, Sensoren und Aktoren (zur Ausautomation, oder einfache LED &#8230;) anzuschlie\u00dfen. Der Blogbeitrag gibt ein paar beispielhafte Hinweise, wie das gelingen kann und &#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75,76],"tags":[414,416,415,413,228,78,124,408],"class_list":["post-1672","post","type-post","status-publish","format-standard","hentry","category-internet-of-things-iot","category-raspberry-pi","tag-gpio","tag-hx711","tag-leuchtdiode","tag-pinbelegung","tag-raspberry","tag-raspberry-pi","tag-sensor","tag-waegezelle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen<\/title>\n<meta name=\"description\" content=\"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen\" \/>\n<meta property=\"og:description\" content=\"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-07T13:13:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-17T21:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/cbrell.de\/zaehler\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Raspberry Pi Pinbelegung &#8211; Sensoren und Aktoren anschlie\u00dfen\",\"datePublished\":\"2021-03-07T13:13:20+00:00\",\"dateModified\":\"2024-11-17T21:16:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/\"},\"wordCount\":361,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/cbrell.de\\\/zaehler\",\"keywords\":[\"GPIO\",\"HX711\",\"Leuchtdiode\",\"Pinbelegung\",\"Raspberry\",\"Raspberry Pi\",\"Sensor\",\"W\u00e4gezelle\"],\"articleSection\":[\"Internet of Things (IoT)\",\"Raspberry Pi\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/\",\"name\":\"Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/cbrell.de\\\/zaehler\",\"datePublished\":\"2021-03-07T13:13:20+00:00\",\"dateModified\":\"2024-11-17T21:16:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#primaryimage\",\"url\":\"http:\\\/\\\/cbrell.de\\\/zaehler\",\"contentUrl\":\"http:\\\/\\\/cbrell.de\\\/zaehler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/raspberry-pi-sensoren-und-aktoren-anschliessen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raspberry Pi Pinbelegung &#8211; Sensoren und Aktoren anschlie\u00dfen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen","description":"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/","og_locale":"de_DE","og_type":"article","og_title":"Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen","og_description":"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.","og_url":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/","og_site_name":"Bienen und Technik","article_published_time":"2021-03-07T13:13:20+00:00","article_modified_time":"2024-11-17T21:16:22+00:00","og_image":[{"url":"http:\/\/cbrell.de\/zaehler","type":"","width":"","height":""}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Raspberry Pi Pinbelegung &#8211; Sensoren und Aktoren anschlie\u00dfen","datePublished":"2021-03-07T13:13:20+00:00","dateModified":"2024-11-17T21:16:22+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/"},"wordCount":361,"commentCount":0,"image":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#primaryimage"},"thumbnailUrl":"http:\/\/cbrell.de\/zaehler","keywords":["GPIO","HX711","Leuchtdiode","Pinbelegung","Raspberry","Raspberry Pi","Sensor","W\u00e4gezelle"],"articleSection":["Internet of Things (IoT)","Raspberry Pi"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/","url":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/","name":"Raspberry Pi Pinbelegung - Sensoren und Aktoren anschlie\u00dfen","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#primaryimage"},"thumbnailUrl":"http:\/\/cbrell.de\/zaehler","datePublished":"2021-03-07T13:13:20+00:00","dateModified":"2024-11-17T21:16:22+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Wie schlie\u00dft man was an die GPIO (General Purpose In- an Output) an? F\u00fcr einige Bauteile und die Raspberry Pi Pinbelegung gibts hier Hinweise.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#primaryimage","url":"http:\/\/cbrell.de\/zaehler","contentUrl":"http:\/\/cbrell.de\/zaehler"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/raspberry-pi-sensoren-und-aktoren-anschliessen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Raspberry Pi Pinbelegung &#8211; Sensoren und Aktoren anschlie\u00dfen"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/1672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=1672"}],"version-history":[{"count":7,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/1672\/revisions"}],"predecessor-version":[{"id":4848,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/1672\/revisions\/4848"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=1672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=1672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=1672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}