{"id":117,"date":"2018-01-26T20:06:27","date_gmt":"2018-01-26T19:06:27","guid":{"rendered":"https:\/\/cbrell.de\/blog\/?p=117"},"modified":"2021-04-15T17:34:53","modified_gmt":"2021-04-15T15:34:53","slug":"spickzettel-erlaubt-als-emotionaler-rettungsanker","status":"publish","type":"post","link":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/","title":{"rendered":"Spickzettel erlaubt &#8211; als emotionaler Rettungsanker"},"content":{"rendered":"<p><strong>M\u00fcssen Pr\u00fcfungen weh tun?<\/strong> Ja, vielleicht, weil Leidensf\u00e4higkeit neben Flei\u00df ein Top-Softskill ist. Aber darf eine Pr\u00fcfung Angst machen? Nein, weil Angst ein denkbar schlechter Lernbegleiter ist. Mit dem gezielt eingesetzten didaktischen Instrument des &#8222;Spickzettel erlaubt&#8220; wie in Abb. 1 gelingt es, Angst aus der Pr\u00fcfungssituation zu nehmen, Bulemielernen zu mindern und nicht zuletzt die Durchfallquote zu senken. Angenehmer Nebeneffekt: Auch Monate nach der Pr\u00fcfung werden wesentliche Inhalte noch gewusst.<\/p>\n<p><strong><a href=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/spickzettel_blog_claus_brell.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-120\" src=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/spickzettel_blog_claus_brell-210x300.jpg\" alt=\"\" width=\"210\" height=\"300\" srcset=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/spickzettel_blog_claus_brell-210x300.jpg 210w, https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/spickzettel_blog_claus_brell.jpg 437w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><\/strong><\/p>\n<p><em>Abb. 1: Beispiel eines Spickzettels in DIN A 5<\/em><\/p>\n<h2>Einf\u00fchrung des &#8222;Spickzettel erlaubt&#8220;<\/h2>\n<p>Ausl\u00f6ser im Wintersemester 2012 war meine Statistikvorlesung, das Antilieblingsfach der Betriebswirtschaftsstudenten. Den Studierenden wurde angeboten, in die Klausur einen handschriftlichen DIN-A-5 Spickzettel mitzunehmen. Zun\u00e4chst wurde das Instrument z\u00f6gerlich angenommen, da die Studies schnell merkten, dass es Arbeit macht, alle Vortragsfolien schrittweise auf zweimal DIN A 5 zu verdichten. Die Aktivierungsrate lag zun\u00e4chst unter den Erwartungen. Dass man durch das Aufschreiben und Verdichten des Stoffs (ein Studie wird permanent gezwungen zu entscheiden, was wichtig ist und was nicht) viel auswendig lernt und sich kritisch mit dem Stoff auseinandersetzt, glaubt ein Zweitsemester erst nach der Klausur. Erst der Bonus von 3 Punkten, die f\u00fcr Spickzettel zu den Klausurpunkten hinzugerechnet wurden, brachte den Durchbruch. Heute fertigen nahezu alle meine Studies sch\u00f6ne Spickzettel an.<\/p>\n<h2><strong>Der Erfolg des &#8222;Spickzettel erlaubt&#8220;<\/strong><\/h2>\n<p>Nach drei Semestern eine Senkung der Durchfallquote in der Statistik von 43% auf 11%. Und jedes Semester knapp 30 Wiederholerklausuren weniger zu korrigieren.<\/p>\n<p>Das Konzept habe ich mittlerweile auf alle meine Veranstaltungen (Programmierung, Wirtschaftsinformatik-Methoden &#8230;) \u00fcbertragen. Der Erfolg hat sich herumgesprochen, und die Zusatzpunkte sind nicht mehr erforderlich. Mehr als 2500 kunstvoll gestaltete Spickzettel k\u00f6nnen bei mir in der Hochschule Niederrhein besichtigt werden.<\/p>\n<p><strong>So funktioniert das Instrument &#8222;Spickzettel erlaubt&#8220;<\/strong><\/p>\n<p>Der Wirkmechanismus des Spickzettels beruht auf zwei S\u00e4ulen:<\/p>\n<ol>\n<li>Durch die intensive Besch\u00e4ftigung wissen die Studies eine Menge auswendig und arbeiten in der Klausur mit h\u00f6herer Leistung.<\/li>\n<li>Dadurch, dass sie den Spickzettel vor sich liegen haben, haben sie ein gutes Gef\u00fchl und weniger Angst. Dass sie den Spickzettel dann gar nicht mehr brauchen, realisieren sie erst hinterher.<\/li>\n<\/ol>\n<p>Traurige Gesichter gibt es manchmal nur nach der Klausur: Der Deal ist, dass der Spickzettel bei mir abgegeben wird.<\/p>\n<h2><strong>Didaktisches Konzept<\/strong><\/h2>\n<p>Hinter dem Konzept des &#8222;Spickzettel erlaubt&#8220; steht ein in der Didaktik breit akzeptierter Wirkmechanismus, das der Time-on-Task (Anderson 1986) . Time-on-Task bezeichnet die effektive Zeitdauer, die sich ein Lerner fokussiert mit dem Lerngegenstand besch\u00e4ftigt. Die Forschung liefert durchg\u00e4ngig das Ergebnis, dass eine h\u00f6here Time-on-Task einen gr\u00f6\u00dferen Lernerfolg impliziert. Wer l\u00e4nger und mehr \u00fcbt, wird einen Lerngegenstand besser beherrschen als jemand, der es nicht tut. Mein Leitspruch f\u00fcr die Studierenden: &#8222;Tennisspielen lernt man nicht durch das Lesen von Tennisb\u00fcchern, sondern indem man auf den Platz geht und gegen den Ball schl\u00e4gt. Oft und regelm\u00e4\u00dfig&#8220;.<\/p>\n<p>Grunds\u00e4tzlich l\u00e4sst sich der Spickzettel als Gamification-Ansatz verstehen. Als Spiel-Design-Element (Deterding 2011)\u00a0 werden hier die &#8222;Gestaltung eigenen Inhaltes&#8220; (eben in Form des bunten Spickzettels) sowie ein Belohnungsmechanismus (Versprechen einer angstfreien Pr\u00fcfung) eingesetzt.<\/p>\n<p>Gek\u00fcrzt aus:<\/p>\n<p>Brell, Claus (2018) Spa\u00dforientiert pr\u00fcfen. Studierendenzentrierte Pr\u00fcfungskomponenten am Rande der Pr\u00fcfungsordnung. LeNi &#8211; Magazin f\u00fcr Lehre an der Hochschule Niederrhein. M\u00f6nchengladbach. S. 38 &#8211; 42, 11, 28-19<\/p>\n<h2>Quellen<\/h2>\n<ol>\n<li>Anderson, Lorin W. (1986) <em>Instruction and Time-on-Task: a Review.<\/em> In: <em>Time and School Learning: Theory, Research and Practice.<\/em> Croom Helm, Beckenham, ISBN 978-0-709-90518-9, S. 143\u2212166.<\/li>\n<li>Deterding S. et al. (2011 a): Gamification: Using Game Design Elements<br \/>\nin Non-Gaming Contexts, in: Tan, Desney; Interaction, ACM Special Interest Group on Computer-Human (Hrsg.), CHI &#8217;11 Extended Abstracts on Human Factors in Computing Systems, ACM Press, New York 2011.<\/li>\n<li><a href=\"https:\/\/www.bpb.de\/lernen\/grafstat\/grafstat-bundestagswahl-2013\/148891\/spickzettel-anfertigen\">Spickzettel auf den Seiten der Bundeszentrale f\u00fcr politische Bildung: https:\/\/www.bpb.de\/lernen\/grafstat\/grafstat-bundestagswahl-2013\/148891\/spickzettel-anfertigen<\/a><\/li>\n<\/ol>\n<p><img decoding=\"async\" src=\"https:\/\/cbrell.de\/zaehler?x=9863\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00fcssen Pr\u00fcfungen weh tun? Ja, vielleicht, weil Leidensf\u00e4higkeit neben Flei\u00df ein Top-Softskill ist. Aber darf eine Pr\u00fcfung Angst machen? Nein, weil Angst ein denkbar schlechter Lernbegleiter ist. Mit dem gezielt &#8230;<\/p>\n","protected":false},"author":1,"featured_media":1773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[198,84,306,200],"tags":[26,432,433,18,28,85,27,29],"class_list":["post-117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gamification","category-lebenslanges-lernen","category-lehre","category-motivation","tag-didaktik","tag-emotion","tag-emotionale-sicherheit","tag-hochschullehre","tag-klausur","tag-lernen","tag-pruefung","tag-spickzettel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spickzettel erlaubt - als emotionaler Rettungsanker<\/title>\n<meta name=\"description\" content=\"Mit dem gezielt eingesetzten didaktischen Instrument des &quot;Spickzettel erlaubt&quot; gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spickzettel erlaubt - als emotionaler Rettungsanker\" \/>\n<meta property=\"og:description\" content=\"Mit dem gezielt eingesetzten didaktischen Instrument des &quot;Spickzettel erlaubt&quot; gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/\" \/>\n<meta property=\"og:site_name\" content=\"Bienen und Technik\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-26T19:06:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T15:34:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Claus Brell\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@clausbrell5859\" \/>\n<meta name=\"twitter:site\" content=\"@clausbrell\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Claus Brell\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/\"},\"author\":{\"name\":\"Claus Brell\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"headline\":\"Spickzettel erlaubt &#8211; als emotionaler Rettungsanker\",\"datePublished\":\"2018-01-26T19:06:27+00:00\",\"dateModified\":\"2021-04-15T15:34:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/\"},\"wordCount\":615,\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Spickzettel-mit-Kussmund.jpg\",\"keywords\":[\"Didaktik\",\"Emotion\",\"emotionale Sicherheit\",\"Hochschullehre\",\"Klausur\",\"Lernen\",\"Pr\u00fcfung\",\"Spickzettel\"],\"articleSection\":[\"Gamification\",\"lebenslanges Lernen\",\"Lehre\",\"Motivation\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/\",\"name\":\"Spickzettel erlaubt - als emotionaler Rettungsanker\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Spickzettel-mit-Kussmund.jpg\",\"datePublished\":\"2018-01-26T19:06:27+00:00\",\"dateModified\":\"2021-04-15T15:34:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\"},\"description\":\"Mit dem gezielt eingesetzten didaktischen Instrument des \\\"Spickzettel erlaubt\\\" gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Spickzettel-mit-Kussmund.jpg\",\"contentUrl\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/Spickzettel-mit-Kussmund.jpg\",\"width\":1024,\"height\":525,\"caption\":\"Spickzettel Wirtschaftsinformatik mit Motivation der Freundin\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/spickzettel-erlaubt-als-emotionaler-rettungsanker\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spickzettel erlaubt &#8211; als emotionaler Rettungsanker\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/\",\"name\":\"Bienen und Technik\",\"description\":\"Alles, was einfach ist. Von Claus Brell\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/#\\\/schema\\\/person\\\/7cf529e46faf1fd7b2b6942fec254c58\",\"name\":\"Claus Brell\",\"description\":\"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}\",\"sameAs\":[\"http:\\\/\\\/claus-brell.de\",\"https:\\\/\\\/x.com\\\/clausbrell5859\",\"https:\\\/\\\/www.youtube.com\\\/@clausbrell5859\"],\"url\":\"https:\\\/\\\/cbrell.de\\\/blog\\\/author\\\/clausb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spickzettel erlaubt - als emotionaler Rettungsanker","description":"Mit dem gezielt eingesetzten didaktischen Instrument des \"Spickzettel erlaubt\" gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/","og_locale":"de_DE","og_type":"article","og_title":"Spickzettel erlaubt - als emotionaler Rettungsanker","og_description":"Mit dem gezielt eingesetzten didaktischen Instrument des \"Spickzettel erlaubt\" gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.","og_url":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/","og_site_name":"Bienen und Technik","article_published_time":"2018-01-26T19:06:27+00:00","article_modified_time":"2021-04-15T15:34:53+00:00","og_image":[{"width":1024,"height":525,"url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg","type":"image\/jpeg"}],"author":"Claus Brell","twitter_card":"summary_large_image","twitter_creator":"@clausbrell5859","twitter_site":"@clausbrell","twitter_misc":{"Verfasst von":"Claus Brell","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#article","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/"},"author":{"name":"Claus Brell","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"headline":"Spickzettel erlaubt &#8211; als emotionaler Rettungsanker","datePublished":"2018-01-26T19:06:27+00:00","dateModified":"2021-04-15T15:34:53+00:00","mainEntityOfPage":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/"},"wordCount":615,"image":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg","keywords":["Didaktik","Emotion","emotionale Sicherheit","Hochschullehre","Klausur","Lernen","Pr\u00fcfung","Spickzettel"],"articleSection":["Gamification","lebenslanges Lernen","Lehre","Motivation"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/","url":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/","name":"Spickzettel erlaubt - als emotionaler Rettungsanker","isPartOf":{"@id":"https:\/\/cbrell.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#primaryimage"},"image":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#primaryimage"},"thumbnailUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg","datePublished":"2018-01-26T19:06:27+00:00","dateModified":"2021-04-15T15:34:53+00:00","author":{"@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58"},"description":"Mit dem gezielt eingesetzten didaktischen Instrument des \"Spickzettel erlaubt\" gelingt es, Pr\u00fcfungsangst und die Durchfall-Quote zu senken.","breadcrumb":{"@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#primaryimage","url":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg","contentUrl":"https:\/\/cbrell.de\/blog\/wp-content\/uploads\/2018\/01\/Spickzettel-mit-Kussmund.jpg","width":1024,"height":525,"caption":"Spickzettel Wirtschaftsinformatik mit Motivation der Freundin"},{"@type":"BreadcrumbList","@id":"https:\/\/cbrell.de\/blog\/spickzettel-erlaubt-als-emotionaler-rettungsanker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/cbrell.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Spickzettel erlaubt &#8211; als emotionaler Rettungsanker"}]},{"@type":"WebSite","@id":"https:\/\/cbrell.de\/blog\/#website","url":"https:\/\/cbrell.de\/blog\/","name":"Bienen und Technik","description":"Alles, was einfach ist. Von Claus Brell","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cbrell.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/cbrell.de\/blog\/#\/schema\/person\/7cf529e46faf1fd7b2b6942fec254c58","name":"Claus Brell","description":"Seit 2021 forsche ich an und mit Bienen (Digitalisierung der Imkerei) Seit 2012 Professur f\u00fcr Wirtschaftsinformatik an der Hochschue Niederrhein. Seit 1981 treibt mich die Frage um: Was haben Physik, Heavy Metal und Spiele miteinander zu tun? Drei m\u00f6gliche Antworten: {nichts | 42 | gleiche Hirnareale werden aktiviert}","sameAs":["http:\/\/claus-brell.de","https:\/\/x.com\/clausbrell5859","https:\/\/www.youtube.com\/@clausbrell5859"],"url":"https:\/\/cbrell.de\/blog\/author\/clausb\/"}]}},"_links":{"self":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":3,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"predecessor-version":[{"id":1774,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/posts\/117\/revisions\/1774"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media\/1773"}],"wp:attachment":[{"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cbrell.de\/blog\/wp-json\/wp\/v2\/tags?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}